{"id":44027,"date":"2015-05-29T11:23:17","date_gmt":"2015-05-29T15:23:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44027"},"modified":"2015-05-29T05:28:26","modified_gmt":"2015-05-29T09:28:26","slug":"conoce-por-que-se-calientan-los-smartphones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conoce-por-que-se-calientan-los-smartphones\/","title":{"rendered":"Conoce por qu\u00e9 se calientan los smartphones"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/using-smartphone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44028 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/using-smartphone.jpg\" alt=\"using-smartphone\" width=\"386\" height=\"257\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/using-smartphone.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/using-smartphone-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/using-smartphone-105x70.jpg 105w\" sizes=\"auto, (max-width: 386px) 100vw, 386px\" \/><\/a>ESTADOS UNIDOS.-<\/strong> En ocasiones, puede ocurrir que un celular que habilit\u00f3 el GPS se sobrecaliente y se dificulte utilizarlo.\u00a0\u201cLa temperatura del iPhone debe disminuir antes de que pueda usarlo\u201d, se lee en la pantalla en esos casos.<!--more--><\/p>\n<p>Para despejar todo tipo de dudas y preocupaciones,\u00a0BBC Mundo explic\u00f3 por qu\u00e9 y revel\u00f3 maneras para evitarlo.<\/p>\n<p>En primer medida, hay que saber que el tel\u00e9fono no se arruin\u00f3 ni dej\u00f3 de funcionar. Si bien suelen publicarse en las redes sociales im\u00e1genes de dispositivos quemados por sobrecalentamiento, esa es una consecuencia extrema en un celular. No obstante, puede pasar por otras razones, como la disminuci\u00f3n de la vida \u00fatil de la bater\u00eda.<\/p>\n<p>Por lo tanto, el aviso que aparece en pantalla es s\u00f3lo para prevenci\u00f3n y se debe a un mecanismo de seguridad que protege los componentes de tu dispositivo.<\/p>\n<p>\u00bfQu\u00e9 hace en ese caso?<\/p>\n<p>Si aparece el mensaje, el usuario debe apagar el dispositivo m\u00f3vil, trasladarlo a un entorno m\u00e1s fr\u00edo y dejar que su temperatura baje antes de volver a utilizarlo. La temperatura que recomiendan los expertos ronda entre los 0 y 35 grados cent\u00edgrados.<br \/>\n<strong><br \/>\nLas razones:<\/strong><\/p>\n<ul>\n<li>Puede que una ola de calor que supera los 40 grados lo haya provocado. Si adem\u00e1s se trata de un celular expuesto a la luz solar directa un largo per\u00edodo de tiempo, tambi\u00e9n es definitivo para que re sobrecaliente.<\/li>\n<li>Dejar el smartphone en el auto en un d\u00eda de extremo calor representar\u00eda las mismas consecuencias, aunque el calentamiento no siempre se debe a la temperatura ambiente. El uso de cargadores de bater\u00eda que proporcionen m\u00e1s corriente de la necesaria tambi\u00e9n pueden tener ese efecto.<\/li>\n<li>Lo mismo puede suceder con el uso del GPS, ya que cuanto m\u00e1s trabaja el celular m\u00e1s tiende a calentarse. Al usar la aplicaci\u00f3n, el dispositivo debe utilizar el sensor durante el 100% del tiempo, con la pantalla encendida y conectado a Internet.<\/li>\n<li>Del mismo modo, la utilizaci\u00f3n de juegos con alta calidad gr\u00e1fica o demasiado pesados para la memoria RAM y las caracter\u00edsticas del CPU de tu celular tambi\u00e9n pueden conllevar el excesivo calentamiento del mismo.<\/li>\n<\/ul>\n<p><strong>Prevenci\u00f3n:<\/strong><strong><br \/>\n<\/strong><\/p>\n<p>Hay que comprobar si se est\u00e1n ejecutando aplicaciones o programas sin que uno se d\u00e9 cuenta. Si se nota una fuerte alza de la temperatura, hay que inhabilitar funciones como el bluetooth o la conexi\u00f3n wifi. De ese modo, se evita una sobrecarga de procesos.<\/p>\n<p>En el caso del uso de juegos, conviene evaluar las condiciones del hardware del dispositivo antes de descargar un juego de alta calidad gr\u00e1fica o demasiado pesados.<\/p>\n<p>Reducir el brillo de la pantalla es igual de recomendable cuando se ejecutan juegos o pel\u00edculas por largos per\u00edodos de tiempo. No hay que dejar el tel\u00e9fono inteligente en un lugar con poca ventilaci\u00f3n, como por ejemplo debajo de la almohada, sobre todo si se est\u00e1 cargando su bater\u00eda o si est\u00e1 descargando una aplicaci\u00f3n.<\/p>\n<p><strong>Aplicaciones para controlar la temperatura<\/strong><\/p>\n<p>Uno de los m\u00e1s populares para el sistema operativo iOS es iStat 2, una app que monitorea por completo la actividad de un iPhone. Adem\u00e1s de la temperatura, muestra la cantidad de datos consumida, al igual que la velocidad restante.<\/p>\n<p>Otra de las opciones para un dispositivo de Apple es el System Status Lite, que reconoce las aplicaciones que mayor carga de energ\u00eda generan y las elimina.<\/p>\n<p>Si se trata de un smartphone Android, se puede optar por la aplicaci\u00f3n gratuita<em>Cooler Master<\/em>. Tras escanear el dispositivo para determinar la temperatura que tiene en ese momento, establece los servicios que producen sobrecalentamiento y los borra.<\/p>\n<p>Tambi\u00e9n hay otras opciones en el mercado para tel\u00e9fonos con el sistema operativo de Google. Entre las m\u00e1s interesantes se encuentran Phone Overheat Alert, TempMonitor o Cpu Gauge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADOS UNIDOS.- En ocasiones, puede ocurrir que un celular que habilit\u00f3 el GPS se sobrecaliente y se dificulte utilizarlo.\u00a0\u201cLa temperatura del iPhone debe disminuir antes de que pueda usarlo\u201d, se lee en la pantalla en esos casos.<\/p>\n","protected":false},"author":12,"featured_media":44028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-44027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44027"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44027\/revisions"}],"predecessor-version":[{"id":44029,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44027\/revisions\/44029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44028"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}