{"id":44030,"date":"2015-05-29T17:05:40","date_gmt":"2015-05-29T21:05:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44030"},"modified":"2015-05-29T07:18:55","modified_gmt":"2015-05-29T11:18:55","slug":"cirugia-bariatrica-opcion-acertada-para-combatir-la-obesidad-extrema","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cirugia-bariatrica-opcion-acertada-para-combatir-la-obesidad-extrema\/","title":{"rendered":"Cirug\u00eda bari\u00e1trica: opci\u00f3n acertada para combatir la obesidad extrema"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44031 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454.jpg\" alt=\"565465454\" width=\"418\" height=\"273\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454-300x196.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454-105x69.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/565465454-400x260.jpg 400w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/a>Desde 1980, la obesidad ha aumentado en m\u00e1s del doble alrededor del mundo. En el a\u00f1o 2014, m\u00e1s de 1900 millones de adultos de 18 o m\u00e1s a\u00f1os ten\u00edan sobrepeso (39% de la poblaci\u00f3n), de los cuales 600 millones eran obesos (13%), seg\u00fan cifras de la Organizaci\u00f3n Mundial de la Salud (OMS).<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<div id=\"field-slideshow-2-wrapper\" class=\"field-slideshow-wrapper\">\n<div class=\"field-slideshow field-slideshow-2 effect-fade timeout-4000 with-pager with-controls field-slideshow-processed\">\n<div class=\"field-slideshow-slide field-slideshow-slide-1 even first\">Sin embargo, esta es una enfermedad que puede prevenirse o tratarse. El doctor Sa\u00fal Hern\u00e1ndez, cirujano general y especialista en cirug\u00eda laparosc\u00f3pica avanzada y bari\u00e1trica, explica que \u201cla obesidad viene en aumento. Se espera que para el a\u00f1o 2030 se dupliquen las cifras, pero esto es alarmante ya que por cada cinco unidades que aumente el \u00edndice de masa muscular del paciente, incrementa en un 30% la probabilidad de muerte de estas personas, sobre todo en ni\u00f1os y adolescentes\u201d.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>De hecho, para el 2013, m\u00e1s de 42 millones de ni\u00f1os menores de cinco a\u00f1os ten\u00edan sobrepeso, siendo esta una acumulaci\u00f3n anormal de grasa que puede ser perjudicial para la salud. \u201cLo ideal es combatir esta enfermedad desde la infancia y adolescencia con la f\u00f3rmula de ejercicio y alimentaci\u00f3n saludable caracterizada por una dieta hiperproteica e hipocal\u00f3rica\u201d, asegura el tambi\u00e9n miembro titular de la Sociedad Venezolana de Cirug\u00eda Bari\u00e1trica y Metab\u00f3lica.<\/p>\n<p>En la actualidad, cada vez m\u00e1s se ha popularizado la llamada cirug\u00eda bari\u00e1trica, que es una intervenci\u00f3n que ayuda a los pacientes a bajar de peso, al cambiar la manera como el est\u00f3mago y el intestino delgado manejan los alimentos consumidos. \u201cUno de los tipos m\u00e1s comunes es la gastrectom\u00eda vertical laparosc\u00f3pica o manga g\u00e1strica. Este procedimiento reduce la capacidad del est\u00f3mago en 90% por v\u00eda laparosc\u00f3pica. Es una t\u00e9cnica restrictiva, lo que significa que la persona va a disminuir su ingesta porque tiene un espacio mucho m\u00e1s reducido. Sin embargo, si el individuo no mejora sus h\u00e1bitos alimenticios, puede reganar peso, perdiendo as\u00ed la cirug\u00eda\u201d, dice el especialista adscrito a Sanitas Venezuela.<\/p>\n<p>No obstante, esta cirug\u00eda tiene sus indicaciones espec\u00edficas, asevera Hern\u00e1ndez. El paciente debe padecer obesidad extrema, con un \u00edndice de masa corporal m\u00ednimo de 35 o m\u00e1s, que tenga comorbilidades asociadas, como hipertensi\u00f3n, diabetes tipo 2, s\u00edndrome obstructivo del sue\u00f1o, osteoartritis, infertilidad, dislipidemia, entre otras.<\/p>\n<p>\u201cEl fin de esta cirug\u00eda es mejorar la calidad de vida y la remisi\u00f3n o cura de comorbilidades, como la hipertensi\u00f3n arterial y la Diabetes Mellitus tipo 2 que ocasionan tantas complicaciones cr\u00f3nicas y muertes a nivel mundial. Incluso, en algunos casos, la persona puede dejar de tomar la medicaci\u00f3n para enfermedades asociadas. En el caso de la infertilidad, por ejemplo, reducen los quistes en los ovarios, ya que aumenta la producci\u00f3n de estr\u00f3geno que estaba bloqueada por la resistencia perif\u00e9rica de la insulina\u201d, comenta el adjunto del Servicio de Cirug\u00eda dos del Hospital Universitario de Caracas.<\/p>\n<p>Luego de la operaci\u00f3n, el periodo de recuperaci\u00f3n incluye una dieta por fases: la primera es dos d\u00edas a base de l\u00edquidos claros; luego le sigue un periodo desde el tercer d\u00eda al 20 de cremas y licuados; despu\u00e9s del 21 la dieta es blanda; y dos semanas despu\u00e9s, comida completa.<\/p>\n<p>\u201cEl proceso de recuperaci\u00f3n tambi\u00e9n incluye actividad f\u00edsica: el primer mes practicar ejercicios isom\u00e9tricos en casa con ligas y mancuernas, el segundo mes realizar caminatas cortas en terrenos planos y el tercer mes ejercicio cardiovascular completo, que deber\u00eda convertirse en una pr\u00e1ctica habitual, al igual que alimentaci\u00f3n hiperproteica e hipocal\u00f3rica\u201d, explica el doctor Sa\u00fal Hern\u00e1ndez.<\/p>\n<p>Todos estos temas ser\u00e1n tratados en el I Coloquio de Avances de Cirug\u00eda Laparosc\u00f3pica en el \u00c1rea Digestiva, que organiza Sanitas Venezuela en la ciudad de Puerto Ordaz de manera gratuita. \u201cLa obesidad es algo que engloba muchos aspectos y va en franco aumento. Por ello, es bueno formar especialistas en cirug\u00eda bari\u00e1trica. De igual manera, esta es una enfermedad que se puede prevenir; la soluci\u00f3n no es \u00fanicamente la operaci\u00f3n, debemos irnos mucho m\u00e1s atr\u00e1s a la adolescencia para no llegar a estados tan avanzados de obesidad y comorbilidades que pudiesen llevar a la muerte\u201d, finaliza el galeno de Sanitas Venezuela. NP<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde 1980, la obesidad ha aumentado en m\u00e1s del doble alrededor del mundo. En el a\u00f1o 2014, m\u00e1s de 1900 millones de adultos de 18 o m\u00e1s a\u00f1os ten\u00edan sobrepeso (39% de la poblaci\u00f3n), de los cuales 600 millones eran obesos (13%), seg\u00fan cifras de la Organizaci\u00f3n Mundial de la Salud (OMS).<\/p>\n","protected":false},"author":12,"featured_media":44031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-44030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44030"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44030\/revisions"}],"predecessor-version":[{"id":44032,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44030\/revisions\/44032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44031"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}