{"id":44046,"date":"2015-05-29T14:52:21","date_gmt":"2015-05-29T18:52:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44046"},"modified":"2015-05-29T14:52:21","modified_gmt":"2015-05-29T18:52:21","slug":"jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/","title":{"rendered":"J\u00fabilo en Sos\u00faa, Danilo Medina entrega polit\u00e9cnico \u00bfLe comunicaron a Danilo del Hospital?"},"content":{"rendered":"<div class=\"_6m3\">\n<div class=\"mbs _6m6\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-44052 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501.jpg\" alt=\"29-29-07-50-21-0326501\" width=\"640\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501-105x59.jpg 105w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nSos\u00faa, Pto. Pta.- La Revoluci\u00f3n Educativa continu\u00f3 aqu\u00ed, con la inauguraci\u00f3n, de parte del presidente Danilo Medina, del Polit\u00e9cnico Licenciado Jos\u00e9 Morel (En memoria de nuestro querido Profe) que beneficiar\u00e1 a 735 estudiantes.<\/div>\n<\/div>\n<div class=\"mbs _6m6\">\n<p>Durante el acto, Juana Nicole Ovalles, estudiante del segundo grado de media y quien habl\u00f3 en representaci\u00f3n de sus compa\u00f1eros, se expres\u00f3 altamente honrada por la entrega del centro educativo que se integra a la Tanda Extendida.<\/p>\n<p>\u201cSe\u00f1or Presidente, nunca como ahora, Sos\u00faa hab\u00eda sido atendida por gesti\u00f3n alguna en el campo de la educaci\u00f3n\u201d, manifest\u00f3 la joven en medio de la algarab\u00eda de la comunidad.<\/p>\n<div style=\"width: 250px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/presidencia.gob.do\/sites\/default\/files\/usr_content\/2do_parrafo_3_9_0.jpg\" alt=\"\" width=\"240\" height=\"135\" \/><p class=\"wp-caption-text\">El polit\u00e9cnico cuenta con 25 aulas, dos laboratorios de ciencias y una biblioteca.<\/p><\/div>\n<p><strong>Facilidades para estudiantes y personal del polit\u00e9cnico<br \/>\n<\/strong>El polit\u00e9cnico, construido a trav\u00e9s del Ministerio de Obras P\u00fablicas, est\u00e1 ubicado en la comunidad La Uni\u00f3n de este municipio, consta de 25 nuevas aulas, dos laboratorios de ciencias y uno de inform\u00e1tica, as\u00ed como una biblioteca.<\/p>\n<p>Otras facilidades que brinda este centro a sus estudiantes y personal son los espacios administrativos, cancha deportiva, salones de orientaci\u00f3n y de profesores, enfermer\u00eda, cocina \u2013 comedor y una plaza c\u00edvica.<\/p>\n<p><strong>Renovaci\u00f3n de la educaci\u00f3n dominicana<\/strong><\/p>\n<div style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/presidencia.gob.do\/sites\/default\/files\/usr_content\/6to_parrafo_1_7_0.jpg\" alt=\"\" width=\"240\" height=\"135\" \/><p class=\"wp-caption-text\">La estudiante, Juana Nicole Ovalles, habl\u00f3 en representaci\u00f3n de sus compa\u00f1eros.<\/p><\/div>\n<p><strong>Mejora de las condiciones de alumnos y padres<\/strong>En ese sentido, el ministro de Obras P\u00fablicas, Gonzalo Castillo, resalt\u00f3 el esfuerzo que el presidente Danilo Medina ha realizado renovando la educaci\u00f3n dominicana y combinando nuevas t\u00e9cnicas de construcci\u00f3n, as\u00ed como una red de servicios que incluyen \u00e1reas el\u00e9ctricas, almacenaje, por lo que Rep\u00fablica Dominicana se encuentra en un proceso de cambio propiciando un \u00a0sistema de educaci\u00f3n eficiente.<\/p>\n<p><img decoding=\"async\" class=\" alignleft\" src=\"http:\/\/presidencia.gob.do\/sites\/default\/files\/usr_content\/18237921241_74e6b8e63c_k_0.jpg\" alt=\"\" \/>\u201cEs una forma de mejorar las condiciones, no solo de los alumnos, sino de los padres, especialmente de las madres sin pareja, que tiene adem\u00e1s de garantizada una educaci\u00f3n de calidad, su desayuno, almuerzo y merienda\u201d, precis\u00f3 el ministro de Educaci\u00f3n, refiri\u00e9ndose a la Revoluci\u00f3n Educativa.De su lado, el ministro de Educaci\u00f3n, Carlos Amarante Baret, manifest\u00f3 que el jefe de Estado ha mostrado la grandeza de una obra dedicada a la educaci\u00f3n, con una inversi\u00f3n responsable de los recursos del cuatro por ciento del Producto Interno Bruto en la educaci\u00f3n.<\/p>\n<p>Tambi\u00e9n estuvieron en el acto, el ministro Administrativo de la Presidencia, Jos\u00e9 Ram\u00f3n Peralta; el senador Francis Vargas; el alcalde Walter Musa y los asistentes del jefe de Estado, Carlos Pared P\u00e9rez y Robert De la Cruz, funcionarios del sector educativo, entre otras personalidades.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-44046 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/29-29-07-50-21-0326501\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/29-29-07-50-21-0326501-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/18237921241_fa0269b914_c\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18237921241_fa0269b914_c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18237921241_fa0269b914_c-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18237921241_fa0269b914_c-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/18048799158_6dab8cb7bb_c\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18048799158_6dab8cb7bb_c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18048799158_6dab8cb7bb_c-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/18048799158_6dab8cb7bb_c-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/17616031233_d648fd40a7_c\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616031233_d648fd40a7_c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616031233_d648fd40a7_c-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616031233_d648fd40a7_c-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/17616022563_3ee6813fc6_c\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616022563_3ee6813fc6_c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616022563_3ee6813fc6_c-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17616022563_3ee6813fc6_c-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/jubilo-en-sosua-danilo-medina-entrega-politecnico-le-comunicaron-a-danilo-del-hospital\/17613998974_2139a810d1_c\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17613998974_2139a810d1_c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17613998974_2139a810d1_c-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/17613998974_2139a810d1_c-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<\/div>\n<div class=\"_6m3\">\n<div class=\"_6lz _6mb ellipsis\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa, Pto. Pta.- La Revoluci\u00f3n Educativa continu\u00f3 aqu\u00ed, con la inauguraci\u00f3n, de parte del presidente Danilo Medina, del Polit\u00e9cnico Licenciado Jos\u00e9 Morel (En memoria de nuestro querido Profe) que beneficiar\u00e1 a 735 estudiantes. Durante el acto, Juana Nicole Ovalles, estudiante del segundo grado de media y quien habl\u00f3 en representaci\u00f3n de sus compa\u00f1eros, se expres\u00f3 altamente honrada por la entrega del centro educativo que se integra a la Tanda Extendida. \u201cSe\u00f1or Presidente, nunca como ahora, Sos\u00faa hab\u00eda sido atendida por gesti\u00f3n alguna en el campo de la educaci\u00f3n\u201d, manifest\u00f3 la joven en medio de la algarab\u00eda de la comunidad. Facilidades para estudiantes y personal del polit\u00e9cnico El polit\u00e9cnico, construido a trav\u00e9s del Ministerio de Obras P\u00fablicas, est\u00e1 ubicado en la comunidad La Uni\u00f3n de este municipio, consta de 25 nuevas aulas, dos laboratorios de ciencias y uno de inform\u00e1tica, as\u00ed como una biblioteca. Otras facilidades que brinda este centro a sus estudiantes y personal son los espacios administrativos, cancha deportiva, salones de orientaci\u00f3n y de profesores, enfermer\u00eda, cocina \u2013 comedor y una plaza c\u00edvica. Renovaci\u00f3n de la educaci\u00f3n dominicana Mejora de las condiciones de alumnos y padresEn ese sentido, el ministro de Obras P\u00fablicas, Gonzalo Castillo, resalt\u00f3 el esfuerzo que el presidente Danilo Medina ha realizado renovando la educaci\u00f3n dominicana y combinando nuevas t\u00e9cnicas de construcci\u00f3n, as\u00ed como una red de servicios que incluyen \u00e1reas el\u00e9ctricas, almacenaje, por lo que Rep\u00fablica Dominicana se encuentra en un proceso de cambio propiciando un \u00a0sistema de educaci\u00f3n eficiente. \u201cEs una forma de mejorar las condiciones, no solo de los alumnos, sino de los padres, especialmente de las madres sin pareja, que tiene adem\u00e1s de garantizada una educaci\u00f3n de calidad, su desayuno, almuerzo y merienda\u201d, precis\u00f3 el ministro de Educaci\u00f3n, refiri\u00e9ndose a la Revoluci\u00f3n Educativa.De su lado, el ministro de Educaci\u00f3n, Carlos Amarante Baret, manifest\u00f3 que el jefe de Estado ha mostrado la grandeza de una obra dedicada a la educaci\u00f3n, con una inversi\u00f3n responsable de los recursos del cuatro por ciento del Producto Interno Bruto en la educaci\u00f3n. Tambi\u00e9n estuvieron en el acto, el ministro Administrativo de la Presidencia, Jos\u00e9 Ram\u00f3n Peralta; el senador Francis Vargas; el alcalde Walter Musa y los asistentes del jefe de Estado, Carlos Pared P\u00e9rez y Robert De la Cruz, funcionarios del sector educativo, entre otras personalidades. &nbsp;<\/p>\n","protected":false},"author":12,"featured_media":44052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-44046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44046"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44046\/revisions"}],"predecessor-version":[{"id":44053,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44046\/revisions\/44053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44052"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}