{"id":44055,"date":"2015-05-30T08:06:07","date_gmt":"2015-05-30T12:06:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44055"},"modified":"2015-05-30T08:06:08","modified_gmt":"2015-05-30T12:06:08","slug":"microsoft-hyperlapse-aplicacion-para-hacer-videos-en-timeline-o-camara-rapida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/microsoft-hyperlapse-aplicacion-para-hacer-videos-en-timeline-o-camara-rapida\/","title":{"rendered":"Microsoft Hyperlapse aplicaci\u00f3n para hacer videos en Timeline o c\u00e1mara r\u00e1pida"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse.png\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44063 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse.png\" alt=\"microsoft-hyperlapse\" width=\"688\" height=\"373\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse.png 1053w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse-300x163.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse-1024x555.png 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/microsoft-hyperlapse-105x57.png 105w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/a>Oficialmente, Hyperlapse de Microsoft es una versi\u00f3n beta para Android\u00a0y una vista previa para las m\u00e1quinas de escritorio de Windows; es una aplicaci\u00f3n de pleno derecho para los tel\u00e9fonos Windows. En las plataformas m\u00f3biles de Windows y Android, la aplicaci\u00f3n le permite capturar y hacer time lapse con la c\u00e1mara del tel\u00e9fono inteligente<!--more-->, mientras que en las PCs con Windows, la aplicaci\u00f3n funciona como un editor de lapso de tiempo con videos capturados con c\u00e1maras GoPro y otros dispositivos. En esencia, la aplicaci\u00f3n de Windows es el editor hyperlapse queMicrosoft dio a conocer el a\u00f1o pasado.<\/p>\n<p>Un hyperlapse captura videos filmados durante un per\u00edodo de tiempo, por ejemplo, quince minutos, y lo comprime a s\u00f3lo un minuto m\u00e1s o menos. El resultado, por supuesto, ser\u00e1 que el v\u00eddeo se acelera a trav\u00e9s de lo que normalmente ser\u00eda una pel\u00edcula larga en un clip r\u00e1pido.<\/p>\n<p>Usted probablemente habr\u00e1 visto la t\u00e9cnica utilizada cuando las c\u00e1maras capturan un v\u00eddeo de las estrellas que se mueven lentamente en la noche, de los barcos que se mueven a trav\u00e9s de un puerto, o un edificio en construcci\u00f3n. La aplicaci\u00f3n de Microsoft le permite grabar a velocidades diferentes, sin embargo, usted podr\u00eda variar los efectos.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Q6Lo2-60Tvk\" width=\"640\" height=\"390\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Pero hay otro aspecto de la tecnolog\u00eda de la aplicaci\u00f3n Hyperlapse: estabilidad. La aplicaci\u00f3n suaviza activamente el video, ya que est\u00e1 comprimido, por lo que un trabajo por el parque o un paseo en patineta por una colina no produce un reb v\u00eddeo por todo el lugar.<\/p>\n<p>Para Windows, necesitar\u00e1 Windows Phone 8.0 y uno de los siguientes dispositivos: el Lumia 435, 530, 532, 535, 630, 635, 636, 638, 640, 640 XL, 730, 735, 830, 930, 152, o el HTC One M8.<\/p>\n<p>Los usuarios de Android tendr\u00e1n que utilizar los tel\u00e9fonos compatibles que ejecutan por lo menos Android 4.4. Microsoft dice que las aplicaciones est\u00e1n siendo puestas en libertad sin apoyo oficial, si eso hace la diferencia para usted.<\/p>\n<p><a href=\"http:\/\/www.pcworldenespanol.com\/2015\/05\/25\/hyperlapse-de-microsoft-ya-esta-disponible-en-android-ios\/\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oficialmente, Hyperlapse de Microsoft es una versi\u00f3n beta para Android\u00a0y una vista previa para las m\u00e1quinas de escritorio de Windows; es una aplicaci\u00f3n de pleno derecho para los tel\u00e9fonos Windows. En las plataformas m\u00f3biles de Windows y Android, la aplicaci\u00f3n le permite capturar y hacer time lapse con la c\u00e1mara del tel\u00e9fono inteligente<\/p>\n","protected":false},"author":12,"featured_media":44063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-44055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44055"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44055\/revisions"}],"predecessor-version":[{"id":44064,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44055\/revisions\/44064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44063"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}