{"id":44068,"date":"2015-05-30T08:13:22","date_gmt":"2015-05-30T12:13:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44068"},"modified":"2015-05-30T08:17:17","modified_gmt":"2015-05-30T12:17:17","slug":"impactante-video-una-multitud-intenta-volcar-un-autobus-para-salvar-a-un-hombre-atrapado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/impactante-video-una-multitud-intenta-volcar-un-autobus-para-salvar-a-un-hombre-atrapado\/","title":{"rendered":"Impactante video: Una multitud intenta volcar un autob\u00fas para salvar a un hombre atrapado"},"content":{"rendered":"<div class=\"arcticle-summary\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/556856a3c4618885528b45cb.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44069 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/556856a3c4618885528b45cb.jpg\" alt=\"556856a3c4618885528b45cb\" width=\"743\" height=\"418\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/556856a3c4618885528b45cb.jpg 748w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/556856a3c4618885528b45cb-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/556856a3c4618885528b45cb-105x59.jpg 105w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/a>Un impactante video grabado por una testigo capt\u00f3 el momento en el que una multitud grita y corre para intentar levantar un autob\u00fas de dos pisos en Londres y salvarle la vida a un hombre que qued\u00f3 atrapado entre sus ruedas.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"arcticle-content\">\n<p>Hasta 100 personas se apresuraron para intentar salvarle la vida a hombre atrapado bajo las ruedas de un autob\u00fas en el distrito de Walthamstow, al este de Londres (Reino Unido) este jueves, el cual choc\u00f3 contra el veh\u00edculo mientras iba en uniciclo cerca de las 18:00, hora local, informa el diario &#8216;<a href=\"http:\/\/www.standard.co.uk\/news\/london\/incredible-moment-crowd-of-bystanders-lift-bus-to-free-trapped-cyclist-in-walthamstow-10283901.html\" target=\"_blank\">London Evening Standart<\/a>&#8216;.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/DtxhCFg_4kY\" width=\"630\" height=\"410\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n\u00abEstoy asombrada con la fuerza de Walthamstow. <strong>Nadie dud\u00f3 en ir y empujar el autob\u00fas<\/strong>, yo estaba en &#8216;shock&#8217;. Todo el mundo se uni\u00f3 para ayudar, fue muy agradable al ver algo tan horrible\u00bb, afirma Kyra Sam, una testigo del incidente. Un portavoz de la polic\u00eda metropolitana ha afirmado que la v\u00edctima se encuentra en el hospital en condici\u00f3n grave pero estable.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un impactante video grabado por una testigo capt\u00f3 el momento en el que una multitud grita y corre para intentar levantar un autob\u00fas de dos pisos en Londres y salvarle la vida a un hombre que qued\u00f3 atrapado entre sus ruedas.<\/p>\n","protected":false},"author":12,"featured_media":44069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-44068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44068"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44068\/revisions"}],"predecessor-version":[{"id":44072,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44068\/revisions\/44072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44069"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}