{"id":44190,"date":"2015-06-03T13:54:50","date_gmt":"2015-06-03T17:54:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44190"},"modified":"2015-06-03T10:57:30","modified_gmt":"2015-06-03T14:57:30","slug":"rd-sale-de-lista-de-incumplimientos-graves-de-oit","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rd-sale-de-lista-de-incumplimientos-graves-de-oit\/","title":{"rendered":"RD sale de lista de incumplimientos graves de OIT"},"content":{"rendered":"<p><strong>S<img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-34178 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/estres-trabajo-300x225.jpg\" alt=\"estres-trabajo\" width=\"300\" height=\"225\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/estres-trabajo-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/estres-trabajo.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>ANTO DOMINGO, Rep\u00fablica Dominicana<\/strong>.- Por primera vez en los \u00faltimos a\u00f1os Rep\u00fablica Dominicana est\u00e1 fuera de la lista de pa\u00edses que incurren en incumplimientos graves ante Estados miembros de la Organizaci\u00f3n Internacional del Trabajo (OIT), as\u00ed lo inform\u00f3 la Ministra de Trabajo, Maritza Hern\u00e1ndez en la 104\u00b0 Conferencia Internacional del Trabajo, en Ginebra, Suiza.<!--more--><\/p>\n<p>\u201cEs necesario resaltar el compromiso que tenemos como Gobierno de implementar una pol\u00edtica laboral de inclusi\u00f3n y justicia social en beneficio de todos los dominicanos y dominicanas.\u00a0 El no aparecer en un listado de m\u00e1s de 20 pa\u00edses que no han cumplido con ciertas normas laborales nos llena de satisfacci\u00f3n y de compromiso de seguir aportando desde el Ministerio de trabajo en beneficio del pueblo dominicano, siguiendo las instrucciones del Presidente Danilo Medina\u201d.\u00a0 Resalt\u00f3 Hern\u00e1ndez.<\/p>\n<p>Maritza Hern\u00e1ndez preside la Delegaci\u00f3n de Rep\u00fablica Dominicana Ginebra. Como parte de la Delegaci\u00f3n est\u00e1n presentes el Director General del Instituto Nacional de Formaci\u00f3n T\u00e9cnico Profesional (INFOTEP), Rafael Ovalles, quien participa en las reuniones de la Comisi\u00f3n de Empleo y PYMES; Federico Gomera, Director de Inspecci\u00f3n de Trabajo, integrante de la Comisi\u00f3n de Normas y F\u00e9lix Hidalgo, Director General del Comit\u00e9 Nacional de Salarios, como parte de la Comisi\u00f3n sobre Econom\u00eda Informal, entre otros.<\/p>\n<p>La Delegaci\u00f3n dominicana est\u00e1 acompa\u00f1ada por Homero Luis Hern\u00e1ndez,\u00a0 Embajador Representante Permanente de la Rep\u00fablica Dominicana ante la Oficina de las Naciones Unidas, en Ginebra, Suiza.<\/p>\n<p>El conclave mundial se lleva a cabo del primero al 13 de junio, con el prop\u00f3sito de plantear el futuro del trabajo y la transici\u00f3n de la econom\u00eda informal a la econom\u00eda formal.<\/p>\n<p>En el encuentro se dan cita los delegados de trabajadores, empleadores y gobiernos de los 185 Estados miembros de la OIT, con la finalidad de tratar una gran diversidad de temas sobre la creaci\u00f3n de empleo decente y productivo.<\/p>\n<p>De igual manera abordan temas puntuales de la protecci\u00f3n social de los trabajadores, la aplicaci\u00f3n de las normas internacionales del trabajo, y las propuestas de programa y presupuesto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO, Rep\u00fablica Dominicana.- Por primera vez en los \u00faltimos a\u00f1os Rep\u00fablica Dominicana est\u00e1 fuera de la lista de pa\u00edses que incurren en incumplimientos graves ante Estados miembros de la Organizaci\u00f3n Internacional del Trabajo (OIT), as\u00ed lo inform\u00f3 la Ministra de Trabajo, Maritza Hern\u00e1ndez en la 104\u00b0 Conferencia Internacional del Trabajo, en Ginebra, Suiza.<\/p>\n","protected":false},"author":3,"featured_media":34178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-44190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44190"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44190\/revisions"}],"predecessor-version":[{"id":44191,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44190\/revisions\/44191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/34178"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}