{"id":44217,"date":"2015-06-04T08:28:49","date_gmt":"2015-06-04T12:28:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44217"},"modified":"2015-06-04T08:28:49","modified_gmt":"2015-06-04T12:28:49","slug":"muere-la-directora-de-efectos-visuales-de-juego-de-tronos-atacada-por-un-leon","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-la-directora-de-efectos-visuales-de-juego-de-tronos-atacada-por-un-leon\/","title":{"rendered":"Muere la directora de efectos visuales de \u00abJuego de Tronos\u00bb, atacada por un le\u00f3n"},"content":{"rendered":"<p>En el caso de \u00abJuego de Tronos\u00bb es dif\u00edcil que la realidad supere a la ficci\u00f3n, pero lo ocurrido con la responsable de efectos visuales de la serie de HBO rivaliza con las historias de George R. R. Martin. Katherine Chappell, de 29 a\u00f1os, ha muerto en Sud\u00e1frica despu\u00e9s de sufrir el ataque de un le\u00f3n, seg\u00fan informam en Huffpost TV.<!--more--> <img decoding=\"async\" class=\" aligncenter\" title=\"Muere la directora de efectos visuales de \u00abJuego de Tronos\u00bb, atacada por un le\u00f3n\" src=\"http:\/\/laguiatv.abc.es\/Media\/201506\/04\/katherinechappel-instagram--644x362.jpg\" alt=\"Muere la directora de efectos visuales de \u00abJuego de Tronos\u00bb, atacada por un le\u00f3n\" \/><br \/>\nLos hechos ocurrieron el lunes, en el transcurso de un safari en Johannesburgo. Chappel era conocida tambi\u00e9n por sus trabajos en el cine, en pel\u00edculas como \u00abLa vida secreta de Walter Mitty\u00bb, \u00abNo\u00e9\u00bb, \u00abCapit\u00e1n Am\u00e9rica: El Soldado de Invierno\u00bb y \u00abGodzilla\u00bb. Acababa de terminar \u00abEn el coraz\u00f3n del mar\u00bb, dirigida por Ron Howard.<\/p>\n<p>Scott Simpson, uno de los responsables de Lion Park, declar\u00f3 a la agencia Associated Press que el ataque ocurri\u00f3 cuando una leona se acerc\u00f3 al coche por el lado que ocupaba Chappelthe, quien hac\u00eda fotos con su c\u00e1mara. \u00abFueron todo el d\u00eda con la ventanilla bajada, algo que va contra nuestras normas. El le\u00f3n mordi\u00f3 a la chica a trav\u00e9s de la ventana\u00bb, explic\u00f3. El conductor del veh\u00edculo, por su parte, neg\u00f3 que hubieran tenido las ventanillas bajadas, y explic\u00f3 que pararon un momento para permitir que los pasajeros vieran de cerca a los leones, momento que aprovech\u00f3 Chappel para inclumir las normas, informa AFP. La leona, rapid\u00edsima, salt\u00f3 y la mordi\u00f3 en el cuello.<\/p>\n<p>El conductor, de 66 a\u00f1os, que est\u00e1 ingresado \u00abseriamente traumatizado\u00bb trat\u00f3 entonces de actuar, antes de que llegaran los encargados de segurida del parque, pero el ataque fue fulminante y no se pudo hacer nada por la vida de la joven. Simpson a\u00f1adi\u00f3 que el le\u00f3n no ser\u00e1 sacrificado, sino que ser\u00e1 enviado a otra zona del parque, alejada de los turistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el caso de \u00abJuego de Tronos\u00bb es dif\u00edcil que la realidad supere a la ficci\u00f3n, pero lo ocurrido con la responsable de efectos visuales de la serie de HBO rivaliza con las historias de George R. R. Martin. Katherine Chappell, de 29 a\u00f1os, ha muerto en Sud\u00e1frica despu\u00e9s de sufrir el ataque de un le\u00f3n, seg\u00fan informam en Huffpost TV.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-44217","post","type-post","status-publish","format-standard","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44217"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44217\/revisions"}],"predecessor-version":[{"id":44218,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44217\/revisions\/44218"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}