{"id":44314,"date":"2015-06-09T07:44:59","date_gmt":"2015-06-09T11:44:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44314"},"modified":"2015-06-09T07:44:59","modified_gmt":"2015-06-09T11:44:59","slug":"cardiologo-pide-amas-de-casa-cocinar-alimentos-con-equilibrio-de-sal","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cardiologo-pide-amas-de-casa-cocinar-alimentos-con-equilibrio-de-sal\/","title":{"rendered":"Cardi\u00f3logo pide amas de casa cocinar alimentos con equilibrio de sal"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/sal-en-los-alimentos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-44315 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/sal-en-los-alimentos.jpg\" alt=\"sal en los alimentos\" width=\"300\" height=\"226\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/sal-en-los-alimentos.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/sal-en-los-alimentos-100x75.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El director del Instituto Dominicano de Cardiolog\u00eda (IDC), doctor Ernesto D\u00edaz \u00c1lvarez, alert\u00f3 a la poblaci\u00f3n, sobre todo a las amas de casa, a cocer los alimentos con un adecuado equilibrio de sal. D\u00edaz \u00c1lvarez se\u00f1al\u00f3 que \u201cexiste una importante relaci\u00f3n entre el consumo inadecuado de sal con el desarrollo de enfermedades cardiovasculares<!--more-->, as\u00ed como las consecuencias derivadas, que se constituyen en infartos al miocardio, accidentes cerebrovasculares, descontrol en la presi\u00f3n arterial y mayor descomposici\u00f3n en la salud del paciente\u201d.<\/p>\n<p>Sostuvo que si la sal se consume en exceso resulta muy perjudicial al coraz\u00f3n, as\u00ed como si se consume en bajas cantidades, y agreg\u00f3 que lo ideal es preparar los alimentos con productos y sazones naturales.<\/p>\n<p>Al exponer en el XXV Congreso dominicano de Cardiolog\u00eda, el destacado cardi\u00f3logo dijo que lo ideal es consumir 6 gramos de sal al d\u00eda; lo cual equivale a una cucharadita de caf\u00e9 y que el aumento de esta cantidad en la ingesta diaria de la sal se constituye en una bomba de tiempo para la salud de los seres humanos.<\/p>\n<p>\u201cRep\u00fablica Dominicana es un pa\u00eds que, por cultura, se cocina y se come con exceso de condimentos y de sal; debemos hacer un sacrificio en el sabor de nuestra alimentaci\u00f3n y reducir significativamente la sal hasta llevarla a los 6 gramos diarios que necesita el cuerpo humano, para reponerse de la p\u00e9rdida de este sodio a trav\u00e9s del sudor, las heces, la orina y la saliva\u201d, plante\u00f3.<\/p>\n<p>Recomend\u00f3 que en la alimentaci\u00f3n diaria, para los dominicanos disminuir la sal, consumir menos embutidos; as\u00ed como evitar la comida pre cocida y en caso de consumo lavar esos alimentos para quitar el exceso de sal; evitar los caldos de pollo en cubitos y los sazones artificiales.<\/p>\n<p><strong>Publicidad responsable<\/strong><\/p>\n<p>En otro orden, D\u00edaz \u00c1lvarez pidi\u00f3 a las empresas fabricantes de productos alimenticios adoptar un marketing sano para vender sus productos, disminuyendo y quitando la sal en sus componentes.<\/p>\n<p>Dijo que con ello se contribuye a bajar las muertes relacionadas directamente con la hipertensi\u00f3n.<\/p>\n<p>Al respecto, dijo que la Rep\u00fablica Dominicana tiene m\u00e1s de dos millones de personas hipertensas a partir de los 18 a\u00f1os, lo cual constituye el 38.7% de la poblaci\u00f3n, lo que de hecho es alarmante debido a que coloca al pa\u00eds en el mismo nivel que los pa\u00edses del primer mundo y de poblaciones mucho m\u00e1s altas.<\/p>\n<p>Observ\u00f3 que en el continente Am\u00e9rica se registran unos 250 millones de hipertensos. \u201cEn el Instituto Dominicano de Cardiolog\u00eda el 45% de los fallecimientos corresponden a enfermedades cardiovasculares, y en gran medida relacionadas al consumo de sal\u201d, apunt\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del Instituto Dominicano de Cardiolog\u00eda (IDC), doctor Ernesto D\u00edaz \u00c1lvarez, alert\u00f3 a la poblaci\u00f3n, sobre todo a las amas de casa, a cocer los alimentos con un adecuado equilibrio de sal. D\u00edaz \u00c1lvarez se\u00f1al\u00f3 que \u201cexiste una importante relaci\u00f3n entre el consumo inadecuado de sal con el desarrollo de enfermedades cardiovasculares<\/p>\n","protected":false},"author":3,"featured_media":44315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-44314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44314"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44314\/revisions"}],"predecessor-version":[{"id":44316,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44314\/revisions\/44316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44315"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}