{"id":44364,"date":"2015-06-09T16:23:28","date_gmt":"2015-06-09T20:23:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44364"},"modified":"2015-06-09T16:25:10","modified_gmt":"2015-06-09T20:25:10","slug":"lista-de-los-futbolistas-mas-caros-del-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lista-de-los-futbolistas-mas-caros-del-mundo\/","title":{"rendered":"Lista de los futbolistas m\u00e1s caros del mundo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/lionel-messi-538278.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-44367 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/lionel-messi-538278-300x178.jpg\" alt=\"lionel-messi-538278\" width=\"300\" height=\"178\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/lionel-messi-538278-300x178.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/lionel-messi-538278-105x62.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/lionel-messi-538278.jpg 590w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El Observatorio del F\u00fatbol de la Universidad de Neuchatel, Suiza, tas\u00f3 al jugador del FC Barcelona, <strong>Lionel Messi<\/strong>, como el<strong> futbolista m\u00e1s caro del mundo<\/strong>. \u00abLa Pulga\u00bb fue tasada entre 255.3 y 280.8 millones de euros, m\u00e1s del doble que el portugu\u00e9s del Real Madrid, Cristiano Ronaldo.<!--more--><\/p>\n<p>El segundo puesto est\u00e1 ocupado por el belga del Chelsea, Eden Hazard, con un valor que oscila de 135.4 a 148.9 millones de euros. Relegado a un tercer puesto se encuentra Cristiano Ronaldo entre 113.3 a 124.7 en una temporada donde se qued\u00f3 con la Supercopa de Europa y el Mundial de Clubes junto al Real Madrid.<\/p>\n<p>Para fijar el precio de las transacciones de los futbolistas se considera el equipo con el que juegan, as\u00ed como la participaci\u00f3n que tienen con su selecci\u00f3n, la posici\u00f3n que juegan, condiciones de su contrato y su edad.<\/p>\n<p>Los 10 futbolistas m\u00e1s caros:<\/p>\n<ul>\n<li>Lionel Messi<\/li>\n<li>Eden Hazard<\/li>\n<li>Cristiano Ronaldo<\/li>\n<li>Neynar<\/li>\n<li>Sergio Ag\u00fcero<\/li>\n<li>Raheem Sterling<\/li>\n<li>Paul Pogba<\/li>\n<li>Diego Costa<\/li>\n<li>Alexis S\u00e1nchez<\/li>\n<li>James Rodr\u00edguez<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Observatorio del F\u00fatbol de la Universidad de Neuchatel, Suiza, tas\u00f3 al jugador del FC Barcelona, Lionel Messi, como el futbolista m\u00e1s caro del mundo. \u00abLa Pulga\u00bb fue tasada entre 255.3 y 280.8 millones de euros, m\u00e1s del doble que el portugu\u00e9s del Real Madrid, Cristiano Ronaldo.<\/p>\n","protected":false},"author":3,"featured_media":44367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-44364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44364"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44364\/revisions"}],"predecessor-version":[{"id":44369,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44364\/revisions\/44369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44367"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}