{"id":44504,"date":"2015-06-11T15:06:04","date_gmt":"2015-06-11T19:06:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44504"},"modified":"2015-06-11T15:06:04","modified_gmt":"2015-06-11T19:06:04","slug":"algunos-antiacidos-podrian-aumentar-riesgo-de-crisis-cardiacas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/algunos-antiacidos-podrian-aumentar-riesgo-de-crisis-cardiacas\/","title":{"rendered":"Algunos anti\u00e1cidos podr\u00edan aumentar riesgo de crisis card\u00edacas"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44505 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos.jpg\" alt=\"antibioticos\" width=\"356\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos-300x196.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos-105x69.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/antibioticos-400x260.jpg 400w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><\/a>Ciertos medicamentos que reducen la acidez de est\u00f3mago podr\u00edan estar ligados a un aumento del 16 a 21% del riesgo de una crisis card\u00edaca, seg\u00fan un estudio publicado el mi\u00e9rcoles. Conocidos como inhibidores de la bomba de protones (PPI, en ingl\u00e9s) como el Nexium, Prilosec o el PrevAcid, estos medicamentos figuran entre los m\u00e1s prescritos del mundo y representan un mercado de 14.000 millones de d\u00f3lares, indicaron los autores de esta investigaci\u00f3n de la facultad de medicina de Stanford, en California.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden\"><\/div>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Son eficaces para reducir la acidez del est\u00f3mago y evitar reflujos gastroesof\u00e1gicos.<\/p>\n<p>\u00abEl v\u00ednculo que constatamos entre la utilizaci\u00f3n de esos medicamentos y el aumento del riesgo de crisis card\u00edaca no prueba en s\u00ed mismo una relaci\u00f3n de causa y efecto\u00bb, sostuvo Nigam Shah, profesor adjunto de inform\u00e1tica biom\u00e9dica de la Universidad de Stanford y uno de los autores de la investigaci\u00f3n.<\/p>\n<p><strong>Remedios disponibles sin receta m\u00e9dica<\/strong><\/p>\n<p>Pero insisti\u00f3 que, visto que este an\u00e1lisis se realiz\u00f3 en base a las historias m\u00e9dicas electr\u00f3nicas de casi tres millones de personas, y tras rastrillar minuciosamente miles de millones de datos m\u00e9dicos, este v\u00ednculo deber\u00eda ser considerado como algo serio, sobre todo teniendo en cuenta que muchos de estos anti\u00e1cidos est\u00e1n disponibles sin receta m\u00e9dica.<\/p>\n<p>En Estados Unidos, los m\u00e9dicos hacen m\u00e1s de cien millones de recetas m\u00e9dicas por a\u00f1o para estos anti\u00e1cidos considerados como benignos &#8211;salvo para las personas que toman el anticoagulante Plavix&#8211;, indicaron los investigadores cuyo estudio fue publicado en la revista estadounidense PLOS ONE.<\/p>\n<p><strong>Los anti\u00e1cidos sin el presunto riesgo<\/strong><\/p>\n<p>\u00abEstos medicamentos no son quiz\u00e1 tampoco tan seguros como creemos\u00bb, coment\u00f3 Nicholas Leeper, profesor adjunto de cirug\u00eda cardiovascular de la Universidad de Stanford, principal autor del estudio.<\/p>\n<p>Si se compara con otra clase de anti\u00e1cidos conocidos como antihistam\u00ednicos H2, como el Pepcid, Tagamet o el Zantec, \u00e9stos no se vinculan con un aumento del riesgo card\u00edaco, seg\u00fan un an\u00e1lisis de los registros m\u00e9dicos de 2,9 millones de pacientes.<\/p>\n<p>Estos antihistam\u00ednicos H2 est\u00e1n presentes en el mercado hace m\u00e1s tiempo que los IPP y son razonablemente eficades contra la acidez de est\u00f3mago.<\/p>\n<p>Cabe destacar que se observ\u00f3 una mayor frecuencia de crisis card\u00edaca en personas que tomaban los anti\u00e1cidos IPP de menos de 45 a\u00f1os y con buena salud, concluyeron los investigadores.<\/p>\n<p>AFP \/ AM<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ciertos medicamentos que reducen la acidez de est\u00f3mago podr\u00edan estar ligados a un aumento del 16 a 21% del riesgo de una crisis card\u00edaca, seg\u00fan un estudio publicado el mi\u00e9rcoles. Conocidos como inhibidores de la bomba de protones (PPI, en ingl\u00e9s) como el Nexium, Prilosec o el PrevAcid, estos medicamentos figuran entre los m\u00e1s prescritos del mundo y representan un mercado de 14.000 millones de d\u00f3lares, indicaron los autores de esta investigaci\u00f3n de la facultad de medicina de Stanford, en California.<\/p>\n","protected":false},"author":12,"featured_media":44505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-44504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44504"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44504\/revisions"}],"predecessor-version":[{"id":44506,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44504\/revisions\/44506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44505"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}