{"id":44672,"date":"2015-06-17T09:34:38","date_gmt":"2015-06-17T13:34:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44672"},"modified":"2015-06-17T09:34:38","modified_gmt":"2015-06-17T13:34:38","slug":"golden-state-campeon-2015-regresa-al-trono-de-la-nba-tras-40-anos-de-espera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/golden-state-campeon-2015-regresa-al-trono-de-la-nba-tras-40-anos-de-espera\/","title":{"rendered":"Golden State Campe\u00f3n 2015: regresa al trono de la NBA tras 40 a\u00f1os de espera"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps_670.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-44671 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps_670.jpg\" alt=\"warriorschamps_670\" width=\"670\" height=\"377\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps_670.jpg 670w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps_670-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps_670-105x59.jpg 105w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/a><br \/>\nCLEVELAND &#8212; Los Golden State Warriors terminaron una sequ\u00eda sin campeonatos de 40 a\u00f1os al derrotar a los Cleveland Cavaliers 105-97 frustrando as\u00ed las aspiraciones de los locales de traer un campeonato a la ciudad.<!--more--><\/p>\n<p>Los Warriors ganaron tres partidos al hilo para remontar, tras caer en desventaja en la serie 2-1.Stephen Curry, el JMV de la temporada regular, y Andre Iguodala encabezaron el balanceador ataque de los Warriors combin\u00e1ndose para 50 puntos. Fue la primera vez que un JMV primerizo gana el trofeo desde el 1999-2000, cuando Shaquille O&#8217;Neal y los Lakers derrotaron a los Indiana Pacers.Draymond Green compil\u00f3 un triple doble con 16 puntos, 11 rebotes y 10 asistencias para los campeones.Los Cavaliers dominaron en la pintura: sumaron 56 rebotes, 16 m\u00e1s que Golden State, pero entregaron el bal\u00f3n en 16 ocasiones y lanzaron un raqu\u00edtico 23 por ciento del \u00e1rea de tres puntos. Hicieron una corrida desesperada apoyados en J.R.Smith en los \u00faltimos minutos del cuarto parcial, que ganaron 38-32, pero no fue suficiente para alcanzar a los Warriors.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44673 size-full aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps.jpg\" alt=\"\" width=\"646\" height=\"394\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps.jpg 646w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps-300x183.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/warriorschamps-105x64.jpg 105w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/a><\/p>\n<p>La derrota opac\u00f3 una espectacular serie de LeBron James, quien se convirti\u00f3 en el primer jugador en promediar 36.6 puntos, 12.4 rebotes and 8.8 asistencias por juego en una final. James termin\u00f3 con 32 puntos, incluyendo 17 rebotes, pero con una rotaci\u00f3n de s\u00f3lo siete jugadores, no recibi\u00f3 mucho apoyo de sus compa\u00f1eros.<\/p>\n<p>Qued\u00f3 a una asistencia de un triple doble.Fue el tercer t\u00edtulo para la franquicia de los Warriors, y el primero desde la temporada de 1974-75, cuando barrieron en cuatro partidos a los Washington Bullets. Previamente, cuando eran los Philadelphia Warriors ganaron en 1947 y en 1956.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLEVELAND &#8212; Los Golden State Warriors terminaron una sequ\u00eda sin campeonatos de 40 a\u00f1os al derrotar a los Cleveland Cavaliers 105-97 frustrando as\u00ed las aspiraciones de los locales de traer un campeonato a la ciudad.<\/p>\n","protected":false},"author":3,"featured_media":44673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-44672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44672"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44672\/revisions"}],"predecessor-version":[{"id":44674,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44672\/revisions\/44674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44673"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}