{"id":44853,"date":"2015-06-20T12:43:17","date_gmt":"2015-06-20T16:43:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44853"},"modified":"2015-06-20T12:43:17","modified_gmt":"2015-06-20T16:43:17","slug":"rescatan-dos-gavilanes-de-la-hispaniola-en-bayaguana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rescatan-dos-gavilanes-de-la-hispaniola-en-bayaguana\/","title":{"rendered":"Rescatan dos gavilanes de La Hispaniola en Bayaguana"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-44861 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan.jpg\" alt=\"infogavilan\" width=\"600\" height=\"594\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan-300x297.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan-76x75.jpg 76w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/infogavilan-120x120.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nBayaguana. <\/strong>Este viernes por la ma\u00f1ana fueron rescatados dos gavilanes de La Hispaniola (Buteo Ridgwayi) que permanec\u00edan enjaulados en esta localidad.<!--more--><\/p>\n<p>La denuncia fue hecha por las redes sociales el jueves, donde se publicaron dos fotograf\u00edas con las aves cautivas, que pertenecen a una especie en peligro cr\u00edtico de extinci\u00f3n.<\/p>\n<p>Carlos Voigt, administrador del Parque Nacional Los Haitises, y Thomas Hayes, bi\u00f3logo de The Peregrine Fund, responsables del programa de conservaci\u00f3n del gavil\u00e1n de La Hispaniola, se presentaron temprano por la ma\u00f1ana para constatar la denuncia y proceder a rescatar a las dos aves.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/693mY1HYZIY\" width=\"630\" height=\"410\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>El ciudadano que ten\u00eda los ejemplares en cautiverio explic\u00f3 que compr\u00f3 los pichones a dos ni\u00f1os que los bajaron de un nido en la localidad de Pilanc\u00f3n, cercano al Parque Nacional Los Haitises.<\/p>\n<p>El hombre asegur\u00f3 que su intenci\u00f3n era cuidarlas y educar a ni\u00f1os de la localidad sobre la protecci\u00f3n de la especie. Las entreg\u00f3 de manera voluntaria.<br \/>\n<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44857\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan4.jpg\" alt=\"gavilan4\" width=\"600\" height=\"354\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan4.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan4-300x177.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan4-105x62.jpg 105w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Thomas Hayes explica que el problema que representa este tipo de situaciones ya que comprar este tipo de animales promueve las capturas y en muchos de los casos no sobreviven. Aprovech\u00f3 la oportunidad para entregar material impreso sobre la conservaci\u00f3n de esta especie a las personas presentes.<br \/>\n<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44859\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan6.jpg\" alt=\"gavilan6\" width=\"600\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan6.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan6-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan6-105x63.jpg 105w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Las dos hembras juveniles de gavil\u00e1n ten\u00edan aproximadamente 28 d\u00edas en cautiverio. Ambas se encuentran en un buen estado f\u00edsico, salvo algunas peque\u00f1as heridas en las patas y el pico, por permanecer en un lugar no adecuado. A una le fueron cortadas las plumas de las alas, lo que complicar\u00e1 su rehabilitaci\u00f3n.<br \/>\n<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44856\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan3.jpg\" alt=\"gavilan3\" width=\"600\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan3.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan3-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan3-105x63.jpg 105w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Fueron llevadas a Punta Cana, donde The Peregrine Fund tiene un programa de repoblaci\u00f3n de estas aves y su retorno a la vida silvestre.<\/p>\n<p>Usando un sistema denominado \u00abhacking\u00bb, The Peregrine Fund intentar\u00e1 reinsertar estas aves en las pr\u00f3ximas semanas. El m\u00e9todo completo puede durar hasta tres meses.<\/p>\n<p>Las dos aves, a su llegada a Punta Cana, fueron colocadas en una caja especial para su evaluaci\u00f3n. Foto cortes\u00eda de Thomas Hayes.<\/p>\n<p><strong>Sobre el gavil\u00e1n de La Hispaniola:<\/strong><\/p>\n<p>Ave end\u00e9mica poco com\u00fan. Lamentablemente es la especie amenazada m\u00e1s cr\u00edtica de La Hispaniola. Desde hace m\u00e1s de 20 a\u00f1os no se ha reportado avistamiento en Hait\u00ed y solamente se encuentra en el Parque Nacional Los Haitises. En 2010 se calculaban de 250 a 300 individuos en estado silvestre.<\/p>\n<p>Se distingue por sus partes superiores color gris marr\u00f3n oscuro, partes inferiores grises con un lavado rojo marr\u00f3n. Los machos son m\u00e1s grises que las hembras y tienen el doblado del ala de un brillante color rojizo marr\u00f3n. La hembra tiene un pecho m\u00e1s claro, con m\u00e1s barras, y es un cuarto m\u00e1s grande que el macho.<\/p>\n<p>Pone dos huevos color blanco cremoso, muy moteados de naranja-rojo. Este gavil\u00e1n a menudo construye su nido justo encima de un nido activo de cigua palmera, el ave nacional de la Rep\u00fablica Dominicana. Los gavilanes agregan ramas m\u00e1s grandes en la parte superior de sin causar ning\u00fan da\u00f1o a las ciguas. Es como un edificio de dos pisos para los p\u00e1jaros. La anidaci\u00f3n se produce entre marzo y junio. Sus vuelos de cortejo empiezan en enero y la mayor\u00eda ocurre a finales de la ma\u00f1ana, mientras que la construcci\u00f3n del nido, labor que hacen mayormente los machos, empieza a finales de febrero. Las hembras se ocupan de casi toda la incubaci\u00f3n de los huevos, lo cual comienza a finales de marzo y toma de 10 a 12 semanas. Los machos capturan casi todas las presas que son llevadas al nido.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44854\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan1.jpg\" alt=\"gavilan1\" width=\"600\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan1.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan1-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan1-105x63.jpg 105w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Frecuentemente permite el acercamiento antes de salir volando. Se alimenta de lagartos, serpientes, ratones, murci\u00e9lagos y algunos anfibios, insectos y peque\u00f1as aves.<\/p>\n<p>Aunque esta especie parece preferir bosques no alterados en las tierras bajas y colinas, que vive en una gran variedad de h\u00e1bitats, incluyendo bosques, bosques secos y h\u00famedos tropicales, bosques de pino, bosque de piedra caliza c\u00e1rstica. Incluso se encuentra en el h\u00e1bitat humano alterado, incluyendo plantaciones, fragmentos de bosques degradados y tierras de pastoreo. Esta capacidad de adaptarse y sobrevivir en diferentes tipos de ambientes es una buena noticia para la especie. Mientras existan presas adecuadas y sitios de anidaci\u00f3n, \u00a0el gavil\u00e1n tiene una buena oportunidad de sobrevivir incluso en las zonas que han cambiado dr\u00e1sticamente por la gente o por otros factores.<\/p>\n<p>Desde finales del siglo 19, la poblaci\u00f3n del gavil\u00e1n ha estado en franco declive. Gran parte de su h\u00e1bitat natural est\u00e1 desapareciendo por la tala de los bosques y los incendios forestales, y muchas personas est\u00e1n caz\u00e1ndola o recolectado en los nidos los pichones \u00a0mayormente por miedo a que estos maten los pollos. Adem\u00e1s de estas dos amenazas principales, otros factores podr\u00edan estar afectando la capacidad de los gavilanes \u00a0para sobrevivir. Bi\u00f3logos de The Peregrine Fund, que trabajan con esta especie, han descubierto que las cr\u00edas suelen ser infestados con larvas de mosca que se \u00a0alimentan de los tejidos que a veces puede matar a las aves j\u00f3venes, si no se tratan. Los bi\u00f3logos no saben a\u00fan si la poblaci\u00f3n de esta mosca se ha incrementado debido a los cambios relacionados con los humanos en el h\u00e1bitat, el cambio clim\u00e1tico o las fluctuaciones c\u00edclicas de la poblaci\u00f3n, o si siempre ha estado presente en gran n\u00famero. Bi\u00f3logos roc\u00edan con una soluci\u00f3n los pichoes y el nido para evitar la picada de esta mosca.<\/p>\n<p>Hist\u00f3ricamente, los gavilanes anidan en \u00e1rboles altos y palmeras. Hoy en d\u00eda, con cada vez menos \u00e1rboles de madera en pie, los gavilanes anidan, casi en su totalidad, en las palmeras. Si bien estas son buenos de anidaci\u00f3n\u00a0 suponen un problema, las hojas de palma natural se despegan y se caen durante todo el a\u00f1o. Si las hojas de palma que apoyan el nido desaparecen mientras que todav\u00eda hay huevos o muy peque\u00f1os polluelos en el interior, esto podr\u00eda significar un problema. Si los huevos o los j\u00f3venes caen al suelo, hay muy pocas posibilidades de que sobrevivan.<\/p>\n<p>El gavil\u00e1n come casi cualquier cosa lo suficientemente peque\u00f1a como para atraparlo. Se alimentan de serpientes, lagartos, ranas y sapos, peque\u00f1os roedores, murci\u00e9lagos y aves. En un estudio de 20 parejas nidificantes, bi\u00f3logos identificaron\u00a0 que el 97% de las presas son reptiles.<\/p>\n<p>Los gavilanes \u00a0son cazadores pacientes. A diferencia de algunas otras aves rapaces que vuelan alto en el cielo en busca de alimento, los gavilanes pasan mucho tiempo encaramado en ramas de \u00e1rboles. Cuando logra ver a su presa se lanza en picada a troncos o el suelo. Durante la temporada de anidaci\u00f3n, y quiz\u00e1 todo el a\u00f1o, \u00a0son capaces de almacenar alimentos para ser consumidos despu\u00e9s. Esto les ahorra tiempo y energ\u00eda, y les permite tomar ventaja de una f\u00e1cil captura, en lugar de dejarlo escapar porque no tienen hambre en este momento.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44855\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan2.jpg\" alt=\"gavilan2\" width=\"600\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan2.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan2-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/gavilan2-105x63.jpg 105w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>The Peregrine Fund<\/strong>\u00a0ha estado estudiando al gavil\u00e1n de La Hispaniola desde 2000. Los bi\u00f3logos comenzaron mediante la b\u00fasqueda de los individuos y las parejas reproductoras en muchos lugares alrededor de la isla de La Espa\u00f1ola. A trav\u00e9s de estos estudios iniciales, se dieron cuenta de que el \u00fanico resto de la poblaci\u00f3n se encontraba en el Parque Nacional Los Haitises y comenzaron a centrar sus esfuerzos all\u00ed.<\/p>\n<p>Los bi\u00f3logos pasan largas jornadas en el campo, el senderismo por muchas horas en un intento de visitar todos los sitios de anidaci\u00f3n conocidos y encontrar otros nuevos. En cada nido, los bi\u00f3logos han visto las aves para aprender m\u00e1s acerca de su comportamiento, lo que est\u00e1n comiendo, la frecuencia con que alimentan a sus cr\u00edas, y todo tipo de otras cosas interesantes. Los bi\u00f3logos tambi\u00e9n se suben a los nidos para comprobar los pollitos, los tratan para infestaciones de moscas y les ponen anillos marcados en las patas. Este anillamiento de aves es una de aprender cuantos gavilanes juveniles sobreviven cada temporada de cr\u00eda y para reunir informaci\u00f3n sobre qu\u00e9 tan lejos y donde viajan despu\u00e9s de dejar a sus padres y territorio.<\/p>\n<p>M\u00e1s informaci\u00f3n en\u00a0<a href=\"http:\/\/www.peregrinefund.org\/\">www.peregrinefund.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bayaguana. Este viernes por la ma\u00f1ana fueron rescatados dos gavilanes de La Hispaniola (Buteo Ridgwayi) que permanec\u00edan enjaulados en esta localidad.<\/p>\n","protected":false},"author":3,"featured_media":44857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-44853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44853"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44853\/revisions"}],"predecessor-version":[{"id":44862,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44853\/revisions\/44862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44857"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}