{"id":44885,"date":"2015-06-20T13:32:20","date_gmt":"2015-06-20T17:32:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44885"},"modified":"2015-06-20T13:32:20","modified_gmt":"2015-06-20T17:32:20","slug":"fetichistas-y-enfermos-se-ponen-en-riesgo-por-consumir-leche-materna","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fetichistas-y-enfermos-se-ponen-en-riesgo-por-consumir-leche-materna\/","title":{"rendered":"Fetichistas y enfermos se ponen en riesgo por consumir leche materna"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/banco_de_leche_materna_kiss_and_cakes_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-44886 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/banco_de_leche_materna_kiss_and_cakes_3.jpg\" alt=\"banco_de_leche_materna_kiss_and_cakes_3\" width=\"640\" height=\"427\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/banco_de_leche_materna_kiss_and_cakes_3.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/banco_de_leche_materna_kiss_and_cakes_3-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/banco_de_leche_materna_kiss_and_cakes_3-105x70.jpg 105w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nLa leche materna se ha convertido en el \u201csuperalimento\u201d de moda para fisiculturistas, fetichistas y hasta pacientes de c\u00e1ncer.\u00a0Y seg\u00fan investigadores brit\u00e1nicos, este negocio del llamado \u201cOro liquido\u201d est\u00e1 alimentando un comercio a trav\u00e9s de internet que entra\u00f1a serios riesgos para la salud.<!--more--><\/p>\n<p>Un estudio de la Universidad Queen Mary de Londres se\u00f1ala que la venta de leche materna en sitios especializados y en las redes sociales es un negocio en expansi\u00f3n en todo el mundo.\u00a0La doctora Sarah Steele, de la Escuela de Medicina y Odontolog\u00eda de la Universidad de Londres, le dijo a la BBC que este mercado \u201cmuestra un crecimiento persistente en todo el mundo\u201d.<\/p>\n<p>P\u00e1ginas especializadas como Only the Breast -S\u00f3lo el Pecho-, una de las p\u00e1ginas de internet m\u00e1s conocidas al respecto, surgieron con la idea de ayudar a madres que no estaban produciendo suficiente leche para sus beb\u00e9s.\u00a0\u201d\u00bfEst\u00e1s sobreproduciendo y quieres poner tu oro l\u00edquido en venta? \u00bfTe interesa ganar dinero extra al mismo tiempo que haces espacio en tu refrigerador? se\u00f1ala el sitio Only the Breast.<\/p>\n<p>\u201cC\u00f3mo muchas madres ganan US$60 por d\u00eda vendiendo Oro L\u00edquido\u201d, se\u00f1ala otra p\u00e1gina de internet, thepennyhoarder.com, que trata de convencer a madres lactantes para que vendan su excedente de leche.\u00a0Pero una lectura de estos sitios por BBC Mundo indica que ninguno habla expresamente de venta de leche para el consumo de adultos.<\/p>\n<p>Sin embargo, expertos se\u00f1alan que, conectado a esto ha surgido un mercado informal dirigido a adultos que es dif\u00edcil de cuantificar porque en muchos casos se trata de arreglos entre dos partes.\u00a0\u201dClaramente, la leche materna se ha convertido en una mercanc\u00eda cuya venta est\u00e1 destinada no s\u00f3lo al consumo de beb\u00e9s, sino tambi\u00e9n como un suplemento nutritivo para fisioculturistas y atletas\u201d, se\u00f1ala Breastfeeding Medicine Academy, una entidad con sede en Los \u00c1ngeles, California.<\/p>\n<p><strong>Riesgos para la salud<\/strong><\/p>\n<p>La doctora Steele dijo que la mayor\u00eda de la leche que se vende por internet entra\u00f1a serios riesgos para la salud.\u00a0El estudio, publicado en la Revista de la Sociedad Real de Medicina de Reino Unido, se\u00f1al\u00f3 que el 93% de la leche materna que se vende online contiene bacterias, debido al uso de contenedores o equipos no esterilizados en su manejo.<\/p>\n<p>Steele destac\u00f3 que muchos pacientes de c\u00e1ncer est\u00e1n recurriendo a ella con el objetivo de fortalecer el sistema inmunol\u00f3gico.\u00a0Esta idea es falsa, se\u00f1al\u00f3 la investigadora, y destac\u00f3 que esta leche puede m\u00e1s bien representar un riesgo para estos pacientes.<\/p>\n<p>\u201cLos pacientes de c\u00e1ncer y de otras enfermedades presentan debilidades en el sistema inmunol\u00f3gico. Quienes venden este producto dicen que ayudar\u00eda a estos pacientes, pero m\u00e1s bien los pone en riesgo\u201d, enfatiz\u00f3.\u00a0Agrega que quienes recurren a esta alternativa \u201cest\u00e1n m\u00e1s bien exponi\u00e9ndose a virus y bacterias que pueden traer complicaciones\u201d.<\/p>\n<p>Muchos sitios est\u00e1n incentivando a madres lactantes para que vendan el exceso de leche.\u00a0Entre los riesgos asociados al consumo de esta leche, seg\u00fan la profesora Steele, entre los que destaca la hepatitis B y C, VIH y s\u00edfilis.\u00a0La doctora Steele le dijo a la BBC que la venta de este producto no est\u00e1 regulada y no cumple con los est\u00e1ndares sanitarios apropiados.\u00a0Onlythebreast.com le dijo a la BBC que asesora a sus usuarios para que pasteuricen la leche antes de usarla y que sus miembros son \u201chonestos e interesados \u00fanicamente en proveer leche saludable para beb\u00e9s\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La leche materna se ha convertido en el \u201csuperalimento\u201d de moda para fisiculturistas, fetichistas y hasta pacientes de c\u00e1ncer.\u00a0Y seg\u00fan investigadores brit\u00e1nicos, este negocio del llamado \u201cOro liquido\u201d est\u00e1 alimentando un comercio a trav\u00e9s de internet que entra\u00f1a serios riesgos para la salud.<\/p>\n","protected":false},"author":3,"featured_media":44886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-44885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44885"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44885\/revisions"}],"predecessor-version":[{"id":44887,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44885\/revisions\/44887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44886"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}