{"id":45254,"date":"2015-06-29T06:49:11","date_gmt":"2015-06-29T10:49:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=45254"},"modified":"2015-06-29T06:49:11","modified_gmt":"2015-06-29T10:49:11","slug":"empleados-del-popular-plantan-5260-arboles-de-caoba-en-sjm","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/empleados-del-popular-plantan-5260-arboles-de-caoba-en-sjm\/","title":{"rendered":"Empleados del Popular plantan 5,260 \u00e1rboles de caoba en SJM"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/reforestando-sjm.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-45255 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/reforestando-sjm.jpg\" alt=\"reforestando sjm\" width=\"361\" height=\"240\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/reforestando-sjm.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/reforestando-sjm-300x199.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/reforestando-sjm-105x70.jpg 105w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><\/a>M\u00e1s de 400 empleados del Banco Popular Dominicano sembraron en San Jos\u00e9 de las Matas, provincia Santiago, 5,260 \u00e1rboles de caoba hondure\u00f1a, dentro del proyecto del Plan Sierra, en la primera jornada de reforestaci\u00f3n que realiza la entidad bancaria en 2015.<!--more--><\/p>\n<p>Con esta actividad recurrente y que forma parte de la actuaci\u00f3n sostenible de la entidad bancaria desde 1999, el Popular busca contribuir a la reducci\u00f3n de la huella ambiental y aportar as\u00ed al cuidado del medio ambiente.<\/p>\n<p>Estas jornadas de reforestaci\u00f3n son realizadas por ejecutivos y empleados de la entidad financiera y de otras empresas del Grupo Popular, en coordinaci\u00f3n con la Fundaci\u00f3n Popular y el Plan Sierra.<\/p>\n<p>En esta ocasi\u00f3n, se sembraron plantas de caoba en las localidades de El Pinal, La Cuesta y San Jos\u00e9 de las Matas, las cuales, una vez alcanzada su etapa adulta, absorber\u00e1n casi 1,578 toneladas de producci\u00f3n potencial de captura de Co2 equivalente por a\u00f1o, contrarrestando de este modo los gases de efecto invernadero y la desertificaci\u00f3n de los suelos dominicanos.<\/p>\n<p>En adici\u00f3n, las siembras de estas matas de madera preciosa multiplica adem\u00e1s el valor de la finca, mejorando a futuro las condiciones econ\u00f3micas de los propietarios del terreno y su sostenibilidad en el tiempo.<\/p>\n<p>El Plan Sierra es uno de los proyectos de sostenibilidad ambiental m\u00e1s importantes del pa\u00eds, ya que las reforestaciones realizadas durante a\u00f1os impactan directamente en el equilibrio medioambiental de la isla de La Hispaniola, habiendo ayudado a recuperar el r\u00edo Yaque del Norte y sus afluentes y asegurando con ello la provisi\u00f3n de una gran parte del agua para el consumo humano y la producci\u00f3n agr\u00edcola de Santiago, el Cibao Central y el Valle del Cibao.<\/p>\n<p>\u201cSe trata de una de las principales iniciativas que nuestra entidad bancaria realiza con miras al desarrollo sostenible del pa\u00eds, mediante la inversi\u00f3n socialmente responsable que nos ha caracterizado desde nuestra fundaci\u00f3n, hace ya m\u00e1s de 51 a\u00f1os\u201d, explic\u00f3<br \/>\nel se\u00f1or Sergio Solari, vicepresidente ejecutivo de Tecnolog\u00eda.<\/p>\n<p>Adem\u00e1s de las jornadas de reforestaci\u00f3n con empleados del Grupo Popular, la organizaci\u00f3n aporta tambi\u00e9n recursos econ\u00f3micos cada a\u00f1o, que garantizan la capacitaci\u00f3n de la poblaci\u00f3n de estas sierras en el manejo racional y sostenible de sus suelos y bosques.<\/p>\n<p>Como en las dem\u00e1s jornadas de reforestaci\u00f3n, el personal del grupo financiero recibi\u00f3 la asistencia de voluntarios de la comunidad y t\u00e9cnicos del Plan Sierra, con quienes posteriormente compartieron un almuerzo. &#8211; See more at: http:\/\/www.elcaribe.com.do\/2015\/06\/29\/empleados-del-popular-plantan-5260-arboles-caoba-sjm#sthash.pefGcmgk.dpuf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 400 empleados del Banco Popular Dominicano sembraron en San Jos\u00e9 de las Matas, provincia Santiago, 5,260 \u00e1rboles de caoba hondure\u00f1a, dentro del proyecto del Plan Sierra, en la primera jornada de reforestaci\u00f3n que realiza la entidad bancaria en 2015.<\/p>\n","protected":false},"author":3,"featured_media":45255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-45254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=45254"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45254\/revisions"}],"predecessor-version":[{"id":45257,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45254\/revisions\/45257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/45255"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=45254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=45254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=45254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}