{"id":45622,"date":"2015-07-06T10:48:43","date_gmt":"2015-07-06T14:48:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=45622"},"modified":"2015-07-06T10:48:43","modified_gmt":"2015-07-06T14:48:43","slug":"a-los-52-anos-la-actriz-vanessa-williams-se-caso-por-tercera-vez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-los-52-anos-la-actriz-vanessa-williams-se-caso-por-tercera-vez\/","title":{"rendered":"A los 52 a\u00f1os, la actriz Vanessa Williams se cas\u00f3 por tercera vez"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/vanessa-Williams.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-45623 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/vanessa-Williams.jpg\" alt=\"vanessa Williams\" width=\"770\" height=\"433\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/vanessa-Williams.jpg 770w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/vanessa-Williams-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/vanessa-Williams-105x59.jpg 105w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><br \/>\nLa actriz y cantante <b>Vanessa Wiliams <\/b>contrajo matrimonio el s\u00e1bado con <b>Jim Skrip<\/b>, con quien se prometi\u00f3 el a\u00f1o pasado. En la ceremonia \u00edntima, s\u00f3lo particip\u00f3 un peque\u00f1o grupo de familiares y amigo, inform\u00f3 <i><b>People.<\/b><\/i><br \/>\n<!--more--><i><b><br \/>\n<\/b><\/i>El tercer matrimonio se da luego de m\u00e1s de diez a\u00f1os de que la neoyorquina se divorciara del basquetbolista canadiense <b>Rick Fox<\/b>, con quien tuvo a su hija Sasha.<\/p>\n<p>En una entrevista con la revista<i><b><a href=\"http:\/\/madamenoire.com\/\"> Madame Noir<\/a><\/b><\/i>, la estrella de<b><i> Desperate Housewives<\/i><\/b> revel\u00f3 detalles de c\u00f3mo conoci\u00f3 a su nuevo marido en un <b>viaje de vacaciones<\/b> con su hija en<b> Egipto<\/b>. Seg\u00fan cont\u00f3 entonces, desde el primer momento tuvieron muchas cosas que decirse. Adem\u00e1s, relat\u00f3, que \u00e9l no es un<b> \u00absuper fan<\/b>\u00bb suyo.<\/p>\n<p>Williams salt\u00f3 a la fama en 1983, a\u00f1o en que se convirti\u00f3 en la primera Miss Am\u00e9rica afroamericana. Desde entonces ha participado de una larga lista de series de televisi\u00f3n, pel\u00edculas, e incluso grab\u00f3 varios discos.<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La actriz y cantante Vanessa Wiliams contrajo matrimonio el s\u00e1bado con Jim Skrip, con quien se prometi\u00f3 el a\u00f1o pasado. En la ceremonia \u00edntima, s\u00f3lo particip\u00f3 un peque\u00f1o grupo de familiares y amigo, inform\u00f3 People.<\/p>\n","protected":false},"author":12,"featured_media":45623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-45622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=45622"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45622\/revisions"}],"predecessor-version":[{"id":45624,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45622\/revisions\/45624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/45623"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=45622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=45622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=45622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}