{"id":45768,"date":"2015-07-12T02:27:56","date_gmt":"2015-07-12T06:27:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=45768"},"modified":"2015-07-12T02:29:36","modified_gmt":"2015-07-12T06:29:36","slug":"manute-bol-el-basquetbolista-de-231-metros-que-gasto-su-dinero-en-obras-beneficas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/manute-bol-el-basquetbolista-de-231-metros-que-gasto-su-dinero-en-obras-beneficas\/","title":{"rendered":"Manute Bol, el basquetbolista de 2,31 metros que gast\u00f3 su dinero en obras ben\u00e9ficas"},"content":{"rendered":"<div id=\"Header-nota\">\n<div id=\"entradilla\">\n<div id=\"DTElementID-5895600\" class=\"QuickRead\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-45769 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol.jpg\" alt=\"manute bol\" width=\"666\" height=\"409\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol.jpg 1416w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol-300x184.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol-1024x629.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol-105x65.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/manute-bol-440x270.jpg 440w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><br \/>\n<\/a>El espigado jugador de b\u00e1squetbol muri\u00f3 en 2010 a los 47 a\u00f1os a causa del s\u00edndrome de Stevens-Johnson, Bol qued\u00f3 en la ruina.<\/p>\n<p><object id=\"limelight_player_963689\" class=\"LimelightEmbeddedPlayerFlash swfPrev-beforeswfanchor0 swfNext-afterswfanchor0\" tabindex=\"0\" data=\"http:\/\/assets.delvenetworks.com\/player\/loader.swf\" type=\"application\/x-shockwave-flash\" name=\"limelight_player_963689\" width=\"100%\" height=\"100%\"><\/object><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more-->Bol, ya en la ruina por sus ayudas a obras ben\u00e9ficas en su pa\u00eds africano, fue abandonado por su mujer e hijos.<\/p>\n<div id=\"text\">\n<div id=\"DTElementID-5895601\" class=\"WebText\">\n<p>Muy pocos se acordar\u00e1n de Manute Bol, un p\u00edvot sudan\u00e9s que jug\u00f3 entre 1986 y 1994 en la NBA, m\u00e1s que todo conocido por sus 2,31 metros de estatura, que lo convirtieron en toda una atracci\u00f3n en las canchas estadounidenses.<\/p>\n<p>La historia de Bol, quien falleci\u00f3 en el 2010 a causa del s\u00edndrome de Stevens-Johnson, es muy interesante y te la resumimos en estos p\u00e1rrafos.<\/p>\n<p><strong>El extinto africano, tras dejar la NBA, perdi\u00f3 todo el dinero que gan\u00f3 en sus casi 10 a\u00f1os de profesional del baloncesto americano en iniciativas humanitarias<\/strong>para su pa\u00eds.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>Visit\u00f3 muchos campos de refugiados en su Sud\u00e1n natal.<\/strong> Tras renunciar a convertirse al Islam, el Gobierno sudan\u00e9s le acus\u00f3 de apoyar a la guerrilla del Ej\u00e9rcito de Liberaci\u00f3n del Pueblo de Sud\u00e1n, que de hecho, est\u00e1 liderado por miembros de la tribu Dinka, a la que Bol pertenece.<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" title=\"1350379112_extras_albumes_0(1024x768)\" src=\"http:\/\/www.diez.hn\/csp\/mediapool\/sites\/dt.common.streams.StreamServer.cls?STREAMOID=mos$vlZ5q4SWqSxaY4$_A8$daE2N3K4ZzOUsqbU5sYu4pWJOZPb3gWxbZRy0JlTnWCsjLu883Ygn4B49Lvm9bPe2QeMKQdVeZmXF$9l$4uCZ8QDXhaHEp3rvzXRJFdy0KqPHLoMevcTLo3h8xh70Y6N_U_CryOsw6FTOdKL_jpQ-&amp;CONTENTTYPE=image\/jpeg\" alt=\"1350379112_extras_albumes_0(1024x768)\" width=\"631\" height=\"768\" border=\"0\" \/><\/div>\n<div>\n<p>El sudan\u00ed fue uno de los mejores en su puesto ya que la estatura era su aliado.<\/p>\n<\/div>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">No le permit\u00edan salir del pa\u00eds hasta que el propio Gobierno de los Estados Unidos intervino para conseguirlo.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>Bol cre\u00f3 una fundaci\u00f3n, la Ring True Fundation<\/strong>, en la que se estima que se gast\u00f3 su fortuna de 3,5 millones de d\u00f3lares.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">Arruinado, <strong>tuvo que recurrir a un combate de boxeo televisado<\/strong> contra una antigua estrella del football americano <strong>para recaudar fondos.<\/strong><\/p>\n<div><img loading=\"lazy\" decoding=\"async\" title=\"manute-bol-in-2002(1024x768)\" src=\"http:\/\/www.diez.hn\/csp\/mediapool\/sites\/dt.common.streams.StreamServer.cls?STREAMOID=YTGjfBTzmbvf8S$ayowBMM$daE2N3K4ZzOUsqbU5sYuv6alKMnTZoMX4U3cuopnnWCsjLu883Ygn4B49Lvm9bPe2QeMKQdVeZmXF$9l$4uCZ8QDXhaHEp3rvzXRJFdy0KqPHLoMevcTLo3h8xh70Y6N_U_CryOsw6FTOdKL_jpQ-&amp;CONTENTTYPE=image\/jpeg\" alt=\"manute-bol-in-2002(1024x768)\" width=\"403\" height=\"768\" border=\"0\" \/><\/div>\n<div>\n<p>Manute con este combate que realiz\u00f3 gan\u00f3 \u00abunos\u00bb d\u00f3lares.<\/p>\n<\/div>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">Fue el precio que le hizo pagar la cadena FOX a cambio de sacar el n\u00famero de tel\u00e9fono de su fundaci\u00f3n.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">Tambi\u00e9n <strong>accedi\u00f3 a fichar por un d\u00eda por el equipo Indianapolis Ice de hockey<\/strong>sobre hielo e incluso fue jockey de h\u00edpica.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">Antes de fallecer,<strong> la artritis afectaba seriamente sus mu\u00f1ecas y sus rodillas<\/strong>, pero no segu\u00eda un tratamiento m\u00e9dico adecuado por falta de recursos econ\u00f3micos.<\/p>\n<div><img decoding=\"async\" title=\"UntitledSSD-1(1024x768)\" src=\"http:\/\/www.diez.hn\/csp\/mediapool\/sites\/dt.common.streams.StreamServer.cls?STREAMOID=iHCP_pErXvhPikvsP9sFk8$daE2N3K4ZzOUsqbU5sYsqftVf8$lLghzm4d92uXx1WCsjLu883Ygn4B49Lvm9bPe2QeMKQdVeZmXF$9l$4uCZ8QDXhaHEp3rvzXRJFdy0KqPHLoMevcTLo3h8xh70Y6N_U_CryOsw6FTOdKL_jpQ-&amp;CONTENTTYPE=image\/jpeg\" alt=\"UntitledSSD-1(1024x768)\" border=\"0\" \/><\/div>\n<div>\n<p>Bol ingresando a la pista de hielo cuando acept\u00f3 ser de los Indianapolis Ice de hockey.<\/p>\n<\/div>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>Su mujer le abandon\u00f3 y se march\u00f3 a vivir a Nueva Jersey<\/strong> con sus cuatro hijos. Tuvo que vender sus casas de Egipto y Jartum, y su casa de los Estados Unidos fue embargada, aunque la pudo recuperar posteriormente.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>Bol estuvo viviendo en una casa alquilada<\/strong> en los suburbios de Khartoum, con dos esposas, un hijo y 14 parientes.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>Tambi\u00e9n, antes de morir lider\u00f3 una la Sudan Freedom Walk<\/strong>, unas marchas pac\u00edficas realizadas en Estados Unidos como protesta por el genocidio en Darfur, Sud\u00e1n.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">El gigant\u00f3n Manute Bol vivi\u00f3 sus \u00faltimos d\u00edas en Kansas, Estados Unidos.<\/p>\n<p><strong>JUG\u00d3 EN EGIPTO Y UGANDA<\/strong><\/p>\n<p>En su \u00e9poca en El Cairo fund\u00f3 una escuela de baloncesto en la que se form\u00f3 el actual jugador de los Cleveland Luol Deng, un refugiado sudan\u00e9s en Egipto.<\/p>\n<p>Adem\u00e1s, ah\u00ed coincidi\u00f3 en los Washington Bullets (hoy Wizards) con el jugador m\u00e1s peque\u00f1o de la historia de la NBA, Muggsy Bogues (1,60).<\/p>\n<p>La leyenda cuenta que lleg\u00f3 a Estados Unidos despu\u00e9s de que un cazatalentos escuchara a un estudiante sudan\u00e9s \u201cque ten\u00eda un primo que med\u00eda 2,31\u2033.<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" title=\"cad0c44d2ee65fc29d91ce5ff6b299fd(1024x768)\" src=\"http:\/\/www.diez.hn\/csp\/mediapool\/sites\/dt.common.streams.StreamServer.cls?STREAMOID=RfViytybJqOI8DeBv4S3_M$daE2N3K4ZzOUsqbU5sYspdDcvHXYB3g7JVZIf9jeWWCsjLu883Ygn4B49Lvm9bPe2QeMKQdVeZmXF$9l$4uCZ8QDXhaHEp3rvzXRJFdy0KqPHLoMevcTLo3h8xh70Y6N_U_CryOsw6FTOdKL_jpQ-&amp;CONTENTTYPE=image\/jpeg\" alt=\"cad0c44d2ee65fc29d91ce5ff6b299fd(1024x768)\" width=\"578\" height=\"768\" border=\"0\" \/><\/div>\n<div>\n<p>La altura de Bol era impresionante, con respecto a sus compa\u00f1eros.<\/p>\n<\/div>\n<p>Tambi\u00e9n se dice que nada m\u00e1s llegar a los Estados Unidos e intentar un mate, se rompi\u00f3 todos los dientes tras chocar su boca con el aro.<\/p>\n<p><strong>La historia de Bol inspir\u00f3 la pel\u00edcula \u00abUna tribu en la cancha\u00bb<\/strong>, protagonizada por Kevin Bacon.<\/p>\n<p>El rumano Gheorghe Muresan le desbanc\u00f3 como el jugador m\u00e1s alto en jugar nunca en la NBA, pero s\u00f3lo por unos mil\u00edmetros.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\"><strong>PERFIL<\/strong><br \/>\nBol naci\u00f3 el 16 de octubre de 1962 en Gogrial, Sud\u00e1n. <strong>Con 18 a\u00f1os lleg\u00f3 a los Estados Unidos y en 1985<\/strong> fue elegido en el draft por los Washington Bullets, donde permaneci\u00f3 tres a\u00f1os.<\/p>\n<p style=\"border: 0px; margin: 5px 0px 0px; outline: 0px; padding: 7.4px 0px; vertical-align: baseline; color: #666666; font-size: 15px; line-height: 1.5em; background: 0px 0px;\">Jug\u00f3 en Golden State Warriors, en Philadelphia 76ers, en <strong>Miami Heat<\/strong> y de nuevo en los Bullets, en los Sixers y en los Warriors.<\/p>\n<p>Manute Bol destac\u00f3, obviamente por su altura, como uno de los mejores taponadores de la historia de la NBA.<\/p>\n<p><a href=\"http:\/\/www.diez.hn\/notodoesfutbol\/767056-99\/manute-bol-el-basquetbolista-de-231-metros-que-gast%C3%B3-su-dinero-en\">FUENTE<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El espigado jugador de b\u00e1squetbol muri\u00f3 en 2010 a los 47 a\u00f1os a causa del s\u00edndrome de Stevens-Johnson, Bol qued\u00f3 en la ruina.<\/p>\n","protected":false},"author":12,"featured_media":45769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312,9],"tags":[],"class_list":["post-45768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=45768"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45768\/revisions"}],"predecessor-version":[{"id":45772,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45768\/revisions\/45772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/45769"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=45768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=45768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=45768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}