{"id":45893,"date":"2015-07-14T10:34:33","date_gmt":"2015-07-14T14:34:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=45893"},"modified":"2015-07-14T10:34:33","modified_gmt":"2015-07-14T14:34:33","slug":"martelly-presiona-para-que-rd-negocie-repatriaciones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/martelly-presiona-para-que-rd-negocie-repatriaciones\/","title":{"rendered":"Martelly Presiona Para Que RD Negocie Repatriaciones"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/martelly1-300x197.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-45899 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/martelly1-300x197.jpg\" alt=\"martelly1-300x197\" width=\"300\" height=\"197\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/martelly1-300x197.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/martelly1-300x197-105x69.jpg 105w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El presidente haitiano, Michel Martelly, reiter\u00f3 ayer, con motivo de su reuni\u00f3n con una delegaci\u00f3n de la Organizaci\u00f3n de Estados Americanos (OEA), el compromiso de su gobierno en buscar una \u201csoluci\u00f3n pac\u00edfica\u201d a la crisis migratoria que mantiene con Rep\u00fablica Dominicana.<!--more--><\/p>\n<p>Al igual que lo hiciera el canciller haitiano, Lener Renauld, la semana pasada ante el Consejo Permanente de la OEA, Martelly pidi\u00f3 ayer a la comunidad internacional que intervenga en esta crisis.<\/p>\n<p>En su cuenta oficial de la red social Twitter, Martelly pidi\u00f3 ayer la \u201cfirme intervenci\u00f3n de la comunidad internacional\u201d para lograr que Rep\u00fablica Dominicana negocie las condiciones en que se llevar\u00e1n a cabo las posibles repatriaciones.<\/p>\n<p>Reiter\u00f3 as\u00ed mismo sus \u201cpreocupaciones\u201d expresadas el 3 de julio en Barbados en la Cumbre de la Comunidad del Caribe (Caricom), donde solicit\u00f3 una soluci\u00f3n pac\u00edfica a la crisis entre ambos pa\u00edses.<\/p>\n<p>\u201cHait\u00ed preferir\u00eda mantenerse en la mesa de negociaciones con (Rep\u00fablica) Dominicana para resolver la crisis pac\u00edficamente\u201d, dijo.<\/p>\n<p>Una delegaci\u00f3n de la OEA, encabezada por su secretario de Asuntos Pol\u00edticos, el mexicano Francisco Guerrero, lleg\u00f3 anteayer al pa\u00eds para tratar el problema migratorio con Rep\u00fablica Dominicana.<\/p>\n<p>La delegaci\u00f3n arrib\u00f3 tras concluir una visita de tres d\u00edas a territorio dominicano que, seg\u00fan indicaron fuentes de la OEA a Efe, fue \u201cedificante, positiva y constructiva\u201d.<\/p>\n<p>Antes del encuentro con Martelly, la misi\u00f3n se reuni\u00f3 en la base de la Misi\u00f3n de la ONU para la Estabilizaci\u00f3n de Hait\u00ed (Minustah) en el pa\u00eds con el equipo de trabajo de Naciones Unidas.<\/p>\n<p>Tambi\u00e9n visit\u00f3 el puesto fronterizo de Anse-\u00e0-Pitres, entre la Rep\u00fablica Dominicana y Hait\u00ed y el mercado binacional de la provincia Pedernales.<\/p>\n<p>Fuente: Listin Diario<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente haitiano, Michel Martelly, reiter\u00f3 ayer, con motivo de su reuni\u00f3n con una delegaci\u00f3n de la Organizaci\u00f3n de Estados Americanos (OEA), el compromiso de su gobierno en buscar una \u201csoluci\u00f3n pac\u00edfica\u201d a la crisis migratoria que mantiene con Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":12,"featured_media":45899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-45893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=45893"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45893\/revisions"}],"predecessor-version":[{"id":45900,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/45893\/revisions\/45900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/45899"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=45893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=45893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=45893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}