{"id":46083,"date":"2015-07-20T09:11:30","date_gmt":"2015-07-20T13:11:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=46083"},"modified":"2015-09-23T20:35:06","modified_gmt":"2015-09-24T00:35:06","slug":"hasta-donde-estas-dispuesto-a-llegar-para-recargar-tu-celular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hasta-donde-estas-dispuesto-a-llegar-para-recargar-tu-celular\/","title":{"rendered":"\u00bfHasta d\u00f3nde est\u00e1s dispuesto a llegar para recargar tu celular?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/630pilacel4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46084\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/630pilacel4.jpg\" alt=\"630pilacel4\" width=\"630\" height=\"354\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/630pilacel4.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/630pilacel4-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/630pilacel4-105x59.jpg 105w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><\/p>\n<p>Justo antes de comenzar una funci\u00f3n en un teatro de Broadway, en Nueva York,<strong> una persona del p\u00fablico salt\u00f3 al escenario<\/strong> para conectar su celular a lo que pens\u00f3 era un tomacorriente.<!--more--><span id=\"more-23174\"><\/span><\/p>\n<p>La situaci\u00f3n fue inesperada y caus\u00f3 sorpresa a los presentes, pero a muchos le pareci\u00f3 algo normal.<\/p>\n<p>\u00bfLa necesidad de estar conectados nos est\u00e1 llevando demasiado lejos?<br \/>\n<strong><br \/>\n<\/strong><\/p>\n<h3><strong>Cayendo bajo<\/strong><\/h3>\n<p>El episodio que <strong>paraliz\u00f3 moment\u00e1neamente el inicio<\/strong> de la obra \u201cHand to God\u201d, trajo reacciones en las redes sociales.<\/p>\n<p>\u201cEl equipo del teatro tuvo que detener el inicio del show, retirar el celular del escenario, y hacer un anuncio por los parlantes para recordarle a la gente que ese tipo de comportamiento estaba prohibido\u201d, escribi\u00f3 Chris York en Facebook.<\/p>\n<div class=\"photo\">\n<p><img decoding=\"async\" src=\"http:\/\/fotos2013.cloud.noticias24.com\/630pilacel2.jpg\" alt=\"\" \/><\/p>\n<div class=\"caption\">En esta foto de la obra \u201cHand to God\u201d, se aprecia el enchufe que fue utilizado por un miembro del p\u00fablico para tratar de recargar su tel\u00e9fono antes que comenzara la funci\u00f3n.<\/div>\n<\/div>\n<p>\u201c<strong>Hay que tener modales en el teatro<\/strong>. Por Dios, sentido com\u00fan. \u00bfDe verdad, hay que llegar a eso?\u201d, concluy\u00f3 York.<\/p>\n<p>Pareciera una an\u00e9cdota de las peores situaciones en un teatro, sobre todo porque el tomacorriente era de utiler\u00eda.<\/p>\n<p>No obstante, muchos de nosotros hemos estado en ese dilema, buscando una fuente de electricidad cuando vemos que nuestro tel\u00e9fono comienza a mostrar la barra roja que antecede a la<strong> desconexi\u00f3n con nuestro mundo<\/strong>.<\/p>\n<p>No era as\u00ed no hace tanto. Es decir, cuando los tel\u00e9fonos solo hac\u00edan llamadas, conservar la bater\u00eda era bastante sencillo. Tu celular parec\u00eda un ladrillo, pero la pila le pod\u00eda durar al menos tres d\u00edas.<\/p>\n<p>Ahora, mantener tu tel\u00e9fono en la \u201czona verde\u201d puede llevar a las personas a realizar las m\u00e1s incre\u00edbles maromas: mantenerse en la punta de los pies como las bailarinas para alcanzar un enchufe, agacharse en cuclillas en el piso de un ba\u00f1o p\u00fablico, maniobrar con unos cables debajo de una mesa en un caf\u00e9.<br \/>\n<strong><br \/>\n<\/strong><\/p>\n<h3><strong>La fuente de la desesperaci\u00f3n<\/strong><\/h3>\n<p>Estas actitudes desesperadas se hacen cada vez m\u00e1s comunes a medida que nuestros tel\u00e9fonos tienen m\u00e1s aplicaciones, las cuales pr\u00e1cticamente se devoran las pilas.<\/p>\n<p>\u201cLas bater\u00edas est\u00e1n trabajando tiempo extra, sin que la gente tome esto en consideraci\u00f3n, como si se tratara de unos trabajadores poco apreciados. En realidad las pilas no han avanzado tan r\u00e1pido como el resto del hardware de tu tel\u00e9fono\u201d, explica el corresponsal de la BBC en Silicon Valley, David Lee.<\/p>\n<div class=\"photo derecha\">\n<p><img decoding=\"async\" src=\"http:\/\/fotos2013.cloud.noticias24.com\/630pilacel3.jpg\" alt=\"\" \/><\/p>\n<div class=\"caption\">Las aplicaciones instaladas en los celulares devoran la bater\u00eda, lo cual genera mayor desespero en la busca de fuentes de energ\u00eda.<\/div>\n<\/div>\n<p>En este sentido, los fabricantes est\u00e1n trabajando arduamente <strong>para resolver el problema de la carga<\/strong>. Por ejemplo, el \u00faltimo modelo de Samsung requiere solo de 10 minutos para recargarse, comenta Lee.<\/p>\n<p>Sin embargo, las pilas est\u00e1n peleando una batalla perdida, porque muchas de las aplicaciones de los tel\u00e9fonos secan la energ\u00eda desde el mismo momento que se encienden.<\/p>\n<p>\u201cLos fabricantes tambi\u00e9n est\u00e1n estudiando c\u00f3mo pueden modernizar los software para ahorrar energ\u00eda\u201d, indica Lee. Los tel\u00e9fonos podr\u00e1n tener un modo de bajo consumo en la pr\u00f3xima edici\u00f3n del Apple iOS, lo cual<strong> permitir\u00e1 extender la vida del equipo<\/strong> por unas pocas horas, aun cuando implica reducir significativamente la funcionalidad del tel\u00e9fono.<\/p>\n<h3><strong>Evitar la nomofobia<\/strong><\/h3>\n<p>M\u00e1s all\u00e1 de los cambios a los tel\u00e9fonos, hay toda una industria de dispositivos port\u00e1tiles para cargar los equipos que se est\u00e1 desarrollando velozmente.<\/p>\n<p>Greenlight Planet, un fabricante y comercializador de l\u00e1mparas alimentadas con energ\u00eda solar, agreg\u00f3 un enchufe a sus productos luego de recibir m\u00faltiples solicitudes de sus clientes.<\/p>\n<div class=\"photo\">Cient\u00edficos indican que al no poder utilizar el celular algunas personas sufren ansiedad y mayor estr\u00e9s, una condici\u00f3n que se llama nomofobia.<\/div>\n<p>\u201cMuchos hogares que se encuentran fuera de la red el\u00e9ctrica en el este de \u00c1frica nos han dicho que es bueno tener luz, pero que tener el celular encendido es una necesidad\u201d, comenta Radhika Thakkar, vicepresidente del \u00e1rea de <strong>desarrollo de negocios globales en la compa\u00f1\u00eda<\/strong>.<\/p>\n<p>Thakkar advierte que a medida que el uso de celulares aumenta en estos mercados, las personas los est\u00e1n utilizando para muchos fines m\u00e1s all\u00e1 de efectuar llamadas. Los tel\u00e9fonos son ahora una herramienta indispensable para realizar transacciones bancarias, obtener informaci\u00f3n sobre las cosechas, as\u00ed como para conectarse a Internet.<\/p>\n<p>En todo el mundo estas innovaciones est\u00e1n ayudando a la gente a mantener sus tel\u00e9fonos encendidos por per\u00edodos m\u00e1s largos, mucho m\u00e1s desde que crece el n\u00famero de personas que sufren de nomofobia, o ansiedad por estar separado de tu celular.<\/p>\n<p>Una investigaci\u00f3n de la Universidad de Misuri, en Estados Unidos, revela que esta aflicci\u00f3n puede elevar el nivel de estr\u00e9s y generar da\u00f1os psicol\u00f3gicos severos.<\/p>\n<p>Los hallazgos cient\u00edficos indican que <strong>cuando nos separamos del celular<\/strong> \u201cexperimentamos una disminuci\u00f3n de nuestro ser y pasamos a un estado psicol\u00f3gico negativo\u201d.<\/p>\n<p>Esto puede explicar por qu\u00e9 hay personas que est\u00e1 dispuestas a hacer cualquier cosa, incluso saltar sobre un escenarios ante cientos de personas, con tal de no sentirse aterrorizado por el\u00a0<strong>mensaje de \u201cbater\u00eda baja\u201d en su tel\u00e9fono<\/strong>.<\/p>\n<p>Fuente:BBC Mundo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Justo antes de comenzar una funci\u00f3n en un teatro de Broadway, en Nueva York, una persona del p\u00fablico salt\u00f3 al escenario para conectar su celular a lo que pens\u00f3 era un tomacorriente.<\/p>\n","protected":false},"author":12,"featured_media":46084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,10],"tags":[],"class_list":["post-46083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=46083"}],"version-history":[{"count":4,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46083\/revisions"}],"predecessor-version":[{"id":48680,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46083\/revisions\/48680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/46084"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=46083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=46083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=46083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}