{"id":46138,"date":"2015-07-20T12:26:02","date_gmt":"2015-07-20T16:26:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=46138"},"modified":"2015-07-20T12:26:51","modified_gmt":"2015-07-20T16:26:51","slug":"un-ano-de-prision-como-coercion-contra-exempleados-de-fiscalia-por-corrupcion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-ano-de-prision-como-coercion-contra-exempleados-de-fiscalia-por-corrupcion\/","title":{"rendered":"Un a\u00f1o de prisi\u00f3n como coerci\u00f3n contra exempleados de Fiscal\u00eda por corrupci\u00f3n"},"content":{"rendered":"<div id=\"sidebar\"><\/div>\n<div id=\"content\" class=\"single-wrapper\">\n<section>\n<div id=\"single-heading-content\">\n<div class=\"single-right \">\n<div class=\"cat-links-single cat-links-padding-social\">\n<div class=\"toggleable-addthis addthis_toolbox addthis_default_style social-bottom-single\">\n<div class=\"fb-like fb_iframe_widget\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/Palacio-PN-663x441.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-46139 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/Palacio-PN-663x441-300x200.jpg\" alt=\"Palacio-PN-663x441\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/Palacio-PN-663x441-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/Palacio-PN-663x441-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/Palacio-PN-663x441.jpg 663w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Puerto Plata. El Ministerio P\u00fablico, representado por la Procuradur\u00eda Fiscal de Puerto Plata, logr\u00f3 que fueran\u00a0impuestas medidas coercitivas de un a\u00f1o de prisi\u00f3n \u00a0contra dos ex empleados de este organismo, por actos de corrupci\u00f3n cometidos en el ejercicio de sus funciones como servidores p\u00fablicos.<\/div>\n<\/div>\n<\/div>\n<article id=\"post-1243872\" class=\"post-1243872 post type-post status-publish format-standard hentry category-el-pais category-portada\">\n<div class=\"entry-content\">\n<p>Se trata de los exsecretarios de la Fiscal\u00eda de Puerto Plata, Juan Michelle V\u00e1squez y Antonio Guzm\u00e1n Rosario, acusados de asociarse y apropiarse de manera il\u00edcita y beneficiarse de dinero proveniente del pago de garant\u00edas econ\u00f3micas, impuestas a varios imputados.<\/p>\n<p>La Fiscal\u00eda de este Distrito Judicial, que dirige Alba N\u00fa\u00f1ez Pichardo, present\u00f3 los elementos probatorios ante la Oficina de Servicios de Atenci\u00f3n\u00a0 Permanente del Juzgado de la\u00a0 Instrucci\u00f3n que demuestra el desfalco por la suma de 1 mill\u00f3n 463 mil quinientos pesos en dep\u00f3sitos tard\u00edos y un faltante identificado hasta la fecha de trescientos setenta mil pesos, lo cual se estableci\u00f3 constituye violaci\u00f3n a los art\u00edculos 59, 60, 166, 169, 170, 171, 172, 265, 266, 379, 386 y 408 del C\u00f3digo Penal Dominicano, que sancionan los delitos de prevaricaci\u00f3n, desfalco, asociaci\u00f3n de malhechores, abuso de confianza y robo agravado.<\/p>\n<p>En tal sentido, la titular de dicha Fiscal\u00eda expres\u00f3, \u201cel Ministerio P\u00fablico \u00a0no permitir\u00e1 que ning\u00fan miembro involucrado en actuaciones dolosas,\u00a0 que deshonre la Instituci\u00f3n, salga sin la sanci\u00f3n debida.\u00a0Tenemos el compromiso de combatir la corrupci\u00f3n en cualquier manifestaci\u00f3n\u201d.<\/p>\n<p>A la vez exhort\u00f3 \u201cel miembro de la Instituci\u00f3n que no se sienta c\u00f3modo con el sueldo actual que le paga el Estado dominicano,\u00a0 tiene las puertas abiertas para salir y desempe\u00f1ar cualquier otra funci\u00f3n en la vida, puntualiz\u00f3\u00a0N\u00fa\u00f1ez Pichardo.<\/p>\n<p>Con relaci\u00f3n a este mismo caso existe una orden de captura internacional contra la se\u00f1ora Antonia Estrella Cueto, secretaria titular de la Fiscal\u00eda de Puerto Plata.<\/p>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Plata. El Ministerio P\u00fablico, representado por la Procuradur\u00eda Fiscal de Puerto Plata, logr\u00f3 que fueran\u00a0impuestas medidas coercitivas de un a\u00f1o de prisi\u00f3n \u00a0contra dos ex empleados de este organismo, por actos de corrupci\u00f3n cometidos en el ejercicio de sus funciones como servidores p\u00fablicos. Se trata de los exsecretarios de la Fiscal\u00eda de Puerto Plata, Juan Michelle V\u00e1squez y Antonio Guzm\u00e1n Rosario, acusados de asociarse y apropiarse de manera il\u00edcita y beneficiarse de dinero proveniente del pago de garant\u00edas econ\u00f3micas, impuestas a varios imputados. La Fiscal\u00eda de este Distrito Judicial, que dirige Alba N\u00fa\u00f1ez Pichardo, present\u00f3 los elementos probatorios ante la Oficina de Servicios de Atenci\u00f3n\u00a0 Permanente del Juzgado de la\u00a0 Instrucci\u00f3n que demuestra el desfalco por la suma de 1 mill\u00f3n 463 mil quinientos pesos en dep\u00f3sitos tard\u00edos y un faltante identificado hasta la fecha de trescientos setenta mil pesos, lo cual se estableci\u00f3 constituye violaci\u00f3n a los art\u00edculos 59, 60, 166, 169, 170, 171, 172, 265, 266, 379, 386 y 408 del C\u00f3digo Penal Dominicano, que sancionan los delitos de prevaricaci\u00f3n, desfalco, asociaci\u00f3n de malhechores, abuso de confianza y robo agravado. En tal sentido, la titular de dicha Fiscal\u00eda expres\u00f3, \u201cel Ministerio P\u00fablico \u00a0no permitir\u00e1 que ning\u00fan miembro involucrado en actuaciones dolosas,\u00a0 que deshonre la Instituci\u00f3n, salga sin la sanci\u00f3n debida.\u00a0Tenemos el compromiso de combatir la corrupci\u00f3n en cualquier manifestaci\u00f3n\u201d. A la vez exhort\u00f3 \u201cel miembro de la Instituci\u00f3n que no se sienta c\u00f3modo con el sueldo actual que le paga el Estado dominicano,\u00a0 tiene las puertas abiertas para salir y desempe\u00f1ar cualquier otra funci\u00f3n en la vida, puntualiz\u00f3\u00a0N\u00fa\u00f1ez Pichardo. Con relaci\u00f3n a este mismo caso existe una orden de captura internacional contra la se\u00f1ora Antonia Estrella Cueto, secretaria titular de la Fiscal\u00eda de Puerto Plata.<\/p>\n","protected":false},"author":3,"featured_media":46139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-46138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=46138"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46138\/revisions"}],"predecessor-version":[{"id":46141,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46138\/revisions\/46141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/46139"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=46138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=46138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=46138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}