{"id":46219,"date":"2015-07-21T14:55:15","date_gmt":"2015-07-21T18:55:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=46219"},"modified":"2015-07-21T11:59:54","modified_gmt":"2015-07-21T15:59:54","slug":"grupo-de-jovenes-representara-al-pais-en-mundial-de-hip-hop-2015","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/grupo-de-jovenes-representara-al-pais-en-mundial-de-hip-hop-2015\/","title":{"rendered":"Grupo de j\u00f3venes representar\u00e1 al pa\u00eds en \u2018Mundial de hip hop 2015\u2019"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/201507210230171.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-46220 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/201507210230171-300x200.jpg\" alt=\"201507210230171\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/201507210230171-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/201507210230171-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/07\/201507210230171.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Todo inici\u00f3 como una diversi\u00f3n. Hace unos 12 a\u00f1os atr\u00e1s, j\u00f3venes de corta edad\u00a0 y con muy buena amistad decidieron reunirse todas las tardes en la galer\u00eda de una casa en los alrededores de la avenida Venezuela. Con el tiempo el c\u00edrculo comenz\u00f3 a acrecentarse, a tal punto que termin\u00f3 convirti\u00e9ndose en lo que es hoy: Una academia.<!--more--><\/p>\n<p>Esta historia tiene sus protagonistas. Tanto Jonathan Castillo, uno de sus bailarines fundadores, (quien a sus 18 a\u00f1os fue contratado por el Ballet Nacional Dominicano) como su esposa, quien le dio inicio a la escuela N\u00facleo Extremo (en donde los integrantes mueven sus cuerpos con m\u00fasica urbana, al comp\u00e1s de sus pasiones). En la actualidad cuentan con 34 estudiantes que son parte esencial del programa y representan este espacio de manera profesional, tanto as\u00ed, que este a\u00f1o tienen como proyecto, por segunda vez, prepararse para poner en alto a Rep\u00fablica Dominicana en el Mundial de Hip Hop que se realizar\u00e1 en San Diego, California.<\/p>\n<p><strong>El principio<\/strong><br \/>\nEn cuanto a las oportunidades, seg\u00fan gran parte de los bailarines, tras una visita al LIST\u00cdN DIARIO, manifestaron que como todo proyecto que est\u00e1 iniciando, tuvo sus dificultades. Sin embargo, hoy en d\u00eda son contratados por artistas urbanos, algunos como Vaker\u00f3 y Daddy Yankee.<\/p>\n<p>Una de las bailarinas de N\u00facleo Extremo y parte de los 34 j\u00f3venes que ir\u00e1n a San Diego, al Mundial de Hip Hop, coment\u00f3 que al principio, cuando inici\u00f3 todo, la escuela no tuvo el gran apoyo de las empresas, porque ellos entend\u00edan que \u2018un bailar\u00edn era un simple bailar\u00edn\u2019, que solo se encarga de decorar las actividades y no le daban esa importancia que actualmente se les reconoce.<\/p>\n<p><strong>FRASES QUE LOS IDENTIFICAN<\/strong><br \/>\n<strong>Jennifer Vargas<\/strong> \u201cSomos lo que damos y esto nos ayuda llegar a donde queremos\u201d.<\/p>\n<p><strong>Larry Olivero<\/strong> \u201cNunca abandones lo que de verdad te apasiona\u201d.<\/p>\n<p><strong>Larybel Olivero<\/strong> \u201cNunca renuncies a algo en lo que no puedes dejar de pensar\u201d.<\/p>\n<p><strong>Jonathan Castillo <\/strong>\u201cQue nadie te diga que no puedes lograr algo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo inici\u00f3 como una diversi\u00f3n. Hace unos 12 a\u00f1os atr\u00e1s, j\u00f3venes de corta edad\u00a0 y con muy buena amistad decidieron reunirse todas las tardes en la galer\u00eda de una casa en los alrededores de la avenida Venezuela. Con el tiempo el c\u00edrculo comenz\u00f3 a acrecentarse, a tal punto que termin\u00f3 convirti\u00e9ndose en lo que es hoy: Una academia.<\/p>\n","protected":false},"author":3,"featured_media":46220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-46219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=46219"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46219\/revisions"}],"predecessor-version":[{"id":46221,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46219\/revisions\/46221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/46220"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=46219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=46219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=46219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}