{"id":46709,"date":"2015-08-07T09:50:36","date_gmt":"2015-08-07T13:50:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=46709"},"modified":"2015-08-07T09:50:36","modified_gmt":"2015-08-07T13:50:36","slug":"descubre-las-novedades-que-traera-whatsapp-para-iphone","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/descubre-las-novedades-que-traera-whatsapp-para-iphone\/","title":{"rendered":"Descubre las novedades que traer\u00e1 Whatsapp para iPhone"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-46712 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp.jpg\" alt=\"iphone-whatsapp\" width=\"753\" height=\"424\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp.jpg 1280w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp-1024x576.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/iphone-whatsapp-105x59.jpg 105w\" sizes=\"auto, (max-width: 753px) 100vw, 753px\" \/><br \/>\n<\/a>La versi\u00f3n 2.12.5 de WhatApp trae para los usuarios de IOS\u00a0<strong>nuevas opciones<\/strong> entre las que se destacan la posibilidad de marcar como no le\u00eddos los mensaje, as\u00ed como silenciar una conversaci\u00f3n en grupo.<!--more--><\/p>\n<p>Entre las nuevas opciones tambi\u00e9n se\u00a0encuentra la posibilidad de<strong>compartir directamente la ubicaci\u00f3n desde Apple Maps<\/strong> e incluir videos en las copias de seguridad que crea la aplicaci\u00f3n de las conversaciones.<\/p>\n<p>Tambi\u00e9n se encuentra la opci\u00f3n de <strong>silenciar los mensajes de los chats<\/strong>, dentro de las conversaciones grupales sin que el remitente lo note, de la misma manera el usuario de IOS podr\u00e1 limitar el consumo de los datos m\u00f3viles mientras se realizan las llamadas desde la aplicaci\u00f3n.<\/p>\n<p>Ahora, tambi\u00e9n se podr\u00e1<strong> compartir contactos y ubicaciones<\/strong> sin necesidad de estar dentro de la aplicaci\u00f3n sino desde el directorio telef\u00f3nico y Apple Maps mostrar\u00e1 en las conversaciones un peque\u00f1o ma\u00e1 de las ubicaciones.<\/p>\n<p>De igual forma, la aplicaci\u00f3n optimiz\u00f3 la edici\u00f3n de fotos y videos, mientras que <strong>el bot\u00f3n de cargar m\u00e1s mensajes desaparecer\u00e1.<\/strong><\/p>\n<p><a href=\"http:\/\/www.elespectador.com\/tecnologia\/trae-nueva-actualizacion-de-whatsapp-ios-articulo-577698\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La versi\u00f3n 2.12.5 de WhatApp trae para los usuarios de IOS\u00a0nuevas opciones entre las que se destacan la posibilidad de marcar como no le\u00eddos los mensaje, as\u00ed como silenciar una conversaci\u00f3n en grupo.<\/p>\n","protected":false},"author":12,"featured_media":46712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-46709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=46709"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46709\/revisions"}],"predecessor-version":[{"id":46713,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/46709\/revisions\/46713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/46712"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=46709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=46709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=46709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}