{"id":47445,"date":"2015-08-31T10:02:54","date_gmt":"2015-08-31T14:02:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=47445"},"modified":"2015-08-31T10:02:54","modified_gmt":"2015-08-31T14:02:54","slug":"almonte-da-grand-slam-contra-los-angelinos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/almonte-da-grand-slam-contra-los-angelinos\/","title":{"rendered":"Almonte da grand slam contra los Angelinos"},"content":{"rendered":"<p class=\"name post-title entry-title\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/almonte-da-grand-slam-contra-los-angelinos.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47446 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/almonte-da-grand-slam-contra-los-angelinos.jpeg\" alt=\"almonte-da-grand-slam-contra-los-angelinos\" width=\"294\" height=\"222\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/almonte-da-grand-slam-contra-los-angelinos.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/08\/almonte-da-grand-slam-contra-los-angelinos-99x75.jpeg 99w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/a>Abraham Almonte conect\u00f3 el primer grand slam de su carrera y Josh Tomlin lanz\u00f3 hasta el octavo inning para que los Indios de Cleveland.<!--more--><\/p>\n<div class=\"entry\">\n<div id=\"article_zone\">\n<div id=\"ArticleBody\">\n<p>&nbsp;<\/p>\n<p>Derrotasen el domingo 9-2 a los Angelinos de Los Angeles.\u00a0El jonr\u00f3n del dominicano Almonte fue en el quinto inning ante Jered Weaver y permiti\u00f3 a los Indios despegarse rumbo a su quinta victoria seguida.<\/p>\n<p>Weaver (6-10) no cont\u00f3 con mucha ayuda de su defensa. Tanto el jardinero central Mike Trout como el derecho Kole Calhoun perdieron f\u00e1ciles elevados en el sol, derivando en cinco carreras de los Indios.<\/p>\n<p>Carlos Santana produjo tres carreras por los Indios, que comenzaron la jornada situados a cinco juegos de Texas por el segundo wildcard de la Liga Americana.<\/p>\n<p>Por los Angelinos, los dominicanos Albert Pujols y Erick Aybar de 4-0. El venezolano Carlos P\u00e9rez de 4-0.<\/p>\n<p>Por los Indios, el puertorrique\u00f1o Francisco Lindor de 3-1, una anotada y remolcada. Los dominicanos Almonte de 4-2, una anotada y cuatro remolcadas; y Carlos Santana de 4-3, una anotada y tres remolcadas. El colombiano Giovanny Urshela de 4-0. El puertorrique\u00f1o Roberto P\u00e9rez de 2-0.<\/p>\n<p><strong>Azulejos \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 9<br \/>\nDetroit \u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a02<\/strong><br \/>\n<strong>(AP) Toronto<\/strong><br \/>\nEl pelotero dominicano de los Azulejos de Toronto Edwin Encarnaci\u00f3n descarg\u00f3 su cuarto jonr\u00f3n en dos d\u00edas, Josh Donaldson tambi\u00e9n la desapareci\u00f3 y los Azulejos de Toronto vencieron 9-2 a unos Tigres de Detroit sumidos en una mala racha el domingo para completar la barrida en la serie de tres juegos.<\/p>\n<p>Russell Martin y Kevin Pillar tambi\u00e9n conectaron vuelacercas productores de dos carreras para Toronto, que es l\u00edder en Grandes Ligas con 184. Los l\u00edderes del Este de la Americana lograron su segundo partido en fila con cuatro jonrones, y el sexto de la campa\u00f1a.<\/p>\n<p>MPor los Azulejos, los dominicanos Edwin Encarnaci\u00f3n de 3-2 con una carrera anotada y una producida, Jos\u00e9 Bautista de 5-1.<\/p>\n<p><strong>Mellizos \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a07<br \/>\nHouston \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 5<\/strong><br \/>\n<strong>(AP) Minnesota<\/strong><br \/>\nEl dominicano Ervin Santana recet\u00f3 10 ponches para conseguir su primera victoria como local, mientras que sus compatriotas Eduardo N\u00fa\u00f1ez y Miguel San\u00f3 contribuyeron con sendos cuadrangulares en el duelo que los Mellizos de Minnesota ganaron el domingo 7-5 a los Astros de Houston.<\/p>\n<p>Los Mellizos se llevaron un susto en el noveno inning antes de salir airosos. Houston estaba abajo por 7-0, pero Chris Carter dispar\u00f3 un jonr\u00f3n de tres carreras y el venezolano Jos\u00e9 Altuve a\u00f1adi\u00f3 un garrotazo de dos vueltas que coloc\u00f3 la pizarra en 7-5.<\/p>\n<p>Por los Astros, los venezolanos Altuve de 5-4 con una anotada y dos empujadas, Gonz\u00e1lez de 5-3, Luis Valbuena de 3-0 con una anotada. El dominicano Carlos G\u00f3mez de 4-2.<\/p>\n<p>Por los Mellizos, el venezolano Escobar de 3-1 con una anotada y una producida. Los dominicanos San\u00f3 de 2-1 con dos anotadas y dos impulsadas, N\u00fa\u00f1ez de 4-1 con una anotada y dos empujadas. El puertorrique\u00f1o Eddie Rosario de 3-1 con una remolcada.<\/p>\n<p><strong>Tampa \u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a03<br \/>\nKansas \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a02<\/strong><br \/>\n<strong>(AP) Florida<\/strong><br \/>\nBrandon Guyer y Kevin Kiermaier conectaron sendos jonrones y el bullpen de los Rays limit\u00f3 a Kansas City a un solo hit en cinco innings para que Tampa Bay derrotara el domingo 3-2 a los Reales.<\/p>\n<p>El vuelacerca de Kiermaier en la sexta entrada frente a Luke Hochevar (1-1) quebr\u00f3 el empate 2-2. Fue el segundo bambinazo de Kiermaier en dos encuentros y su sexto de la temporada.<\/p>\n<p><strong>Medias Blancas \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a06<br \/>\nMarineros \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a05<\/strong><br \/>\n<strong>(AP) Chicago<\/strong><br \/>\nEl novato Tyler Saladino produjo la carrera de la diferencia mediante un sencillo en la und\u00e9cima entrada, y los Medias Blancas de Chicago remontaron para superar el domingo 6-5 a los Marineros de Seattle.<\/p>\n<p>Por los Marineros, los dominicanos Nelson Cruz de 4-1, Robinson Can\u00f3 de 4-2. El venezolano Franklin Guti\u00e9rrez de 5-0. Por los Medias Blancas, los cubanos Jos\u00e9 Abreu de 6-0 con una empujada, Ram\u00edrez de 5-3 con dos anotadas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Abraham Almonte conect\u00f3 el primer grand slam de su carrera y Josh Tomlin lanz\u00f3 hasta el octavo inning para que los Indios de Cleveland.<\/p>\n","protected":false},"author":12,"featured_media":47446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-47445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=47445"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47445\/revisions"}],"predecessor-version":[{"id":47447,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47445\/revisions\/47447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/47446"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=47445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=47445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=47445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}