{"id":47499,"date":"2015-09-01T12:12:01","date_gmt":"2015-09-01T16:12:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=47499"},"modified":"2015-09-01T12:12:01","modified_gmt":"2015-09-01T16:12:01","slug":"desconocidos-uniformados-matan-ganadero-a-balazos-en-el-cupey","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/desconocidos-uniformados-matan-ganadero-a-balazos-en-el-cupey\/","title":{"rendered":"Desconocidos uniformados matan ganadero a balazos en El Cupey"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Muerto-Cupey2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47500 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Muerto-Cupey2-300x169.jpg\" alt=\"Muerto-Cupey2\" width=\"300\" height=\"169\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Muerto-Cupey2-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Muerto-Cupey2-105x59.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Muerto-Cupey2.jpg 576w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>PUERTO PLATA.-<\/strong>Cuatro individuos uniformados mataron de cuatro balazos la ma\u00f1ana de este marte a un ganadero\u00a0en la carretera Gran Parada, el Cupey tramo la Vig\u00eda.<\/p>\n<p>La v\u00edctima fue identificada como el ganadero Rub\u00e9n Almonte (El Rubio de Juano), de 50 a\u00f1os de edad, el cual resid\u00eda en la comunidad de las Tres Canas, el Cupey.<\/p>\n<p>Testigos osculares se\u00f1alan que la v\u00edctima se desplazaba en su camioneta cuando fue interceptado por cuatro personas con uniformes militares, los cuales le abrieron fuego y luego se llevaron una pistola y dinero producto del cobro de la leche.<br \/>\nEl ganadero Rub\u00e9n Almonte era el esposo de la abogada Juana Spencer, asistente del procurador general de Medio Ambiente, departamento Puerto Plata, doctor Domingo Antonio Belliard.<\/p>\n<div class=\"yarpp-related\">\n<h3><\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.-Cuatro individuos uniformados mataron de cuatro balazos la ma\u00f1ana de este marte a un ganadero\u00a0en la carretera Gran Parada, el Cupey tramo la Vig\u00eda. La v\u00edctima fue identificada como el ganadero Rub\u00e9n Almonte (El Rubio de Juano), de 50 a\u00f1os de edad, el cual resid\u00eda en la comunidad de las Tres Canas, el Cupey. Testigos osculares se\u00f1alan que la v\u00edctima se desplazaba en su camioneta cuando fue interceptado por cuatro personas con uniformes militares, los cuales le abrieron fuego y luego se llevaron una pistola y dinero producto del cobro de la leche. El ganadero Rub\u00e9n Almonte era el esposo de la abogada Juana Spencer, asistente del procurador general de Medio Ambiente, departamento Puerto Plata, doctor Domingo Antonio Belliard.<\/p>\n","protected":false},"author":3,"featured_media":47500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-47499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=47499"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47499\/revisions"}],"predecessor-version":[{"id":47501,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47499\/revisions\/47501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/47500"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=47499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=47499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=47499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}