{"id":47762,"date":"2015-09-07T12:13:16","date_gmt":"2015-09-07T16:13:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=47762"},"modified":"2015-09-07T12:13:16","modified_gmt":"2015-09-07T16:13:16","slug":"eduardos-del-batey-y-sosua-sharks-triunfan-en-el-basket-superior-de-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eduardos-del-batey-y-sosua-sharks-triunfan-en-el-basket-superior-de-puerto-plata\/","title":{"rendered":"Eduardos del Batey y Sos\u00faa Sharks triunfan en el Basket Superior de Puerto Plata"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/basket-superior-pop.jpg\"><br \/>\n<\/a>Puerto Plata.- Los Eduardos del Batey y Sos\u00faa Sharks consiguieron sendas victorias en la continuaciones de la serie regular del XXII Torneo de Baloncesto Superior de Puerto Plata, organizado por la ABAPPLATA.<!--more--><\/p>\n<p>El evento cuenta con el Aval y el respaldo de la Federaci\u00f3n Dominicana de Baloncesto (FEDOMBAL) y se juega la Copa BRUGAL.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-47763 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/basket-superior-pop.jpg\" alt=\"basket superior pop\" width=\"455\" height=\"365\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/basket-superior-pop.jpg 900w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/basket-superior-pop-300x241.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/basket-superior-pop-93x75.jpg 93w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><\/p>\n<h3>Eduardos del Batey ligaron importante triunfo.<\/h3>\n<p>Jean Carlos Severino y Yohansi Minaya se combinaron para encestar 56 puntos en la victoria de los Eduados del Batey sobre los Mellizos con marcador de 96 por 78, saliendo de la racha negativa.<\/p>\n<p>La primera mitad finalizo 45 por 32 a favor de los ganadores. Los mejores en la primera mitad por los Eduardos, Jean Carlos Severino 12 puntos y Yohansi Minaya 7.<\/p>\n<p>Por los Mellizos, Miguel Ortiz 11 y Luis Miguel Almonte 9.<\/p>\n<p>En la segunda mitad del partido los Mellizos del Sur entraron a cancha con otra mentalidad que fue defender y bajar la ventaja con buenas ofensivas, lograron irse delante en el marcador por varias ocasiones, pero los Eduardos volvieron al ritmo ofensivo con Jean Carlos Severino y Yohansi Minaya y la defensa sobre el refuerzo de los Mellizos, Adonis N\u00fa\u00f1ez el cual fue frenado.<\/p>\n<p>Jean Carlos Severino fue el mejor por los Eduardos del Batey con 32 puntos, incluyendo 6 disparos de 3 y 7 rebotes, Yohansi Minaya 24 unidades y reparti\u00f3 9 asistencias, Jhon Garc\u00eda 13 puntos y 14 rebotes y el novato Skarling V\u00e1squez 10.<\/p>\n<p>En la causa perdida, Adolfo Williams 20 puntos y 6 rebotes, Miguel Ortiz 14, Luis Miguel Almonte 12, Javier Bonilla 11 encestes con 13 rebotes y Gabriel Balbuena 8 tantos y 10 capturas.<\/p>\n<p>Los Eduardos del Batey consiguieron su segunda victoria del torneo con 4 derrotas, los Mellizos del Sur se mantienen en el segundo lugar del torneo con 4 victorias y 2 derrotas.<\/p>\n<p>Enllery Batista gu\u00eda a los Sos\u00faa Sharks a su quinta victoria.<\/p>\n<p>El combinado de los Sos\u00faa Sharks consiguieron su quinta victoria del torneo, al vencer 82 por 75 a los Correcaminos de la Parte Baja, en el cierre de la doble jornada.<\/p>\n<p>El primer cuarto fue ganador por los Correcaminos 24-22 y el segundo los Sos\u00faa Sharks 18-14. La primera mitad termin\u00f3 40-38 a favor de Sos\u00faa.<\/p>\n<p>Enllery Batista lider\u00f3 a cinco compa\u00f1eros en cifras dobles en puntos con 24, 8 rebotes y 2 balones robadas, Jaison Valdez 16 unidades y 7 rebotes, Sa\u00fal Mart\u00ednez 12 y 6 rebotes, Dilky Thomas 12 encestes y 5 rebotes y Edson Taveras 11 con 7 capturas.<\/p>\n<p>En el rev\u00e9s, Lavel Payne 19 puntos y 11 rebotes, Johan Torres 16, Jos\u00e9 Acosta 11 tantos y 6 asistencias y Rolando Suero lig\u00f3 9, 5 rebotes y 5 balones robados.<\/p>\n<p>El tercer cuarto qued\u00f3 empatado a 18 y el \u00faltimo cuarto fue ganador por los Sos\u00faa Sharks 24-19.<\/p>\n<p>El torneo cuenta con el auspicio de, Brugal &amp; Co., Compraventa Antonio, La Uni\u00f3n Shipping, Gobernaci\u00f3n Provincial, La Sirena y S\u00faper Pola, Tienda Jim\u00e9nez, Farmacia Popular, Ayuntamiento de Sos\u00faa, Coca Cola, Diputado F\u00e9lix Castillo, Farmacia Cristal, Ferreter\u00eda Internacional Freddy, Plaza G\u00e1lvez, Hielo y Agua Internacional, Precandidata a Regidora Yajaira Santana, Ministerio de la Presidencia.<\/p>\n<p>Las acciones contin\u00faan el pr\u00f3ximo mi\u00e9rcoles partir de las 7 de la noche, donde a primera hora se enfrentar\u00e1n los conjuntos de las Cotorras del Gustavo (0-4) y Eduardos del Batey (2-4), mientras que en el cierre lo har\u00e1n los Correcaminos de la Parte Baja (2-2) y los Mellizos del Sur (4-2) en el Techado Fabio Rafael Gonz\u00e1lez.<\/p>\n<p>Las posiciones del torneo son las siguientes: Sos\u00faa Sharks 5-0, Mellizos del Sur 4-2, Correcaminos de la Parte Baja 2-2, Eduardos del Batey 2-4 y Cotorras del Gustavo 0-4.<\/p>\n<p>La trasmisi\u00f3n de los encuentros es por la Estaci\u00f3n Radial Fantas\u00eda 90.5 FM, bajo la conducci\u00f3n de los Cronistas Deportivos, Winston Cid y Pedro L\u00f3pez, en la Internet www.fantasiafm.com.do<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Plata.- Los Eduardos del Batey y Sos\u00faa Sharks consiguieron sendas victorias en la continuaciones de la serie regular del XXII Torneo de Baloncesto Superior de Puerto Plata, organizado por la ABAPPLATA.<\/p>\n","protected":false},"author":12,"featured_media":47763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-47762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=47762"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47762\/revisions"}],"predecessor-version":[{"id":47764,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47762\/revisions\/47764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/47763"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=47762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=47762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=47762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}