{"id":47773,"date":"2015-09-07T15:13:10","date_gmt":"2015-09-07T19:13:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=47773"},"modified":"2015-09-07T15:13:10","modified_gmt":"2015-09-07T19:13:10","slug":"ay-que-muchachos-mas-amenos-fnp-dice-rd-no-existe-un-estado-de-bienestar-ahora","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ay-que-muchachos-mas-amenos-fnp-dice-rd-no-existe-un-estado-de-bienestar-ahora\/","title":{"rendered":"\u00a1Ay que muchachos m\u00e1s amenos! FNP dice RD no existe un estado de bienestar \u00bfAhora?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/los-vinchos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47778 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/los-vinchos.jpg\" alt=\"los vinchos\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/los-vinchos.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/los-vinchos-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/los-vinchos-105x56.jpg 105w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a><br \/>\nSANTO DOMINGO. La Fuerza Nacional Progresista (FNP) calific\u00f3 de irreal el estado de bienestar general el presidente Danilo Medina en sus declaraciones, en las cuales afirma ha disminuido la pobreza y aumentado el n\u00famero de ciudadanos que ingresan a la clase media, debido a que cree que por el contrario, se han agravado los problemas sociales que general iniquidad, empezando por el salario real de los trabajadores dominicanos que es el equivalente al de 1992.<!--more--><\/p>\n<p>A trav\u00e9s de una nota de prensa, la FNP cuestion\u00f3 los sueldos de miseria para la mayor\u00eda de empleados del sector privado y el sector p\u00fablico, incluyendo la Polic\u00eda Nacional, el Ministerio de Defensa y el Ministerio P\u00fablico; adem\u00e1s, de la inseguridad \u201calarmante\u201d que mantiene enrejada la poblaci\u00f3n y lo que se\u00f1ala como la masiva invasi\u00f3n haitiana que \u201cdesnacionaliza\u201d los mercados laborales.<\/p>\n<p>Adem\u00e1s, critica el deficiente sistema de salud donde pacientes haitianos est\u00e1n desplazando a los dominicanos; que el sistema educativo, seg\u00fan estudios internacionales, se sit\u00fae dentro de los \u00faltimos lugares y el pago de los combustibles y la tarifa el\u00e9ctrica elevadas por supuestos sobre costos ocultos, transferencia de rentas y m\u00e1rgenes de intermediaci\u00f3n abusivos e impuestos excesivos.<\/p>\n<p>\u201cEs evidente que el Presidente Danilo Medina est\u00e1 percibiendo otro pa\u00eds que no es en el que viven los dominicanos\u201d, afirman en el documento remitido a los medios de comunicaci\u00f3n.<\/p>\n<p>Concluye que \u201cel partido azul que impulsa el Polo Soberano para las elecciones pr\u00f3ximas, expresa que el panorama es diametralmente distinto al descrito por el Presidente Medina. La clase media ha sido golpeada y, lejos de fortalecerse, tiene un peligroso proceso de empobrecimiento debido a cargas econ\u00f3micas en servicios b\u00e1sicos que el Estado debiera estarle brindando y que tiene que costear con sus magros recursos\u201d.<\/p>\n<p>PD: \u00bfPor qu\u00e9 lo notan hasta ahora? \u00a1Ay que muchachos m\u00e1s amenos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. La Fuerza Nacional Progresista (FNP) calific\u00f3 de irreal el estado de bienestar general el presidente Danilo Medina en sus declaraciones, en las cuales afirma ha disminuido la pobreza y aumentado el n\u00famero de ciudadanos que ingresan a la clase media, debido a que cree que por el contrario, se han agravado los problemas sociales que general iniquidad, empezando por el salario real de los trabajadores dominicanos que es el equivalente al de 1992.<\/p>\n","protected":false},"author":12,"featured_media":47778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-47773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=47773"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47773\/revisions"}],"predecessor-version":[{"id":47779,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/47773\/revisions\/47779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/47778"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=47773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=47773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=47773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}