{"id":48203,"date":"2015-09-27T08:00:45","date_gmt":"2015-09-27T12:00:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=48203"},"modified":"2015-09-15T23:51:06","modified_gmt":"2015-09-16T03:51:06","slug":"diadelabiblia-para-que-nos-sirve-la-biblia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/diadelabiblia-para-que-nos-sirve-la-biblia\/","title":{"rendered":"#D\u00edaDeLaBiblia: \u00bfPara qu\u00e9 nos sirve la Biblia?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-48204 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n.png\" alt=\"Picture1n\" width=\"2018\" height=\"1123\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n.png 2018w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n-300x167.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n-1024x570.png 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/Picture1n-105x58.png 105w\" sizes=\"auto, (max-width: 2018px) 100vw, 2018px\" \/><\/a><\/p>\n<p>Cada 27 de septiembre los cristianos de todo el mundo celebramos el D\u00eda Internacional de la Biblia, en honor al libro m\u00e1s importante de todos los tiempos. Considerada la base doctrinal de las religiones cristianas, la Biblia es el libro inspirado por Dios, (2 Timoteo 3:16).<\/p>\n<p>Sin dudas, la biblia es la fuente inagotable de la palabra divina, no se trata de un texto est\u00e1tico sino por el contrario de una palabra viva, poderosa y transformadora apra aquellos que se sumergen en sus p\u00e1ginas. El vers\u00edculo antes citado en 2 Timoteo 3:16 dice lo siguiente: <strong>Toda Escritura es inspirada\u00a0por\u00a0Dios y\u00a0\u00fatil para ense\u00f1ar, para reprender, para corregir, para instruir en justicia. <\/strong><\/p>\n<p>Analicemos esta porci\u00f3n y que ella misma nos ayude a traer luz sobre nuestro entendimiento de cu\u00e1n importante son las Sagradas Escrituras.<\/p>\n<p><strong>\u00bfQui\u00e9n es el autor de la Biblia? <\/strong><\/p>\n<p>Lo primero y lo m\u00e1s importante a lo que Pedro (el autor de la carta a Timoteo) dice en este verso es que la escritura \u201cha sido inspirada por Dios\u201d. Todo lo que se halla contenido dentro de los 66 libros que componen la Biblia ha sido escrito por mano humana bajo la direcci\u00f3n de Dios mismo. As\u00ed como, Jehov\u00e1 imparti\u00f3 a Mois\u00e9s los 10 mandamientos en el monte Sina\u00ed, el habl\u00f3 en m\u00faltiples maneras e inspir\u00f3 su palabra a quienes escribieron la Biblia. Por lo tanto Dios es el autor supremo de la Biblia.<\/p>\n<p><strong>\u00bfQu\u00e9 prop\u00f3sito tiene la Biblia?<\/strong><\/p>\n<p>La palabra de Dios no ha sido escrita, compilada e impresa solo para adornar un rinc\u00f3n de un hogar cristiano, tiene unos prop\u00f3sitos muy claros y definidos. El verso dice \u201c\u2026\u00fatil para ense\u00f1ar\u2026\u201d, y efectivamente la Biblia es una fuente de ense\u00f1anza para la vida espiritual y natural. La palabra de Dios es una excelente guianza moral \u00a0para la familia, para la formaci\u00f3n de valores y es adem\u00e1s un amplio compendio de historia pol\u00edtica, social y cultural de los pueblos que sirven de escenario a todo lo que se expone a lo largo del Antiguo y Nuevo Testamento.<\/p>\n<p>Pero lo m\u00e1s importante que podemos aprender en la Biblia, es conocer a Dios a trav\u00e9s de su palabra, su plan y prop\u00f3sito con la humanidad, el pecado y sus consecuencias, la promesa de salvaci\u00f3n a trav\u00e9s de Jes\u00fas, su sacrificio en la cruz y su gloriosa venida para llevarse consigo su iglesia.<\/p>\n<p>\u201c\u2026\u00fatil para reprender, para corregir\u2026\u201d en el desglose de este vers\u00edculo vemos que la Biblia tambi\u00e9n reprende,\u2026\u201cporque Jehov\u00e1 al que ama castiga\u2026\u201d (Proverbios 3:12) y en su amor Dios nos corrige a trav\u00e9s de su Palabra y nos permite aprender qu\u00e9 es lo correcto ante cada circunstancia. As\u00ed como castig\u00f3 a Jon\u00e1s por su desobediencia y este recapacit\u00f3 dentro del vientre del pez, as\u00ed mismo la palabra nos confronta en nuestro error y nos ayuda a encontrar luz.<\/p>\n<p>Pero la Biblia tambi\u00e9n es \u201c\u2026 para instruir en justicia.\u201d Y si nos fijamos todo lo que hace Dios es en justicia, como es su naturaleza y todo cu\u00e1nto para lo que es \u00fatil la biblia es para bien del hombre, por ello en justicia Dios nos instruye en la vida espiritual y natural a trav\u00e9s de su palabra.<\/p>\n<p><strong>\u00bfC\u00f3mo lleg\u00f3 la Biblia a nuestras manos? <\/strong><\/p>\n<p>1500 a\u00f1os transcurrieron en el proceso de escritura de la Biblia y se cree que 40 hombres intervinieron en ella. Toda la sabidur\u00eda divina que hay contenida en la Biblia nos llega desde tiempos inmemoriales como los del G\u00e9nesis o de otros m\u00e1s recientes de cuando Jes\u00fas estuvo en la tierra o cuando Pablo hizo sus viajes misioneros. Sin embargo, la Palabra de Dios est\u00e1 m\u00e1s actualizada que el peri\u00f3dico que saldr\u00e1 ma\u00f1ana y hay en ella instrucci\u00f3n certera para lo que vivimos hoy, en momentos tan distantes de los que la Biblia nos muestra.<\/p>\n<p>La versi\u00f3n m\u00e1s popular de la Biblia, la Reina \u2013 Valera de 1960, es la contribuci\u00f3n conjunta de traducci\u00f3n y adaptaci\u00f3n hecha por Casiodoro de Reina y Cipriano Valera. Gracias a esa edici\u00f3n, la Biblia se hizo m\u00e1s asequible para los cristianos de habla hispana. Cabe destacar que hasta principios del siglo pasado, la Biblia era exclusiva de sacerdotes y l\u00edderes religiosos porque se hallaba mayormente en lat\u00edn y exist\u00eda la arraigada cultura de que quien le\u00eda la biblia se volv\u00eda loco.<\/p>\n<p>Gracias a Dios las generaciones actuales podemos acceder a la Biblia de tantas maneras posibles y beneficiarnos de todo lo que es expuesto en 2 Timoteo 3: 16.\u00a0 Y por aquellos que aun son v\u00edctimas del acecho como los primeros cristianos, <em>Bienaventurados los que padecen persecuci\u00f3n por causa de la justicia: porque de ellos es el reino de los cielos<\/em> (Mateo 5:10) y es con ellos nuestra oraci\u00f3n por perseverancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada 27 de septiembre los cristianos de todo el mundo celebramos el D\u00eda Internacional de la Biblia, en honor al libro m\u00e1s importante de todos los tiempos. Considerada la base doctrinal de las religiones cristianas, la Biblia es el libro inspirado por Dios, (2 Timoteo 3:16). Sin dudas, la biblia es la fuente inagotable de la palabra divina, no se trata de un texto est\u00e1tico sino por el contrario de una palabra viva, poderosa y transformadora apra aquellos que se sumergen en sus p\u00e1ginas. El vers\u00edculo antes citado en 2 Timoteo 3:16 dice lo siguiente: Toda Escritura es inspirada\u00a0por\u00a0Dios y\u00a0\u00fatil para ense\u00f1ar, para reprender, para corregir, para instruir en justicia. Analicemos esta porci\u00f3n y que ella misma nos ayude a traer luz sobre nuestro entendimiento de cu\u00e1n importante son las Sagradas Escrituras. \u00bfQui\u00e9n es el autor de la Biblia? Lo primero y lo m\u00e1s importante a lo que Pedro (el autor de la carta a Timoteo) dice en este verso es que la escritura \u201cha sido inspirada por Dios\u201d. Todo lo que se halla contenido dentro de los 66 libros que componen la Biblia ha sido escrito por mano humana bajo la direcci\u00f3n de Dios mismo. As\u00ed como, Jehov\u00e1 imparti\u00f3 a Mois\u00e9s los 10 mandamientos en el monte Sina\u00ed, el habl\u00f3 en m\u00faltiples maneras e inspir\u00f3 su palabra a quienes escribieron la Biblia. Por lo tanto Dios es el autor supremo de la Biblia. \u00bfQu\u00e9 prop\u00f3sito tiene la Biblia? La palabra de Dios no ha sido escrita, compilada e impresa solo para adornar un rinc\u00f3n de un hogar cristiano, tiene unos prop\u00f3sitos muy claros y definidos. El verso dice \u201c\u2026\u00fatil para ense\u00f1ar\u2026\u201d, y efectivamente la Biblia es una fuente de ense\u00f1anza para la vida espiritual y natural. La palabra de Dios es una excelente guianza moral \u00a0para la familia, para la formaci\u00f3n de valores y es adem\u00e1s un amplio compendio de historia pol\u00edtica, social y cultural de los pueblos que sirven de escenario a todo lo que se expone a lo largo del Antiguo y Nuevo Testamento. Pero lo m\u00e1s importante que podemos aprender en la Biblia, es conocer a Dios a trav\u00e9s de su palabra, su plan y prop\u00f3sito con la humanidad, el pecado y sus consecuencias, la promesa de salvaci\u00f3n a trav\u00e9s de Jes\u00fas, su sacrificio en la cruz y su gloriosa venida para llevarse consigo su iglesia. \u201c\u2026\u00fatil para reprender, para corregir\u2026\u201d en el desglose de este vers\u00edculo vemos que la Biblia tambi\u00e9n reprende,\u2026\u201cporque Jehov\u00e1 al que ama castiga\u2026\u201d (Proverbios 3:12) y en su amor Dios nos corrige a trav\u00e9s de su Palabra y nos permite aprender qu\u00e9 es lo correcto ante cada circunstancia. As\u00ed como castig\u00f3 a Jon\u00e1s por su desobediencia y este recapacit\u00f3 dentro del vientre del pez, as\u00ed mismo la palabra nos confronta en nuestro error y nos ayuda a encontrar luz. Pero la Biblia tambi\u00e9n es \u201c\u2026 para instruir en justicia.\u201d Y si nos fijamos todo lo que hace Dios es en justicia, como es su naturaleza y todo cu\u00e1nto para lo que es \u00fatil la biblia es para bien del hombre, por ello en justicia Dios nos instruye en la vida espiritual y natural a trav\u00e9s de su palabra. \u00bfC\u00f3mo lleg\u00f3 la Biblia a nuestras manos? 1500 a\u00f1os transcurrieron en el proceso de escritura de la Biblia y se cree que 40 hombres intervinieron en ella. Toda la sabidur\u00eda divina que hay contenida en la Biblia nos llega desde tiempos inmemoriales como los del G\u00e9nesis o de otros m\u00e1s recientes de cuando Jes\u00fas estuvo en la tierra o cuando Pablo hizo sus viajes misioneros. Sin embargo, la Palabra de Dios est\u00e1 m\u00e1s actualizada que el peri\u00f3dico que saldr\u00e1 ma\u00f1ana y hay en ella instrucci\u00f3n certera para lo que vivimos hoy, en momentos tan distantes de los que la Biblia nos muestra. La versi\u00f3n m\u00e1s popular de la Biblia, la Reina \u2013 Valera de 1960, es la contribuci\u00f3n conjunta de traducci\u00f3n y adaptaci\u00f3n hecha por Casiodoro de Reina y Cipriano Valera. Gracias a esa edici\u00f3n, la Biblia se hizo m\u00e1s asequible para los cristianos de habla hispana. Cabe destacar que hasta principios del siglo pasado, la Biblia era exclusiva de sacerdotes y l\u00edderes religiosos porque se hallaba mayormente en lat\u00edn y exist\u00eda la arraigada cultura de que quien le\u00eda la biblia se volv\u00eda loco. Gracias a Dios las generaciones actuales podemos acceder a la Biblia de tantas maneras posibles y beneficiarnos de todo lo que es expuesto en 2 Timoteo 3: 16.\u00a0 Y por aquellos que aun son v\u00edctimas del acecho como los primeros cristianos, Bienaventurados los que padecen persecuci\u00f3n por causa de la justicia: porque de ellos es el reino de los cielos (Mateo 5:10) y es con ellos nuestra oraci\u00f3n por perseverancia.<\/p>\n","protected":false},"author":3,"featured_media":48204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,311],"tags":[],"class_list":["post-48203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=48203"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48203\/revisions"}],"predecessor-version":[{"id":48263,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48203\/revisions\/48263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/48204"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=48203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=48203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=48203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}