{"id":48249,"date":"2015-09-16T12:10:28","date_gmt":"2015-09-16T16:10:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=48249"},"modified":"2015-09-16T12:10:28","modified_gmt":"2015-09-16T16:10:28","slug":"starling-marte-decide-victoria-de-los-piratas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/starling-marte-decide-victoria-de-los-piratas\/","title":{"rendered":"Starling Marte decide victoria de los Piratas"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/image_content_5533653_20150915192349.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-48250 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/image_content_5533653_20150915192349.jpg\" alt=\"image_content_5533653_20150915192349\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/image_content_5533653_20150915192349.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/image_content_5533653_20150915192349-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/image_content_5533653_20150915192349-105x56.jpg 105w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a><br \/>\nPITTSBURGH, Pennsylvania, EE.UU. El dominicano Pedro Florim\u00f3n anot\u00f3 en un elevado de sacrificio de su compatriota Starling Marte en la octava entrada para que los Piratas de Pittsburgh vencieran 5-4 a los Cachorros de Chicago el martes en el primer partido de una doble jornada.<!--more--><\/p>\n<p>Florim\u00f3n ingres\u00f3 como corredor emergente en lugar de Pedro \u00c1lvarez quien recibi\u00f3 pasaporte de Justin Grimm (3-5). Florim\u00f3n se rob\u00f3 la segunda y pas\u00f3 a la antesala por un mal tiro del receptor Miguel Montero que se fue al jard\u00edn central.<\/p>\n<p>Marte, quien jugaba por primera vez despu\u00e9s de lastimarse el hombro el jueves, conect\u00f3 una l\u00ednea al jard\u00edn izquierdo y Florim\u00f3n venci\u00f3 sin problemas el tiro de Austin Jackson, lo que permiti\u00f3 a los Piratas acercarse a dos partidos de San Luis en la lucha por el liderato de la divisi\u00f3n Central de la Liga Nacional y tom\u00f3 una ventaja de cinco partidos sobre los Cachorros en la carrera por un puesto de comod\u00edn.<\/p>\n<p>Tony Watson (4-1) lanz\u00f3 la octava entrada sin permitir carrera. Mark Melancon tuvo una novena perfecta para su 46mo salvamento en Grandes Ligas, con lo que empata la marca que fij\u00f3 Mike Williams en el club en 2002.<\/p>\n<p>Por los Piratas, los dominicanos Gregory Polanco de 3-0 con una anotada, Pedro \u00c1lvarez de 2-0, Starling Marte produjo una carrera.<\/p>\n<p>Por los Cachorros, el venezolano Miguel Montero bate\u00f3 de 4-2 con una anotada; el dominicano Starlin Castro de 4-1 con una anotada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PITTSBURGH, Pennsylvania, EE.UU. El dominicano Pedro Florim\u00f3n anot\u00f3 en un elevado de sacrificio de su compatriota Starling Marte en la octava entrada para que los Piratas de Pittsburgh vencieran 5-4 a los Cachorros de Chicago el martes en el primer partido de una doble jornada.<\/p>\n","protected":false},"author":12,"featured_media":48250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-48249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=48249"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48249\/revisions"}],"predecessor-version":[{"id":48251,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/48249\/revisions\/48251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/48250"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=48249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=48249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=48249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}