{"id":4886,"date":"2014-06-24T15:25:32","date_gmt":"2014-06-24T19:25:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=4886"},"modified":"2014-06-24T15:25:32","modified_gmt":"2014-06-24T19:25:32","slug":"microsoft-anuncia-su-primer-smartphone-con-sistema-android","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/microsoft-anuncia-su-primer-smartphone-con-sistema-android\/","title":{"rendered":"Microsoft anuncia su primer smartphone con sistema Android"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/06\/Nokia-X2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4887\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/06\/Nokia-X2.jpg\" alt=\"Nokia-X2\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/06\/Nokia-X2.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/06\/Nokia-X2-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>Microsoft\u00a0ha anunciado este martes el nuevo\u00a0smartphone\u00a0Nokia X2, un Android que costar\u00e1 99 euros (135\u00a0d\u00f3lares). Se trata del sucesor del Nokia X, pero tiene la peculiaridad de que es el primer tel\u00e9fono Android fabricado por Microsoft, que adquiri\u00f3 Nokia el pasado mes de abril.<!--more--><\/p>\n<p>De momento, Microsoft a\u00fan no ha eliminado\u00a0Nokia\u00a0del nombre del dispositivo,\u00a0ni\u00a0lo ha sustituido todav\u00eda por Microsoft Mobile\u00a0y el Nokia X2 destaca adem\u00e1s de por su\u00a0Dual SIM,\u00a0por incluir aplicaciones de la tienda\u00a0Nokia y de Google Play.<\/p>\n<p>En cuanto a las caracter\u00edsticas t\u00e9cnicas del Nokia X2, tiene una pantallaClearblack LCD\u00a0IPS de 4,3 pulgadas con resoluci\u00f3n de\u00a0480 por 800 p\u00edxeles,unas dimensiones de 121,7 por 68,3 por 11,1 mil\u00edmetros, y pesa 150 gramos. Utiliza el procesador Qualcomm\u00a0Snapdragon 200 de doble n\u00facleo a 1,2 GHz, una GPU Adreno 305, y dispone de 1GB de RAM y 4GB almacenamiento interno ampliables mediante microSD hasta 32GB.<\/p>\n<p>La c\u00e1mara trasera del tel\u00e9fono es de 5 MP con flash LED, su bater\u00eda es de 1.800 mAh y cuenta con WiFi, 3G, GPS y Bluetooth. El sistema operativo que utiliza es una versi\u00f3n de Android de Nokia.<\/p>\n<p>Asimismo, est\u00e1n disponibles los servicios de Microsoft como Skype -que incluye un mes de llamadas y videollamadas gratuitas-, Outlook, OneDrive -que\u00a0ofrece ya 15GB de almacenamiento gratuito-, HERE Maps y HERE Drive.<\/p>\n<p>Nokia X2 est\u00e1 disponible en los colores verde, amarillo, blanco, negro y naranja, por un precio de 99 euros sin impuestos, y estar\u00e1 a la venta pr\u00f3ximamente, seg\u00fan indica la p\u00e1gina oficial de Nokia.<\/p>\n<p style=\"color: #252324;\"><a style=\"color: #004276;\" href=\"http:\/\/www.eleconomista.es\/tecnologia-gadgets\/noticias\/5887321\/06\/14\/Microsoft-lanza-el-Nokia-X2-un-Android-Dual-SIM-que-se-vendera-por-120-euros-.html#.Kku8VJmyvGROyh7\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft\u00a0ha anunciado este martes el nuevo\u00a0smartphone\u00a0Nokia X2, un Android que costar\u00e1 99 euros (135\u00a0d\u00f3lares). Se trata del sucesor del Nokia X, pero tiene la peculiaridad de que es el primer tel\u00e9fono Android fabricado por Microsoft, que adquiri\u00f3 Nokia el pasado mes de abril.<\/p>\n","protected":false},"author":3,"featured_media":4887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=4886"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4886\/revisions"}],"predecessor-version":[{"id":4888,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4886\/revisions\/4888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/4887"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=4886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=4886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=4886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}