{"id":49405,"date":"2015-10-11T17:02:09","date_gmt":"2015-10-11T21:02:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=49405"},"modified":"2015-10-10T21:06:42","modified_gmt":"2015-10-11T01:06:42","slug":"es-el-humano-la-unica-especie-suicida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/es-el-humano-la-unica-especie-suicida\/","title":{"rendered":"\u00bfEs el humano la \u00fanica especie suicida?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/image_content_5643151_20151010163217.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-49406\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/image_content_5643151_20151010163217.jpg\" alt=\"image_content_5643151_20151010163217\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/image_content_5643151_20151010163217.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/image_content_5643151_20151010163217-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/image_content_5643151_20151010163217-105x56.jpg 105w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><br \/>\n<\/a>M\u00e1s de 800 mil personas se suicidan cada a\u00f1o, lo que representa una muerte cada 40 segundos, seg\u00fan informes de la Organizaci\u00f3n Mundial de la Salud (OMS). De acuerdo a esta entidad, el suicidio es la segunda causa principal de defunci\u00f3n en el grupo etario de 15 a 29 a\u00f1os y el 75 % de estos se produce en pa\u00edses de ingresos bajos y medianos.<!--more--><\/p>\n<p>La ingesta de plaguicidas, el ahorcamiento y las armas de fuego son algunos de los m\u00e9todos m\u00e1s comunes de suicidio en todo el mundo. Por lo general, el suicidio llega luego de largos per\u00edodos de depresi\u00f3n. Es por ello que si se parte de la idea de que los animales irracionales tambi\u00e9n se deprimen, quiz\u00e1s cabe cuestionarse si pudieran adem\u00e1s llegar a suicidarse.<\/p>\n<p>En la comunidad cient\u00edfica esta interrogante siempre estuvo presente y hoy permanece la controversia. Unos creen que no es posible y otros que s\u00ed.<\/p>\n<p>De acuerdo con especialistas veterinarios en el reino animal existe un comportamiento autodestructivo que muchos expertos lo comparan con el suicidio humano.<\/p>\n<p>\u201cMuchos animales que dejan de comer, patos que sumergen la cabeza en el agua hasta que se ahogan, animales a los que se le han muerto sus due\u00f1os se dejan morir de hambre, es decir, que tambi\u00e9n los animales tienen ese instinto, que no se le llama suicidio propiamente, pero es una conducta autodestructiva\u201d, explic\u00f3 a DL la m\u00e9dico veterinaria, Aida Mercedes.<\/p>\n<p>Dijo que aunque no ha conocido un caso de suicidio en animales, tiene la certeza de que estos se deprimen y se estresan.<\/p>\n<p>Algunos clientes que llegan a la cl\u00ednica de Mercedes le dicen: \u201cMi perrito se muri\u00f3 de depresi\u00f3n, ten\u00eda varios d\u00edas sin comer y falleci\u00f3\u201d.<\/p>\n<p>La doctora expres\u00f3 que cuando se presentan casos de depresi\u00f3n en los animales los m\u00e9dicos recurren a ejercicios y estimulaciones que les cambia el estado de \u00e1nimo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 800 mil personas se suicidan cada a\u00f1o, lo que representa una muerte cada 40 segundos, seg\u00fan informes de la Organizaci\u00f3n Mundial de la Salud (OMS). De acuerdo a esta entidad, el suicidio es la segunda causa principal de defunci\u00f3n en el grupo etario de 15 a 29 a\u00f1os y el 75 % de estos se produce en pa\u00edses de ingresos bajos y medianos.<\/p>\n","protected":false},"author":12,"featured_media":49406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-49405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/49405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=49405"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/49405\/revisions"}],"predecessor-version":[{"id":49407,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/49405\/revisions\/49407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/49406"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=49405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=49405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=49405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}