{"id":4957,"date":"2014-06-25T13:44:51","date_gmt":"2014-06-25T17:44:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=4957"},"modified":"2014-06-25T13:44:51","modified_gmt":"2014-06-25T17:44:51","slug":"google-asegura-que-apple-ha-copiado-sus-innovaciones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-asegura-que-apple-ha-copiado-sus-innovaciones\/","title":{"rendered":"Google asegura que Apple ha copiado sus innovaciones"},"content":{"rendered":"<p style=\"color: #252324\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-64159\" src=\"http:\/\/www.audienciaelectronica.net\/wp-content\/uploads\/2014\/06\/android_apple.jpg\" alt=\"android_apple\" width=\"245\" height=\"164\" \/>El vicepresidente s\u00e9nior del gigante Google,\u00a0Sundar Pichai,\u00a0ha afirmado que algunas de las caracter\u00edsticas que presenta Apple para el nuevo \u2018software\u2019 del iPhone han estado disponibles en Android desde hace bastante tiempo.<!--more--><\/p>\n<p style=\"color: #252324\">Respondiendo a la\u00a0r\u00e9plica del CEO de\u00a0Apple,\u00a0pronunciada en la Conferencia Mundial de Desarrolladores, sobre que la mayor\u00eda de los\u00a0usuarios poseen tel\u00e9fonos que se ejecutan en las versiones antiguas de \u2018software\u2019 Android sin las caracter\u00edsticas m\u00e1s recientes., Pichai asegur\u00f3 que\u00a0muchas de las cosas que Apple solo anuncia han sido desarrolladas en\u00a0Google\u00a0hace cuatro o cinco a\u00f1os.<\/p>\n<p style=\"color: #252324\">En una entrevista para la revista \u2018Bloomberg Businessweek\u2018, Pichai, quien est\u00e1 a cargo de la gesti\u00f3n de toda la divisi\u00f3n de Android en Google, ha especificado que se trata de tales\u00a0\u2018innovaciones\u2019\u00a0como el sistema de notificaciones\u00a0Rich Notifications\u00a0que aparecen y se mantienen en la pantalla mientras el dispositivo est\u00e1 inactivo,\u00a0los teclados de terceros y los \u2018widgets\u2019.<\/p>\n<p style=\"color: #252324\">El vicepresidente de Google tambi\u00e9n se\u00f1al\u00f3 que hay una\u00a0diferencia considerable\u00a0en lo que Android y Apple est\u00e1n haciendo. As\u00ed, Apple hace sistemas operativos exclusivamente para sus propios dispositivos, que incluyen algunos modelos de iPhone e iPad, mientras que Google es responsable del desarrollo del \u2018software\u2019 que opera los tel\u00e9fonos inteligentes y las tabletas de diferentes fabricantes, como, por ejemplo,\u00a0Samsung, LG, HTC y Motorola.<\/p>\n<p style=\"color: #252324\">De acuerdo con la estad\u00edstica m\u00e1s reciente de la compa\u00f1\u00eda de investigaci\u00f3n IDC, Android podr\u00eda asumir el control del 80,2% de la cuota de mercado de tel\u00e9fonos inteligentes en todo el mundo a finales del 2014. Se espera que Apple, por su parte, solo llegue al 14,8%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vicepresidente s\u00e9nior del gigante Google,\u00a0Sundar Pichai,\u00a0ha afirmado que algunas de las caracter\u00edsticas que presenta Apple para el nuevo \u2018software\u2019 del iPhone han estado disponibles en Android desde hace bastante tiempo.<\/p>\n","protected":false},"author":3,"featured_media":4960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=4957"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4957\/revisions"}],"predecessor-version":[{"id":4958,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/4957\/revisions\/4958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/4960"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=4957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=4957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=4957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}