{"id":50086,"date":"2015-10-30T08:23:49","date_gmt":"2015-10-30T12:23:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50086"},"modified":"2015-10-28T14:09:32","modified_gmt":"2015-10-28T18:09:32","slug":"bebe-que-nacio-sin-nariz-es-verdaderamente-encantador","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bebe-que-nacio-sin-nariz-es-verdaderamente-encantador\/","title":{"rendered":"Beb\u00e9 que naci\u00f3 sin nariz es verdaderamente encantador"},"content":{"rendered":"<div class=\"article-body\">\n<p><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/screen-shot-2015-10-24-at-3-42-20-pm.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50087 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/screen-shot-2015-10-24-at-3-42-20-pm.jpeg\" alt=\"screen-shot-2015-10-24-at-3-42-20-pm\" width=\"858\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/screen-shot-2015-10-24-at-3-42-20-pm.jpeg 858w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/screen-shot-2015-10-24-at-3-42-20-pm-300x189.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/10\/screen-shot-2015-10-24-at-3-42-20-pm-105x66.jpeg 105w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><br \/>\n<\/a>Timothy Eli Thompson<\/b> lleg\u00f3 al mundo el 4 de marzo de este a\u00f1o, era un ni\u00f1o perfectamente sano, pero naci\u00f3 sin nariz.<!--more--><\/p>\n<p>Tan solo a los cinco d\u00edas de haber nacido, le realizaron una traqueotom\u00eda para facilitar el paso de aire a sus pulmones, sin embargo, el peque\u00f1o supero dicho procedimiento y actualmente es<b>t\u00e1 por cumplir 8 meses de edad.<\/b><\/p>\n<p>Al respecto,\u00a0<b>Brandy McGlathery<\/b>, mam\u00e1 del peque\u00f1o public\u00f3 en \u00abGofundme\u00bb un mensaje conmovedor donde comparte la posibilidad de un tratamiento para su beb\u00e9 con la ayuda de una<b>impresora 3D.<\/b><\/p>\n<\/div>\n<div class=\"html-component\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/CSHFHzlU8AAkET9.jpg\" alt=\"Cr\u00e9dito\" width=\"100%\" \/><\/div>\n<div class=\"article-body\">\n<p>En la publicaci\u00f3n tambi\u00e9n pidi\u00f3 ayuda con donaciones para poder llevar a cabo este tratamiento y mostr\u00f3 esta imagen donde <b>muestra al peque\u00f1o Timothy completamente adorable.\u00a0<\/b><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Timothy Eli Thompson lleg\u00f3 al mundo el 4 de marzo de este a\u00f1o, era un ni\u00f1o perfectamente sano, pero naci\u00f3 sin nariz.<\/p>\n","protected":false},"author":3,"featured_media":50087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-50086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50086"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50086\/revisions"}],"predecessor-version":[{"id":50088,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50086\/revisions\/50088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50087"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}