{"id":50443,"date":"2015-11-13T16:10:54","date_gmt":"2015-11-13T20:10:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50443"},"modified":"2015-11-03T23:16:48","modified_gmt":"2015-11-04T03:16:48","slug":"la-hazana-del-golf-que-se-ve-una-vez-cada-25-millones-de-jugadas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-hazana-del-golf-que-se-ve-una-vez-cada-25-millones-de-jugadas\/","title":{"rendered":"La haza\u00f1a del golf que se ve una vez cada 25 millones de jugadas"},"content":{"rendered":"<p class=\"story-body__introduction\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/150909153849_golf_proeza_624x351_thinkstock_nocredit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-50444\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/150909153849_golf_proeza_624x351_thinkstock_nocredit.jpg\" alt=\"150909153849_golf_proeza_624x351_thinkstock_nocredit\" width=\"624\" height=\"351\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/150909153849_golf_proeza_624x351_thinkstock_nocredit.jpg 624w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/150909153849_golf_proeza_624x351_thinkstock_nocredit-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/150909153849_golf_proeza_624x351_thinkstock_nocredit-105x59.jpg 105w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/a><\/p>\n<p class=\"story-body__introduction\">\nOcurri\u00f3 lo que es casi imposible que pase. Dos golfistas aficionados lograron un doble hoyo en uno en el mismo campo y en golpes consecutivos.<!--more--><\/p>\n<p>La rareza de esta haza\u00f1a es tal, que una de las principales casas de apuestas de Reino Unido, Paddy Power, <strong>calcula una probabilidad de que esto ocurra de 25 millones a uno.<br \/>\n<\/strong><\/p>\n<p>Los afortunados jugadores fueron Mark Avis y Aaron Saddleton, quiene participaban en un torneo aficionado por parejas en el campo del Royal Norwich Golf Club, en el este de Inglaterra.\u00bbYo me asombr\u00e9 y todos quedamos at\u00f3nitos\u00bb, declar\u00f3 Avis, de 43 a\u00f1os, al peri\u00f3dico regional <i>Eastern Daily Press<\/i>, que fue el primero en informar sobre la proeza.<\/p>\n<p><strong>\u00abEs un momento hist\u00f3rico, no puedes inventarlo\u00bb.<\/strong><\/p>\n<h2 class=\"story-body__crosshead\">Empate<\/h2>\n<p>Morgan Thompson, asistente profesional del campo de golf, calific\u00f3 el logro de \u00abexcepcional\u00bb.<\/p>\n<p>El primero en realizar su golpe fue Saddleton, de 29 a\u00f1os, quien consigui\u00f3 el <i>ace<\/i>en el hoyo n\u00famero nueve del recorrido, de par 3 y 135 yardas.\u00a0Pero su celebraci\u00f3n fue corta ya que Avis, su rival en la ronda, repiti\u00f3 la haza\u00f1a en el golpe siguiente.<\/p>\n<p><strong>\u00abNo puedo creer que logr\u00e9 un hoyo en uno y ni siquiera gan\u00e9 el juego\u00bb<\/strong>, lament\u00f3 Saddleton.<\/p>\n<p>Seg\u00fan Thompson, el campo promedia un hoyo en uno cada seis meses. Pero no recuerda que haya ocurrido algo similar desde la d\u00e9cada los 70.\u00a0<span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"js-image-replace alignright\" src=\"http:\/\/ichef.bbci.co.uk\/news\/ws\/304\/amz\/worldservice\/live\/assets\/images\/2015\/09\/09\/150909154047_golf_proeza_304x171_thinkstock_nocredit.jpg\" alt=\"\" width=\"304\" height=\"171\" \/><\/span>En el mismo campo, <strong>en 1971, John Hudson logr\u00f3 lo que se considera ha sido la \u00fanica vez que un jugador logr\u00f3 dos hoyos en uno de manera consecutiva<\/strong> en un torneo profesional.<\/p>\n<p>Pero al tratarse esta vez de jugadores aficionados, la casa de apuestas considera que tiene a\u00fan m\u00e1s m\u00e9rito, ya que si se hubiera tratado de profesionales la probabilidad se hubiera reducido a 1,9 millones a uno.<\/p>\n<p>Paddy Power calcula que es m\u00e1s f\u00e1cil ganar la loter\u00eda en Reino Unido (10 millones a uno) que lograr lo que consiguieron esta semana Saddleton y Avis.<\/p>\n<p>Los jugadores no fueron consultados si hubieran preferido el hipot\u00e9tico dinero o el honor de ser los autores de los golpes perfectos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 lo que es casi imposible que pase. Dos golfistas aficionados lograron un doble hoyo en uno en el mismo campo y en golpes consecutivos.<\/p>\n","protected":false},"author":12,"featured_media":50444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,323],"tags":[],"class_list":["post-50443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50443"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50443\/revisions"}],"predecessor-version":[{"id":50445,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50443\/revisions\/50445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50444"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}