{"id":50625,"date":"2015-11-07T10:04:26","date_gmt":"2015-11-07T14:04:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50625"},"modified":"2015-11-05T05:10:33","modified_gmt":"2015-11-05T09:10:33","slug":"costillas-de-cerdo-al-horno-con-miel-y-mostaza","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/costillas-de-cerdo-al-horno-con-miel-y-mostaza\/","title":{"rendered":"Costillas de cerdo al horno con miel y mostaza"},"content":{"rendered":"<h3><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50629 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334.jpg\" alt=\"costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334\" width=\"500\" height=\"334\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/costillas-de-cerdo-al-horno-con-miel-y-mostaza-500x334-105x70.jpg 105w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><!--more--><\/a><br \/>\nIngredientes:<\/h3>\n<ul>\n<li>1 paquete de costillas de cerdo<\/li>\n<li>\u00bd vaso de aceite de oliva<\/li>\n<li>1 cucharada de miel<\/li>\n<li>1 cucharada de mostaza<\/li>\n<li>1 cucharadita de salsa de soja<\/li>\n<li>Sal<\/li>\n<li>Pimienta negra<\/li>\n<\/ul>\n<h3>Utensilios:<\/h3>\n<ul>\n<li>1 bandeja de horno<\/li>\n<li>1 bol<\/li>\n<li>Varillas<\/li>\n<li>Brocha de cocina<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-64122\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2015\/06\/costillas-carne-500x395.jpg\" alt=\"costillas carne\" width=\"500\" height=\"395\" \/><\/p>\n<ul>\n<li><strong>Precalentar el horno a 180 \u00baC<\/strong> y engrasar una fuente con un poco de aceite de oliva.<\/li>\n<li>Salpimentar las costillas por ambos lados y reservar.<\/li>\n<li>En un bol aparte, mezclar con ayuda de unas varillas, el aceite, la miel, la mostaza y la salsa de soja. Remover bien hasta que quede una mezcla homog\u00e9nea.<\/li>\n<li>Con ayuda de un pincel de cocina, pintar las costillas por el lado de la carne y colocarlas en la fuente de horno,\u00a0<strong>con el lado pintado hacia abajo<\/strong>.<\/li>\n<li>Pintar el lado del hueso.<\/li>\n<li>Hornear durante media hora. Pasado ese tiempo, sacar las costillas, darles la vuelta y pintarlas de nuevo con la salsa.<\/li>\n<li>Volver a hornear durante media hora, <strong>pintando las costillas de nuevo a los 15 minutos.<\/strong><\/li>\n<li>Pasada la primera hora, <strong>subir la temperatura a<\/strong> <strong>200 \u00baC<\/strong> y hornearlas hasta que se doren.<\/li>\n<\/ul>\n<h3>Datos de inter\u00e9s:<\/h3>\n<ul>\n<li>Dificultad: <strong>media<\/strong><\/li>\n<li>Tiempo de preparaci\u00f3n: <strong>20 minutos<\/strong>.<\/li>\n<li>Tiempo de cocci\u00f3n: <strong>1 h y 15 minutos.<\/strong><\/li>\n<li>Si las costillas fuesen m\u00e1s finas, reducir el tiempo de cocci\u00f3n a 50 minutos y darles la vuelta a los 25 minutos.<\/li>\n<li>Para conseguir una costra crujiente en las costillas, poner el grill en el horno en los \u00faltimos 5 minutos, cuidando que no se quemen las costillas por arriba, claro.<\/li>\n<\/ul>\n<h2>Costillas de cerdo a la salsa de miel, mostaza y soja<\/h2>\n<h3>Ingredientes:<\/h3>\n<ul>\n<li>1 costillar de cerdo (750 g)<\/li>\n<li>3 cucharadas de mostaza\u00a0de Dijon<\/li>\n<li>2 cucharadas de miel<\/li>\n<li>5 cucharadas de salsa de soja<\/li>\n<\/ul>\n<h3>Utensilios:<\/h3>\n<ul>\n<li>1 bol ancho<\/li>\n<li>Varillas<\/li>\n<li>1 fuente de horno<\/li>\n<li>1 cuchillo<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-57176\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2015\/03\/lomo-con-mostaza-500x334.jpg\" alt=\"lomo con mostaza\" width=\"500\" height=\"334\" \/><\/p>\n<ul>\n<li>En el bol, mezclar la miel, la mostaza y la salsa de soja, batiendo bien con las varillas hasta que quede una <strong>mezcla uniforme<\/strong>.<\/li>\n<li>Introducir las costillas en el bol y dejar macerar durante <strong>15 minutos<\/strong>.<\/li>\n<li>Precalentar el horno a <strong>200 \u00baC.<\/strong><\/li>\n<li>Sacar las costillas del bol y colocarlas en la fuente de horno, con la carne hacia abajo.<\/li>\n<li>Hornear las costillas durante <strong>25 minutos<\/strong> y darles la vuelta.<\/li>\n<li>Echar media taza de agua a las costillas para que se haga la salsa y hornearlas durante otros <strong>25 minutos<\/strong>.<\/li>\n<li>Una vez listo, separar las costillas con ayuda de un cuchillo y servir.<\/li>\n<\/ul>\n<h3>Datos de inter\u00e9s:<\/h3>\n<ul>\n<li>Dificultad: <strong>media<\/strong><\/li>\n<li>Tiempo de preparaci\u00f3n: <strong>10 minutos<\/strong><\/li>\n<li>Tiempo de cocci\u00f3n: <strong>50 minutos<\/strong><\/li>\n<li>Si las costillas son m\u00e1s gruesas, se pueden hornear durante m\u00e1s tiempo y darles la vuelta a la media hora aproximadamente.<\/li>\n<li>Si sobra salsa, se puede servir con las costillas ya hechas o<strong> como acompa\u00f1amiento para untar las patatas de la guarnici\u00f3n.<\/strong><\/li>\n<li>La salsa que sobre tambi\u00e9n puede usarse como aperitivo, para untar salchichas o patatas, o como guarnici\u00f3n para todo tipo de carnes, a la parrilla o asadas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":50629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-50625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50625"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50625\/revisions"}],"predecessor-version":[{"id":50630,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50625\/revisions\/50630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50629"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}