{"id":50713,"date":"2015-12-05T08:00:02","date_gmt":"2015-12-05T12:00:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50713"},"modified":"2015-11-06T08:05:15","modified_gmt":"2015-11-06T12:05:15","slug":"zumo-de-limon-y-semillas-de-chia-para-el-colesterol","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/zumo-de-limon-y-semillas-de-chia-para-el-colesterol\/","title":{"rendered":"Zumo de lim\u00f3n y semillas de ch\u00eda para el colesterol"},"content":{"rendered":"<div class=\"headline-article\">Las semillas de ch\u00eda son un remedio muy eficaz para reducir el colesterol, pero no debemos tomarlas si estamos siguiendo un tratamiento para la tensi\u00f3n arterial, o tenemos esta baja.<\/div>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/agua-de-ch\u00eda-y-limon-para-adelgazar-500x333.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50714 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/agua-de-ch\u00eda-y-limon-para-adelgazar-500x333.jpg\" alt=\"agua-de-ch\u00eda-y-limon-para-adelgazar-500x333\" width=\"500\" height=\"333\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/agua-de-ch\u00eda-y-limon-para-adelgazar-500x333.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/agua-de-ch\u00eda-y-limon-para-adelgazar-500x333-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/agua-de-ch\u00eda-y-limon-para-adelgazar-500x333-105x70.jpg 105w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Si tu m\u00e9dico te ha indicado que tu colesterol est\u00e1 algo elevado, sabes que vas a tener que cambiar tus h\u00e1bitos de vida.\u00a0Es fundamental llevar\u00a0<strong>una alimentaci\u00f3n adecuada, practicar algo de ejercicio y seguir los tratamientos<\/strong> que los profesionales de la salud nos prescriban.<\/p>\n<p>Ahora bien, dentro de esos peque\u00f1os cambios que debemos hacer en nuestra\u00a0dieta, siempre te vendr\u00e1 bien conocer sencillos remedios caseros que pueden ayudarte.<\/p>\n<p>Tomar de forma regular zumo de lim\u00f3n con semillas de ch\u00eda nos va a permitir regular los niveles de colesterol, de ah\u00ed que sea una opci\u00f3n f\u00e1cil y econ\u00f3mica, adem\u00e1s de deliciosa, que no est\u00e1 de m\u00e1s tener en cuenta.<\/p>\n<p>\u00bfTe animas a probarla?<\/p>\n<div class=\"desktopAd\"><\/div>\n<h2>Beneficios del zumo de lim\u00f3n y semillas de ch\u00eda para bajar nuestro colesterol<\/h2>\n<p>En ocasiones la naturaleza pone al alcance de nuestra mano verdaderos remedios para esas dolencias que, aunque cotidianas, no dejan de ser graves. Nunca le quites importancia al colesterol elevado.<\/p>\n<p>Sabes que, a largo plazo, los riesgos son altos:<\/p>\n<ul>\n<li>Padecer hipercolesterolemia supone tener<strong> el doble de probabilidades\u00a0de\u00a0sufrir un infarto de miocardio <\/strong>que aquellas personas con un nivel normal.<\/li>\n<li>Cuando nuestro organismo ya no es capaz de absorber todo el colesterol que circula por la sangre, el sobrante se deposita en las paredes de las arterias y contribuye a su progresivo estrechamiento.<\/li>\n<\/ul>\n<ul>\n<li>Lo m\u00e1s peligroso del colesterol es que no percibimos\u00a0s\u00edntomas, de ah\u00ed que solo pueda ser diagnosticado a trav\u00e9s de un an\u00e1lisis de sangre. Es vital que establezcamos reconocimientos peri\u00f3dicos con nuestro m\u00e9dico.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-81298\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2015\/11\/zumo-de-limon-y-chia-para-el-colesterol-2-500x282.jpg\" alt=\"zumo de limon y chia para el colesterol 2\" width=\"500\" height=\"282\" \/><\/p>\n<h3>Beneficios del lim\u00f3n para tratar el colesterol<\/h3>\n<p>En nuestro espacio te hablamos muy a menudo de los beneficios del lim\u00f3n para cuidar de tu salud en general. Ahora bien, lo que es posible que no sepas es que este c\u00edtrico es muy eficaz para reducir los niveles de triglic\u00e9ridos:<\/p>\n<ul>\n<li><strong>El lim\u00f3n es un alimento alcalino que nos permite depurar el organismo<\/strong>. Gracias a ello optimizamos la funci\u00f3n hep\u00e1tica y obtenemos\u00a0un resultado<em>hipolipemiante<\/em>, es decir, conseguimos reducir los l\u00edpidos en sangre, as\u00ed como el colesterol y los triglic\u00e9ridos altos de forma natural.<\/li>\n<\/ul>\n<ul>\n<li>El lim\u00f3n es un \u00a0depurador tan efectivo que nos ayuda no solo a reducir el colesterol, sino que, adem\u00e1s, favorece su eliminaci\u00f3n y nos permite depurar grasas.<\/li>\n<\/ul>\n<p>Tampoco podemos olvidar que el lim\u00f3n es muy rico en vitamina C. Esta vitamina, tal y como nos indican estudios como el publicado en la revista \u201c<a href=\"http:\/\/ajcn.nutrition.org\/\" target=\"_blank\">The American journal of nutrition<\/a>\u201c, act\u00faa como una protectora de la salud card\u00edaca:<\/p>\n<ul>\n<li>Tomar zumo de lim\u00f3n de forma regular<strong>\u00a0reduce en un 20% el riesgo de sufrir enfermedades del coraz\u00f3n<\/strong>.<\/li>\n<li>Protege a las c\u00e9lulas de la oxidaci\u00f3n producida por los radicales libres.<\/li>\n<li>Estos resultados solo ser\u00e1n visibles si consumimos el lim\u00f3n fresco, y no en zumo envasado o en comprimidos.<\/li>\n<\/ul>\n<blockquote>\n<div class=\"desktopAd\">\n<div id=\"div-gpt-ad-1443439665272-0\">\n<div id=\"div-gpt-ad-1443439665272-0_ad_container\">\n<div class=\"adm-intext\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<h3>Semillas de ch\u00eda, un tesoro natural para la salud<\/h3>\n<p>No dudes en adquirir semillas de ch\u00eda en tu tienda natural m\u00e1s cercana, tu salud general lo va a agradecer. Ahora bien, si para\u00a0algo son utilizadas las semillas de ch\u00eda es para reducir el colesterol y para perder peso.<\/p>\n<ul>\n<li>Las semillas de ch\u00eda tienen un alto contenido en \u00e1cidos grasos omega 3, que\u00a0son muy efectivos para reducir el colesterol.<\/li>\n<li>Las semillas de ch\u00eda son muy ricas en antioxidantes, prote\u00ednas, vitaminas B1, B2, B3 y minerales tales como f\u00f3sforo, calcio, potasio, magnesio, hierro, zinc y cobre. Adem\u00e1s, nos aportan un 27% de fibra por cada 100 gramos.<\/li>\n<li><strong>La semilla de ch\u00eda est\u00e1 considerada como un \u201csuplemento diet\u00e9tico\u201d <\/strong>muy \u00fatil para los pacientes con colesterol elevado gracias a sus fistosteroles y el \u00e1cido alfa linol\u00e9nico. Son un recurso sencillo para favorecer nuestra salud general.<\/li>\n<\/ul>\n<h2>C\u00f3mo tomar mi zumo de lim\u00f3n y semillas de ch\u00eda para tratar el colesterol<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-81307\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2015\/11\/zumo-de-limon-y-chia-para-el-colesterol1-500x330.jpg\" alt=\"zumo de limon y chia para el colesterol\" width=\"500\" height=\"330\" \/><\/p>\n<h3>\u00bfQu\u00e9 necesito?<\/h3>\n<ul>\n<li>1 cucharadita de semillas de ch\u00eda (5 g)<\/li>\n<li>1 vaso y \u00bd de agua (300 ml)<\/li>\n<li>Un lim\u00f3n<\/li>\n<li>1 cucharada de miel (25 g)<\/li>\n<\/ul>\n<h3>\u00bfC\u00f3mo lo preparo?<\/h3>\n<ul>\n<li>Es muy f\u00e1cil de preparar. Lo primero que haremos ser\u00e1\u00a0dejar en remojo los 5 gramos de semillas\u00a0de ch\u00eda con medio vaso de agua (100 ml) durante una hora. \u00bfCon qu\u00e9 finalidad? Para que se reblandezcan.<\/li>\n<\/ul>\n<p>Poco a poco ver\u00e1s c\u00f3mo se forma una especie de gel muy caracter\u00edstico.<\/p>\n<ul>\n<li>A continuaci\u00f3n,\u00a0obtendremos el jugo de nuestro lim\u00f3n. Una vez listo, lo mezclaremos con un vaso de agua que est\u00e9 a temperatura ambiente.<\/li>\n<\/ul>\n<ul>\n<li>El siguiente paso es igual de f\u00e1cil. Solo tienes que mezclar el vaso de agua con lim\u00f3n con las semillas de ch\u00eda.<\/li>\n<\/ul>\n<p>Si te es complicado combinarlos no dudes en utilizar la batidora. De ese modo tambi\u00e9n podr\u00e1s incluir la cucharada de miel para que esta bebida tenga un sabor a\u00fan m\u00e1s rico. Te encantar\u00e1.<\/p>\n<h3>C\u00f3mo tomarlo<\/h3>\n<p>Recuerda tomar el agua de ch\u00eda con lim\u00f3n cada ma\u00f1ana<strong> en ayunas a lo largo de 20 d\u00edas y descansar una semana.\u00a0<\/strong><\/p>\n<ul>\n<li>Es importante tener en cuenta\u00a0que, si estamos tomando medicaci\u00f3n para reducir la tensi\u00f3n arterial, no conviene excedernos en el consumo de semillas de ch\u00eda, porque por s\u00ed solas ya nos ayudan a regularla.<\/li>\n<li><strong>Si tienes la tensi\u00f3n baja es mejor no tomar semillas de ch\u00eda.<\/strong><\/li>\n<li>Si tomas medicamentos con acci\u00f3n anticoagulante tampoco es recomendable consumir estas semillas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las semillas de ch\u00eda son un remedio muy eficaz para reducir el colesterol, pero no debemos tomarlas si estamos siguiendo un tratamiento para la tensi\u00f3n arterial, o tenemos esta baja.<\/p>\n","protected":false},"author":3,"featured_media":50714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-50713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50713"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50713\/revisions"}],"predecessor-version":[{"id":50715,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50713\/revisions\/50715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50714"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}