{"id":50787,"date":"2015-11-08T20:29:21","date_gmt":"2015-11-09T00:29:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50787"},"modified":"2015-11-08T20:29:21","modified_gmt":"2015-11-09T00:29:21","slug":"jorge-lorenzo-se-convierte-en-el-nuevo-el-rey-de-motogp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jorge-lorenzo-se-convierte-en-el-nuevo-el-rey-de-motogp\/","title":{"rendered":"Jorge Lorenzo se convierte en el nuevo el rey de MotoGP"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/Jorge-Lorenzo-nuevo-el-rey-de-MotoGP.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50789 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/Jorge-Lorenzo-nuevo-el-rey-de-MotoGP.jpg\" alt=\"Jorge Lorenzo nuevo el rey de MotoGP\" width=\"620\" height=\"282\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/Jorge-Lorenzo-nuevo-el-rey-de-MotoGP.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/Jorge-Lorenzo-nuevo-el-rey-de-MotoGP-300x136.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/Jorge-Lorenzo-nuevo-el-rey-de-MotoGP-105x48.jpg 105w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><br \/>\nJorge Lorenzo cruz\u00f3 la meta como nuevo campe\u00f3n de MotoGP y se desat\u00f3 la locura. Todo el equipo del piloto espa\u00f1ol celebr\u00f3 por todo lo alto. Lorenzo no pudo contener las l\u00e1grimas.<!--more--><br \/>\nEl resumen de la \u00faltima carrera del Mundial de MotoGP, en la que se decid\u00eda todo, es que pas\u00f3 lo normal. Es decir, Rossi apret\u00f3 hasta donde pudo, la cuarta plaza, y Lorenzo no se dej\u00f3 adelantar. El mallorqu\u00edn domin\u00f3 la carrera de principio a fin, desde la salida hasta la bandera a cuadros, y no dio opci\u00f3n al italiano, que cedi\u00f3 el liderato en la \u00faltima carrera del a\u00f1o.<\/p>\n<p>Es el tercer t\u00edtulo para Lorenzo, y el quinto en total de su carrera (gan\u00f3 otros dos de 250 cc). El italiano se queda a las puertas del d\u00e9cimo triunfo de su carrera profesional. Rossi sal\u00eda \u00faltimo (en realidad pen\u00faltimo, por una sanci\u00f3n a Crutchlow), y en un par de vueltas se hab\u00eda quitado de en medio a una decena de rivales.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50788 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/jorge-lorenzo.jpg\" alt=\"jorge lorenzo\" width=\"484\" height=\"254\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/jorge-lorenzo.jpg 484w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/jorge-lorenzo-300x157.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/jorge-lorenzo-105x55.jpg 105w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><br \/>\nLa manera de la que el de Urbino se fue quitando pilotos de encima subi\u00f3 el calor de la carrera, aunque con algunos rivales (Petrucci) se lo pusieron muy f\u00e1cil. Pero adelante, Lorenzo apretaba al m\u00e1ximo, seguido por las Honda. Pasado un tercio de la carrera, las posiciones se hab\u00edan estabilizado: Rossi era cuarto, por detr\u00e1s de Lorenzo y las Honda. Ten\u00eda imposible alcanzar al tr\u00edo de cabeza y siendo cuarto, necesitaba que Lorenzo fuera tercero. Confiar en las Honda, tras todo lo que ocurri\u00f3 en Sepang, ten\u00eda su iron\u00eda.<\/p>\n<p>En efecto, Marc M\u00e1rquez no present\u00f3 batalla a Lorenzo pese a lo que dijo el s\u00e1bado. S\u00f3lo Pedrosa, a falta de un par de vueltas, intent\u00f3 echarle pimienta al final, pero no hab\u00eda nada que hacer. Lorenzo cruz\u00f3 primero la meta y gan\u00f3 el Mundial.<\/p>\n<p><a href=\"http:\/\/www.20minutos.es\/deportes\/noticia\/directo-motogp-valencia-cheste-valentino-rossi-jorge-lorenzo-marc-marquez-campeon-mundo-2599679\/0\/#xtor=AD-15&amp;xts=467263\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Lorenzo cruz\u00f3 la meta como nuevo campe\u00f3n de MotoGP y se desat\u00f3 la locura. Todo el equipo del piloto espa\u00f1ol celebr\u00f3 por todo lo alto. Lorenzo no pudo contener las l\u00e1grimas.<\/p>\n","protected":false},"author":3,"featured_media":50789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-50787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50787"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50787\/revisions"}],"predecessor-version":[{"id":50792,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50787\/revisions\/50792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50789"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}