{"id":50852,"date":"2015-11-29T14:40:14","date_gmt":"2015-11-29T18:40:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=50852"},"modified":"2015-11-11T01:44:58","modified_gmt":"2015-11-11T05:44:58","slug":"como-mejorar-tu-vida-en-diez-pasos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-mejorar-tu-vida-en-diez-pasos\/","title":{"rendered":"C\u00f3mo mejorar tu vida en diez pasos"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Un abrazo, un paseo por el parque de tu barrio o una tarde entre <label>familia<\/label> y amigos pueden ser la clave para que <label>d\u00eda<\/label> a d\u00eda saques una <label>sonrisa<\/label> m\u00e1s duradera. No necesitas hacer grandes <label>cambios<\/label> para mejorar tu calidad de vida. Ni necesitas esperar mucho tiempo para ver los resultados que vienen de una actitud positiva.<!--more--> Lo \u00fanico que tienes que hacer es introducir en tu d\u00eda a d\u00eda estos peque\u00f1os pasos:<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/consejos-para-mejorar-tu-vida.jpg\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50855 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/consejos-para-mejorar-tu-vida.jpg\" alt=\"consejos-para-mejorar-tu-vida\" width=\"582\" height=\"388\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/consejos-para-mejorar-tu-vida.jpg 728w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/consejos-para-mejorar-tu-vida-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/consejos-para-mejorar-tu-vida-105x70.jpg 105w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/><\/a><\/p>\n<p><strong>Vivir la naturaleza. <\/strong>Probablemente subestimes lo importantes que es, pero estar en contacto con la naturaleza reduce el estr\u00e9s, aumenta tu creatividad y mejora tu memoria.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><strong>Ejercicio. <\/strong>Todos sabemos lo importante que es, pero pocas personas lo hacen realmente. Hacer deporte te hace m\u00e1s feliz, mejora tu sue\u00f1o y te hace sentir mejor con tu cuerpo. Un estudio de Harvard que ha analizado a un grupo de hombres de m\u00e1s de 70 a\u00f1os lo identific\u00f3 como uno de los secretos de la buena vida.<\/p>\n<p><strong>Pasar tiempo con familia y amigos.<\/strong> El experto en felicidad de Harvard, Daniel Gilbert, identific\u00f3 esto como una de las principales fuentes de felicidad. Las relaciones tienen mucho valor. Sentir que no est\u00e1s conectado socialmente te hace sentir solo, lo que influye tambi\u00e9n en la salud. Los amigos y la familia son la clave para mejorar tu vida. Compartir noticias y responder cuando otros te cuentan buenas noticias.<\/p>\n<p><strong>Expresar gratitud. <\/strong>Te har\u00e1 m\u00e1s feliz, mejorar\u00e1 tus relaciones, te har\u00e1 mejor persona y har\u00e1 la vida mejor a todo aquel que te rodea.<\/p>\n<p><strong>Meditar. <\/strong>La meditaci\u00f3n puede aumentar tu felicidad, el significado de tu vida y el \u00e1nimo social. A la vez, reduce la ansiedad, la depresi\u00f3n y la fatiga.<\/p>\n<p><strong>Dormir lo suficiente.<\/strong> Estar cansado generalmente dificulta que est\u00e9s contento. No solo es malo para la salud, sino que te impide rendir lo suficiente.<\/p>\n<p><strong>Retarte a ti mismo<\/strong>. Aprender idiomas mantiene tu mente despierta. Las clases de m\u00fasica aumentan tu inteligencia, los retos fortalecen tu mente. Aumentar tu fuerza de voluntad solo requiere un peque\u00f1o esfuerzo cada d\u00eda.<\/p>\n<p><strong>Re\u00edr.<\/strong> Las personas que usan el humor para acabar con el estr\u00e9s tienen mejor sistema inmunitario. La risa deber\u00eda ser una vitamina diaria. Solo recordando momentos graciosos podr\u00e1s mejorar tus relaciones.<\/p>\n<p><strong>Abrazar reduce el estr\u00e9s y te ayuda a ser persuasivo.<\/strong> Adem\u00e1s, te hace m\u00e1s feliz.<\/p>\n<p><strong>Ser optimista. <\/strong>El optimismo te hace m\u00e1s saludable y feliz.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un abrazo, un paseo por el parque de tu barrio o una tarde entre familia y amigos pueden ser la clave para que d\u00eda a d\u00eda saques una sonrisa m\u00e1s duradera. No necesitas hacer grandes cambios para mejorar tu calidad de vida. Ni necesitas esperar mucho tiempo para ver los resultados que vienen de una actitud positiva.<\/p>\n","protected":false},"author":3,"featured_media":50855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-50852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=50852"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50852\/revisions"}],"predecessor-version":[{"id":50856,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/50852\/revisions\/50856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50855"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=50852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=50852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=50852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}