{"id":51096,"date":"2015-11-27T05:55:46","date_gmt":"2015-11-27T09:55:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51096"},"modified":"2015-11-27T05:55:46","modified_gmt":"2015-11-27T09:55:46","slug":"llego-el-black-friday-dominicanos-amanecen-en-tiendas-para-aprovechar-las-atractivas-ofertas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/llego-el-black-friday-dominicanos-amanecen-en-tiendas-para-aprovechar-las-atractivas-ofertas\/","title":{"rendered":"Lleg\u00f3 el Black Friday, dominicanos amanecen en tiendas para aprovechar las atractivas ofertas"},"content":{"rendered":"<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/image_content_5868090_20151126184707.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-51097\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/image_content_5868090_20151126184707.jpg\" alt=\"image_content_5868090_20151126184707\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/image_content_5868090_20151126184707.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/image_content_5868090_20151126184707-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/11\/image_content_5868090_20151126184707-105x56.jpg 105w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>SANTO DOMINGO. Miles de personas amanecieron hoy en los grandes establecimientos comerciales para ser de los primeros en aprovechar las rebajas que, en algunos casos, llegan a un 70% del precio original.<!--more--><\/p>\n<p>Desde la medianoche, cientos de personas, en su mayor\u00eda de clase media, hac\u00edan filas frente algunas tiendas, a la espera de que abrieran sus puertas, por temor de llegar tarde a las ofertas.<\/p>\n<p>Sin embargo, algunos centros comerciales comenzaron a promocionar sus rebajas desde ayer.<\/p>\n<p>Los de clase m\u00e1s pudiente hicieron lo mismo, pero desde sus computadoras, aprovechando las ventas por internet, en las cuales ya los empresarios dominicanos empiezan a incursionar, a prop\u00f3sito de lo que representa el fen\u00f3meno de oferta y demanda.<\/p>\n<p>En los centros de trabajo, los medios de transporte, en las calles, conversaciones telef\u00f3nicas, salones de belleza y en cualquier lugar donde se agrupaban personas s\u00f3lo se hablaba del tema: el Viernes Negro, d\u00eda que aprovechan vendedores y consumidores \u201cpara hacer su agosto en noviembre\u201d.<\/p>\n<p>Televisores, acondicionadores de aire, electrodom\u00e9sticos y muebles del hogar, son de las cosas que dec\u00edan que iban a adquirir.<\/p>\n<p>Desde temprano en la ma\u00f1ana, se espera que en calles del Gran Santo Domingo, plazas comerciales y en grandes establecimientos haya un desborde de afluencia de compradores, situaci\u00f3n que desde ayer oblig\u00f3 a las autoridades competentes a redoblar la vigilancia para evitar atracos y otros hechos delictivos.<\/p>\n<p>Se espera que los electrodom\u00e9sticos y los productos de tecnolog\u00eda sean los m\u00e1s demandados. Aunque tambi\u00e9n se ofrecer\u00e1n descuentos en ropa, accesorios, salud, audio, video, joyer\u00eda, veh\u00edculos, medicamentos, art\u00edculos de ferreter\u00eda y jugueter\u00eda, entre otros.<\/p>\n<p>\u201cLos comercios est\u00e1n preparando grandes ofertas para satisfacer a sus clientes, promociones focalizadas en el inter\u00e9s de los clientes seg\u00fan a\u00f1os anteriores; ropa, zapatos, art\u00edculos electr\u00f3nicos; pero tambi\u00e9n extendi\u00e9ndolos a nuevas gamas de productos, como ser\u00eda el rengl\u00f3n de alimentos, para satisfacer a todos los consumidores\u201d, afirm\u00f3 el Presidente de la Organizaci\u00f3n de Empresas Comerciales (ONEC), Antonio Ramos Fern\u00e1ndez.<\/p>\n<p>Ramos expres\u00f3 que, a pesar de esperar una venta masiva que supere el 2014, los socios de la ONEC mantienen su decisi\u00f3n de ofrecer siempre una atenci\u00f3n de primera para todos sus clientes.<\/p>\n<p>A prop\u00f3sito de la guerra de ofertas, la directora de Pro Consumidor, Altagracia Paulino, advirti\u00f3 a los establecimientos comerciales y empresas de servicios que han estado promocionando ventas especiales con motivo del Viernes Negro, abstenerse de utilizar el enunciado \u201chasta agotar existencia\u201d en sus promociones publicitarias de venta de un producto, un bien o servicio.<\/p>\n<p>Dijo que en la \u201cfiesta de las rebajas\u201d, los establecimientos que incurran en esa pr\u00e1ctica podr\u00edan ser multados como lo dispone la resoluci\u00f3n 016\/2014.<\/p>\n<p>Como parte de la estrategia para incentivar la compra de art\u00edculos, los due\u00f1os de establecimientos tienen varias semanas publicando las rebajas de sus art\u00edculos, colocando los precios establecidos en cada mercanc\u00eda y en los que salen con la reducci\u00f3n aplicada.<\/p>\n<\/div>\n<div class=\"entretitulo\">Art\u00edculos para cada edad<\/div>\n<div class=\"text\">\n<p>El p\u00fablico joven prefiere los especiales que incluyen los aparatos, juegos y accesorios tecnol\u00f3gicos.<\/p>\n<p>Las amas de casa aprovechan para adquirir art\u00edculos de decoraci\u00f3n y enseres del hogar, mientras las muchachas apuestan a la moda y a la belleza y buscan los especiales que tengan que ver con mercanc\u00edas para vestir, joyas y accesorios.<\/p>\n<p>Muchos padres aprovecha la ocasi\u00f3n para comprar los juguetes y regalos navide\u00f1os para los m\u00e1s peque\u00f1os de la casa.<\/p>\n<p>En cuanto a los hombres, por lo regular, prefieren el Viernes Negro para comprar veh\u00edculos, accesorios y equipos de \u00e9stos, as\u00ed como equipos de m\u00fasica.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. Miles de personas amanecieron hoy en los grandes establecimientos comerciales para ser de los primeros en aprovechar las rebajas que, en algunos casos, llegan a un 70% del precio original.<\/p>\n","protected":false},"author":12,"featured_media":51097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-51096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51096"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51096\/revisions"}],"predecessor-version":[{"id":51098,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51096\/revisions\/51098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51097"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}