{"id":51744,"date":"2016-01-06T12:50:03","date_gmt":"2016-01-06T16:50:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51744"},"modified":"2016-01-03T16:52:06","modified_gmt":"2016-01-03T20:52:06","slug":"conoce-los-diferentes-tipo-de-drones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conoce-los-diferentes-tipo-de-drones\/","title":{"rendered":"Conoce los diferentes tipo de Drones"},"content":{"rendered":"<p>Un dron es un <span class=\"negrita\">veh\u00edculo a\u00e9reo NO TRIPULADO<\/span>, por eso tambi\u00e9n se le puede llamar VANT abreviatura de veh\u00edculo a\u00e9reo no tripulado en espa\u00f1ol. La palabra dron viene del ingles cuya traducci\u00f3n literal es \u201cz\u00e1ngano\u201d. Se puede llamar dron o drone.<!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ar-drone1.png\" rel=\"attachment wp-att-51745\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51745 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ar-drone1.png\" alt=\"ar-drone1\" width=\"407\" height=\"272\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ar-drone1.png 407w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ar-drone1-300x200.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ar-drone1-105x70.png 105w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/a><\/p>\n<p>Como veh\u00edculo a\u00e9reo puede tener diferentes formas, bien tipo avi\u00f3n, tipo helic\u00f3ptero o incluso formas muy diferentes. Pero los drones no son algo nuevo, el ejemplo m\u00e1s antiguo fue desarrollado despu\u00e9s de la primera guerra mundial, y se emplearon durante la segunda guerra mundial para entrenar a los operarios de los ca\u00f1ones antia\u00e9reos. Sin embargo, no es hasta poco m\u00e1s que a finales del siglo XX cuando operan los drones mediante radio control con todas las caracter\u00edsticas de autonom\u00eda.<\/p>\n<p>Algunos tienen sistema GPS que les permite volver al punto donde inici\u00f3 de su vuelo. En el futuro se espera que los drones vuelen solos, tomando sus propias decisiones, evitando chocar contra las personas y poder evitar los objetos.<\/p>\n<p>La mayor\u00eda de los drones se manejan con radio control, pero pueden ser tambi\u00e9n manejados y programadas mediante una tablet o un smartphone.<\/p>\n<p>Se utilizan para m\u00faltiples tareas, desde tareas de vigilancia, fotograf\u00eda, retransmisiones televisivas, agricultura, ocio y muchas m\u00e1s tareas, ya que cada poco se descubre una nueva forma de utilizar los drones.<\/p>\n<p><strong><span class=\"negrita-subrayado\">Tipos de Drones<\/span><\/strong><\/p>\n<p>La clasificaci\u00f3n es muy amplia, pues debemos tener una\u00a0<strong>comparativas de Drones<\/strong> para saber a que rango pertenecen, pero la primera clasificaci\u00f3n podr\u00eda ser <span class=\"negrita\">en funci\u00f3n del<strong> tipo de alas<\/strong><\/span><strong>.<\/strong><\/p>\n<p>\u2013 <span class=\"negrita\">Drones de Alas Fijas<\/span>: Tienen alas fijas y son similares a un avi\u00f3n.<\/p>\n<p>\u2013 <span class=\"negrita\">Drones MultiRotor<\/span>: Suelen ser cuadric\u00f3pteros (4 rotores con h\u00e9lices) aunque los hay que tienen 6 (hexac\u00f3pteros) o incluso 8 h\u00e9lices. Dos h\u00e9lices giran en el sentido de las agujas del reloj y las otras dos en el otro sentido, creando as\u00ed la fuerza de empuje necesario para llevar al dron hacia arriba. Se pueden mantener en el mismo sitio sin varias la posici\u00f3n, gracias a sus giroscopios y estabilizadores, lo que es perfecto para sacar fotos y grabar v\u00eddeos.<a href=\"http:\/\/10curiosidades.com\/wp-content\/uploads\/2015\/08\/hidrofoil-drone-parrot.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9851 tie-appear\" src=\"http:\/\/10curiosidades.com\/wp-content\/uploads\/2015\/08\/hidrofoil-drone-parrot.jpg\" sizes=\"auto, (max-width: 1022px) 100vw, 1022px\" srcset=\"http:\/\/10curiosidades.com\/wp-content\/uploads\/2015\/08\/hidrofoil-drone-parrot-300x169.jpg 300w, http:\/\/10curiosidades.com\/wp-content\/uploads\/2015\/08\/hidrofoil-drone-parrot.jpg 1022w\" alt=\"hidrofoil-drone-parrot\" width=\"1022\" height=\"575\" \/><\/a><\/p>\n<p><strong><span class=\"negrita\">Seg\u00fan el m\u00e9todo de control tenemos<\/span>:<\/strong><\/p>\n<p>\u2013 <span class=\"negrita\">Aut\u00f3nomo<\/span>: El drone no necesita de un piloto humano que lo controle desde tierra. Se gu\u00eda por sus propios sistemas y sensores integrados.<\/p>\n<p>\u2013 <span class=\"negrita\">Monitorizado<\/span>: En este caso si se necesita la figura de un t\u00e9cnico humano. La labor de esta persona es proporcionar informaci\u00f3n y controlar el feedback del drone. El drone dirige su propio plan de vuelo y el t\u00e9cnico, a pesar de no poder controlar los mandos directamente, s\u00ed puede decidir que acci\u00f3n llevar\u00e1 a cabo.<\/p>\n<p>\u2013 <span class=\"negrita\">Supervisado<\/span>: Un operador pilota el dron, aunque este puede realizar algunas tareas aut\u00f3nomamente.<\/p>\n<p>\u2013 <span class=\"negrita\">Preprogramado<\/span>: El dron sigue un plan de vuelo dise\u00f1ado previamente y no tiene medios de cambiarlo para adaptarse a posibles cambios.<\/p>\n<p>\u2013 <span class=\"negrita\">Controlado remotamente(R\/C)<\/span>: El drone es pilotado directamente por un t\u00e9cnico mediante una consola.<\/p>\n<p><strong><span class=\"negrita\">En funci\u00f3n de su uso<\/span> pueden ser:<\/strong><\/p>\n<p>\u2013 <span class=\"negrita\">Drones Militares<\/span>: son llamados UCAV que procede del ingles Unmanned Combat Air Vehicle, traducido al espa\u00f1ol ser\u00eda vehiculos no tripulados de combate a\u00e9reo. Suelen ir armados y con capacidad de bombardeos.<\/p>\n<p>\u2013 <span class=\"negrita\">Drones Civiles<\/span>: son aquellos drones que no tienen uso militar. A su vez pueden ser de<\/p>\n<p>\u2013 <span class=\"negrita\">De uso comercial<\/span>: como cartograf\u00edas, fotograf\u00edas, v\u00eddeos, etc.<\/p>\n<p>\u2013 <span class=\"negrita\">Para Aficionados<\/span>: Se utilizan como un juguete y suelen tener precios bastantes econ\u00f3micos.<\/p>\n<p>\u2013 <span class=\"negrita\">Para Uso del Gobierno<\/span>: Se utilizan para bomberos, fuerzas de rescate, etc. con el fin de ayudar a las tareas de reconocimiento, rescate, fronterizas e incluso fiscales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un dron es un veh\u00edculo a\u00e9reo NO TRIPULADO, por eso tambi\u00e9n se le puede llamar VANT abreviatura de veh\u00edculo a\u00e9reo no tripulado en espa\u00f1ol. La palabra dron viene del ingles cuya traducci\u00f3n literal es \u201cz\u00e1ngano\u201d. Se puede llamar dron o drone.<\/p>\n","protected":false},"author":12,"featured_media":51745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-51744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51744"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51744\/revisions"}],"predecessor-version":[{"id":51746,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51744\/revisions\/51746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51745"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}