{"id":51773,"date":"2016-01-04T12:31:42","date_gmt":"2016-01-04T16:31:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51773"},"modified":"2016-01-03T19:34:55","modified_gmt":"2016-01-03T23:34:55","slug":"mensajes-de-whatsapp-que-muestran-que-no-te-quiere","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mensajes-de-whatsapp-que-muestran-que-no-te-quiere\/","title":{"rendered":"Mensajes de WhatsApp que muestran que no te quiere"},"content":{"rendered":"<p>Los smartphones son pr\u00e1cticametne una extensi\u00f3n del cuerpo humano. La mayor\u00eda de las personas no dejan de lado el tel\u00e9fono nunca, es lo primero que hacen cuando se levantan y lo \u00faltimo que ven cuando se van a dormir.<!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/45105_msj.jpg\" rel=\"attachment wp-att-51774\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51774 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/45105_msj.jpg\" alt=\"45105_msj\" width=\"669\" height=\"551\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/45105_msj.jpg 669w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/45105_msj-300x247.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/45105_msj-91x75.jpg 91w\" sizes=\"auto, (max-width: 669px) 100vw, 669px\" \/><\/a><\/p>\n<p>Las relaciones, sin lugar a dudas, transcurren -al menos en parte- a trav\u00e9s de WhatsApp, la aplicaci\u00f3n usada por millones de personas en todo el mundo.<\/p>\n<p>Por ese motivo Unicef public\u00f3 a trav\u00e9s de Facebook una campa\u00f1a realizada por la Comunidad de Madrid, donde escribieron: \u201c\u00bfRecibes o mandas mensajes como \u00e9stos? Ten claro que esto NO es amor. \u00a1Identif\u00edcalo!\u201d.<\/p>\n<p>La campa\u00f1a tiene la intenci\u00f3n de mostrarle a las mujeres qu\u00e9 tipos de mensajes muestran que tu pareja no te quiere o que te est\u00e1 tratando mal.<\/p>\n<p>Ac\u00e1 la lista de los mensajes:<\/p>\n<p>-Haces m\u00e1s caso a tus amigas que a m\u00ed<\/p>\n<p>Ey, qu\u00e9 bonita que te pusiste hoy, ya sabes que no me gusta que los dem\u00e1s vean lo que es solo m\u00edo. Mand\u00e1 fotito para darte el ok<\/p>\n<p>-Conectado a estas horas. \u00bfSi no es conmigo con qui\u00e9n?<\/p>\n<p>-No quer\u00eda hacerte da\u00f1o. Sabes que lo hago porque te quiero<\/p>\n<p>-Lo le\u00edste y no contest\u00e1s. Si te olvid\u00e1s de m\u00ed record\u00e1 que tengo unas fotos que no te gustar\u00eda que los dem\u00e1s vieran.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los smartphones son pr\u00e1cticametne una extensi\u00f3n del cuerpo humano. La mayor\u00eda de las personas no dejan de lado el tel\u00e9fono nunca, es lo primero que hacen cuando se levantan y lo \u00faltimo que ven cuando se van a dormir.<\/p>\n","protected":false},"author":12,"featured_media":51774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-51773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51773"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51773\/revisions"}],"predecessor-version":[{"id":51775,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51773\/revisions\/51775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51774"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}