{"id":51784,"date":"2016-01-17T15:48:51","date_gmt":"2016-01-17T19:48:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51784"},"modified":"2016-01-03T19:52:12","modified_gmt":"2016-01-03T23:52:12","slug":"consejos-para-comprar-una-bateria-externa-para-tu-celular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/consejos-para-comprar-una-bateria-externa-para-tu-celular\/","title":{"rendered":"Consejos para comprar una bater\u00eda externa para tu celular"},"content":{"rendered":"<p>A pesar de que los m\u00f3viles cada vez son mejores, tienen m\u00e1s funciones y sirven para m\u00e1s cosas, <strong>lo \u00fanico que no mejora es la autonom\u00eda<\/strong> de los mismos. Es raro el smartphone que aguanta todo el d\u00eda con una carga de su bater\u00eda. <!--more-->Por eso, la proliferaci\u00f3n de bater\u00edas externas est\u00e1 cada vez m\u00e1s extendido y es una opci\u00f3n m\u00e1s que recomendable para recargar tu m\u00f3vil y poder seguir us\u00e1ndolo sin temor a quedarte incomunicado a mitad del d\u00eda.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28.jpg\" rel=\"attachment wp-att-51785\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51785 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28.jpg\" alt=\"Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28\" width=\"797\" height=\"526\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28.jpg 797w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28-300x198.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28-768x507.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Ultrapak_Tour_Portable-UNU-cargadores-telefonos-tabletas_LNCIMA20140801_0069_28-105x69.jpg 105w\" sizes=\"auto, (max-width: 797px) 100vw, 797px\" \/><\/a><\/p>\n<p>Si est\u00e1s pensando en hacerte con una de estas bater\u00edas ten en cuenta estos cuatro consejos que te servir\u00e1n para comprar la que m\u00e1s se adecue a lo que necesitas y al precio que quieres pagar por ella.<\/p>\n<h3>Capacidad de carga<\/h3>\n<p>La capacidad de las bater\u00edas <strong>se mide en miliamperios por hora<\/strong> (mAh), por lo que es recomendable saber de qu\u00e9 capacidad quieres la bater\u00eda externa. Si lo que quieres es disponer de una carga extra debes hacerte con una de la misma capacidad que la bater\u00eda de nuestro smartphone. Para que lo entend\u00e1is ponemos un ejemplo: la capacidad de la bater\u00eda del iPhone 6s es de 2.915 mAh por lo que con una bater\u00eda de 3.000 mAh dispondr\u00e1s de una carga para tu m\u00f3vil. Si quieres disponer de dos cargas tendr\u00e1s que multiplicar la capacidad por dos y comprar una de al menos 6.000 mAh.<\/p>\n<div id=\"adm-c1cec6f8514e3870\"><\/div>\n<h3>Tiempo de cargarlo<\/h3>\n<p>Los <strong>Amperios<\/strong> son los encargados de la velocidad de carga de la bater\u00eda, por lo que a mayor velocidad de carga menor es el tiempo en el que luego tarda en cargarse el m\u00f3vil. Las bater\u00edas habituales son de 0,8 \u00f3 1A aunque<strong>con una de 2A se cargar\u00e1 antes<\/strong>.<\/p>\n<h3>Puertos e intensidad de las salidas<\/h3>\n<p>Tambi\u00e9n tienes que comprobar qu\u00e9 tipo de cable usas para cargar tu m\u00f3vil y si la necesitas para cargar uno o m\u00e1s dispositivos. Lo habitual es que disponga de <strong>un puerto USB tradicional o un micro USB<\/strong>, que te permitir\u00e1 cargarlo con el mismo cable de tu smartphone. Si necesitas cargar m\u00e1s de uno necesitas m\u00e1s salidas de USB, aunque tendr\u00e1s que tener en cuenta que la velocidad de carga se repartir\u00e1. Para gadgets de poca capacidad con una bater\u00eda con una salida de 1 Amperio deber\u00eda valer, pero para m\u00f3viles de m\u00e1s capacidad necesitaremos de 1.8A o 2.1A. Si hablamos de cargar una tablet, tendr\u00e1s que irte a por una de una salida de 2.4A.<\/p>\n<h3>Extras<\/h3>\n<p>Adem\u00e1s de todas estas consideraciones, tambi\u00e9n tendr\u00e1s que tener en cuenta <strong>el tama\u00f1o de la bater\u00eda externa<\/strong> ya que a mayor capacidad, mayor ser\u00e1. Y a igualdad de precio, capacidad y puertos que necesitamos, f\u00edjate en otros extras como <strong>el indicador LED<\/strong> para saber a simple vista el estado de la carga y lo que queda de bater\u00eda. Sin olvidar los <strong>ciclos de carga<\/strong> que nos garantiza cada fabricante y que suelen ser de al menos 500 ciclos en las bater\u00edas de iones de litio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de que los m\u00f3viles cada vez son mejores, tienen m\u00e1s funciones y sirven para m\u00e1s cosas, lo \u00fanico que no mejora es la autonom\u00eda de los mismos. Es raro el smartphone que aguanta todo el d\u00eda con una carga de su bater\u00eda.<\/p>\n","protected":false},"author":12,"featured_media":51785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-51784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51784"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51784\/revisions"}],"predecessor-version":[{"id":51786,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51784\/revisions\/51786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51785"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}