{"id":51839,"date":"2016-01-04T16:18:31","date_gmt":"2016-01-04T20:18:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51839"},"modified":"2016-01-04T16:18:31","modified_gmt":"2016-01-04T20:18:31","slug":"sean-bean-y-eva-green-posibles-villanos-de-wonder-woman","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sean-bean-y-eva-green-posibles-villanos-de-wonder-woman\/","title":{"rendered":"Sean Bean y Eva Green, posibles villanos de \u2018Wonder Woman\u2019"},"content":{"rendered":"<p>A trav\u00e9s de Heroic Hollywood nos hacemos eco de lo que, eso s\u00ed, de momento no podemos considerar m\u00e1s que un rumor: que Warner Bros. quiere que Sean Bean y Eva Green sean los \u201cmalos\u201d de \u2018<strong>Wonder Woman<\/strong>\u2018. M\u00e1s concretamente, que Bean interprete a Ares, el Dios de la Guerra, y que Green haga lo propio con Circe, La Hechicera.<!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/VILLANO-DE-LA-MUJER-MARAVILLA.jpg\" rel=\"attachment wp-att-51842\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51842 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/VILLANO-DE-LA-MUJER-MARAVILLA.jpg\" alt=\"VILLANO DE LA MUJER MARAVILLA\" width=\"500\" height=\"250\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/VILLANO-DE-LA-MUJER-MARAVILLA.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/VILLANO-DE-LA-MUJER-MARAVILLA-300x150.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/VILLANO-DE-LA-MUJER-MARAVILLA-105x53.jpg 105w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Por supuesto, y como buen rumor, la validez que se le quiera dar depende de cada uno\u2026 al menos hasta que el tiempo dicte sentencia, como sin ir m\u00e1s lejos ha sucedido con otro rumor que situaba a la mism\u00edsima Cate Blanchett en la misma producci\u00f3n, y que parece que, despu\u00e9s de todo era cierto\u2026 a medias: la actriz no ser\u00e1 de la partida, pero s\u00ed ha recibido una oferta que al parecer ha declinado amablemente (seg\u00fan Variety).<\/p>\n<p>Por el momento lo \u00fanico confirmado de manera oficial es que Gal Gadot repetir\u00e1 en la piel del citado personaje, en su primera aventura en solitario, tras su presentaci\u00f3n en \u2018<em>Batman v Superman: El amanecer de la justicia<\/em>\u2018, mientras que Chris Pine la secundar\u00e1 dando vida a Steve Trevor, el inter\u00e9s rom\u00e1ntico de la hero\u00edna, en esta superproducci\u00f3n cuyo rodaje comenzar\u00e1 en noviembre en Londres a las \u00f3rdenes de Patty Jenkins.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de Heroic Hollywood nos hacemos eco de lo que, eso s\u00ed, de momento no podemos considerar m\u00e1s que un rumor: que Warner Bros. quiere que Sean Bean y Eva Green sean los \u201cmalos\u201d de \u2018Wonder Woman\u2018. M\u00e1s concretamente, que Bean interprete a Ares, el Dios de la Guerra, y que Green haga lo propio con Circe, La Hechicera.<\/p>\n","protected":false},"author":12,"featured_media":51842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-51839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51839"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51839\/revisions"}],"predecessor-version":[{"id":51843,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51839\/revisions\/51843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51842"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}