{"id":51871,"date":"2016-01-05T09:01:50","date_gmt":"2016-01-05T13:01:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51871"},"modified":"2016-01-05T09:01:50","modified_gmt":"2016-01-05T13:01:50","slug":"bahia-de-las-aguilas-calificada-como-la-playa-mas-cristalina-del-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bahia-de-las-aguilas-calificada-como-la-playa-mas-cristalina-del-mundo\/","title":{"rendered":"Bah\u00eda de las \u00c1guilas calificada como la playa m\u00e1s Cristalina del Mundo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445.jpg\" rel=\"attachment wp-att-51872\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51872 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445.jpg\" alt=\"bahia-de-las-aguilas-1024x614-800x445\" width=\"800\" height=\"445\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445-300x167.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445-768x427.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/bahia-de-las-aguilas-1024x614-800x445-105x58.jpg 105w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\nBah\u00eda de las \u00c1guilas esta ubicada en la parte sur de la Republicana Dominicana. La fabulosa bah\u00eda pertenece al parque nacional Jaragua, \u00a0con aguas cristalinas y una extensi\u00f3n territorial de m\u00e1s de treinta y sietes kil\u00f3metros de largo y bordeada por una fina arena blanca. Bah\u00eda de las \u00c1guilas\u00a0comprende desde\u00a0punta Chimanche\u00a0hasta\u00a0punta \u00c1guila, ubicada en la zona sur de la isla.<!--more--><\/p>\n<p>Bah\u00eda de las \u00e1guilas denominada como un lugar paradisiaco donde se encuentran los m\u00e1s hermosos y coloridos arrecifes coralinos del caribe, donde adem\u00e1s se observan Careyes, Estrellas de mar, Praderas Marinas, Iguanas rinoceronte, Manat\u00edes, Lamb\u00ed, Tortugas, Paloma Coronitas. Tambi\u00e9n les rodean plantas end\u00e9micas como Canelillas, roble, el guayo y la guzabara.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-877\" src=\"http:\/\/popaldia.net\/wp-content\/uploads\/2015\/11\/bahia-de-las-aguilas-03.jpg\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" srcset=\"http:\/\/popaldia.net\/wp-content\/uploads\/2015\/11\/bahia-de-las-aguilas-03-300x187.jpg 300w, http:\/\/popaldia.net\/wp-content\/uploads\/2015\/11\/bahia-de-las-aguilas-03.jpg 900w\" alt=\"bahia-de-las-aguilas-03\" width=\"900\" height=\"560\" \/><\/p>\n<p>VIDEO<\/p>\n<p><iframe loading=\"lazy\" id=\"_dytid_9801\" src=\"https:\/\/www.youtube.com\/embed\/oUSEmQ0olII\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bah\u00eda de las \u00c1guilas esta ubicada en la parte sur de la Republicana Dominicana. La fabulosa bah\u00eda pertenece al parque nacional Jaragua, \u00a0con aguas cristalinas y una extensi\u00f3n territorial de m\u00e1s de treinta y sietes kil\u00f3metros de largo y bordeada por una fina arena blanca. Bah\u00eda de las \u00c1guilas\u00a0comprende desde\u00a0punta Chimanche\u00a0hasta\u00a0punta \u00c1guila, ubicada en la zona sur de la isla.<\/p>\n","protected":false},"author":12,"featured_media":51872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-51871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51871"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51871\/revisions"}],"predecessor-version":[{"id":51873,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51871\/revisions\/51873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51872"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}