{"id":51896,"date":"2016-01-06T11:18:59","date_gmt":"2016-01-06T15:18:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51896"},"modified":"2016-01-06T11:18:59","modified_gmt":"2016-01-06T15:18:59","slug":"es-triste-ver-que-el-trajin-diario-limita-el-tiempo-con-amigos-leales-como-pachy","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/es-triste-ver-que-el-trajin-diario-limita-el-tiempo-con-amigos-leales-como-pachy\/","title":{"rendered":"\u201cEs triste ver que el traj\u00edn diario limita el tiempo con amigos leales como Pachy\u201d"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/correa-llora-a-pachy.jpg\" rel=\"attachment wp-att-51897\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51897 alignnone\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/correa-llora-a-pachy.jpg\" alt=\"correa llora a pachy\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/correa-llora-a-pachy.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/correa-llora-a-pachy-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/correa-llora-a-pachy-105x56.jpg 105w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><br \/>\n<\/a>As\u00ed se refiri\u00f3 Aquiles Correa, quien no pudo contener las l\u00e1grimas en el velatorio al productor musical.<!--more--><\/p>\n<div class=\"text\">\n<p>SANTO DOMINGO. Con la m\u00fasica de Bossa Pop de fondo, orquesta que lider\u00f3, y la proyecci\u00f3n de fotograf\u00edas del artista, contin\u00faa por segundo d\u00eda el velatorio de los restos de Pachy Carasco, en la funeraria Blandino de la avenida Abraham Lincoln.<\/p>\n<p>Este mi\u00e9rcoles, igual que en el d\u00eda de ayer, es notoria la presencia de personalidades del medio art\u00edstico, quienes expresan su pesar a los familiares por el deceso del productor y arreglista musical.<\/p>\n<p>La productora Edilenia Tactuk, los cantautores V\u00edctor V\u00edctor, as\u00ed como el actor y comediante Aquiles Corea, manifestaron su dolor por el repentino fallecimiento de Carrasco en la ma\u00f1ana de ayer, a consecuencia de un accidente cerebrovascular (ACV).<\/p>\n<\/div>\n<div class=\"foto_central cutlineShow\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"waslazy aligncenter\" title=\"\u201cEs triste ver que el traj\u00edn diario limita el tiempo con amigos leales como Pachy\u201d\" src=\"http:\/\/www.diariolibre.com\/documents\/10157\/0\/600x397\/0c14\/600d369\/none\/10904\/BBEF\/image_content_6033341_20160106102228.jpg\" alt=\"\u201cEs triste ver que el traj\u00edn diario limita el tiempo con amigos leales como Pachy\u201d\" width=\"600\" height=\"369\" data-original=\"\/documents\/10157\/0\/600x397\/0c14\/600d369\/none\/10904\/BBEF\/image_content_6033341_20160106102228.jpg\" \/><\/div>\n<\/div>\n<div class=\"text\">\n<p>\u201cLa muerte de Pachy Carrasco representa una gran p\u00e9rdida para la clase art\u00edstica dominicana. Era un gran ser humano, sonriente siempre y leal\u201d, se\u00f1al\u00f3 el cantante Frank Ceara.<\/p>\n<p>Aquiles Correa no pudo contener las l\u00e1grimas al llegar a la funeraria.<\/p>\n<p>Lament\u00f3 que solo un momento como este, de dolor, haya permitido que la clase art\u00edstica se juntara. \u201cTen\u00edamos tiempo diciendo, vamos a juntarnos, y no lo hicimos\u201d, lament\u00f3 el panelista del programa radial El Mismo Golpe.<\/p>\n<p>\u201cSolo nos ve\u00edamos cuando \u00e9l acud\u00eda a uno de los programas donde particip\u00f3, y siempre que nos ve\u00edamos dec\u00edamos, vamos a compartir, es triste ver c\u00f3mo el traj\u00edn diario limita que le dediquemos tiempo a los amigos leales, como Pachy. Eso es lo que me tiene m\u00e1s triste\u201d, sentenci\u00f3 Correa.<\/p>\n<\/div>\n<div class=\"bx-wrapper\">\n<div class=\"bx-viewport\">\n<ul class=\"bxDetalleTexto\">\n<li class=\"foto_galeria_detalle cutlineShow\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"waslazy\" title=\"\u201cEs triste ver que el traj\u00edn diario limita el tiempo con amigos leales como Pachy\u201d\" src=\"http:\/\/www.diariolibre.com\/documents\/10157\/0\/600x397\/0c14\/600d369\/none\/10904\/EBEF\/image_content_6033345_20160106102229.jpg\" alt=\"\u201cEs triste ver que el traj\u00edn diario limita el tiempo con amigos leales como Pachy\u201d\" width=\"600\" height=\"369\" data-original=\"\/documents\/10157\/0\/600x397\/0c14\/600d369\/none\/10904\/EBEF\/image_content_6033345_20160106102229.jpg\" \/><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed se refiri\u00f3 Aquiles Correa, quien no pudo contener las l\u00e1grimas en el velatorio al productor musical.<\/p>\n","protected":false},"author":12,"featured_media":51897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-51896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51896"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51896\/revisions"}],"predecessor-version":[{"id":51898,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51896\/revisions\/51898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51897"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}