{"id":51920,"date":"2016-01-06T12:23:49","date_gmt":"2016-01-06T16:23:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51920"},"modified":"2016-01-06T12:23:49","modified_gmt":"2016-01-06T16:23:49","slug":"10-beneficios-que-la-creatividad-le-aporta-a-tu-vida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-beneficios-que-la-creatividad-le-aporta-a-tu-vida\/","title":{"rendered":"10 beneficios que la creatividad le aporta a tu vida"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Creatividad-500x281.jpg\" rel=\"attachment wp-att-51921\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-51921\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Creatividad-500x281.jpg\" alt=\"Creatividad-500x281\" width=\"500\" height=\"281\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Creatividad-500x281.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Creatividad-500x281-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Creatividad-500x281-105x59.jpg 105w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><br \/>\n<\/a>La creatividad es una forma de ayudarnos a sentirnos \u00fatiles y a crecer como personas, por lo que tambi\u00e9n nos puede servir de terapia para aquellos momentos m\u00e1s depresivos.<!--more--><\/p>\n<p>La creatividad es una facultad\u00a0que todos los seres humanos tienen en menor o mayor medida.<\/p>\n<p>El t\u00e9rmino est\u00e1 relacionado\u00a0con la capacidad de crear obras art\u00edsticas, pero tambi\u00e9n<strong>abarca esas habilidades que permiten ver el mundo de forma diferente<\/strong> para buscar soluciones a aquello que parece no tenerla.<\/p>\n<p>El cerebro est\u00e1 dividido en\u00a0dos hemisferios y cada uno tiene una funci\u00f3n especial. <strong>El derecho es el responsable del pensamiento creativo<\/strong>, mientras que el izquierdo se encarga del trabajo racional.<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sync.mathtag.com\/sync\/img?type=sync&amp;mt_exid=20&amp;redir=http%3a%2f%2fdis.criteo.com%2frex%2fmatch.aspx%3fc%3d2%26uid%3d%5bMM_UUID%5d\" alt=\"\" width=\"0\" height=\"0\" \/><\/p>\n<p>Teniendo esto en cuenta, se descarta que haya personas que no tengan alg\u00fan tipo de creatividad. El hecho de no desarrollarla tanto como otros no quiere decir que no exista.<\/p>\n<p>A menudo <strong>se aconseja estimular esta cualidad desde la infancia<\/strong>, ya que es la forma m\u00e1s eficaz de conservarla por el resto de la vida.<\/p>\n<p>No obstante, siempre es bueno sacarla en su m\u00e1xima expresi\u00f3n en todas las edades para disfrutar de una serie de efectos positivos que tiene para el bienestar general.<\/p>\n<p>A continuaci\u00f3n revelamos los<strong> 10 beneficios de los que toda persona puede disfrutar cuando potencia su creatividad.<\/strong> \u00a1Con\u00f3celos!<\/p>\n<h2>1. Construye y mejora la autoestima<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-85934\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Construye-y-mejora-la-autoestima-500x334.jpg\" alt=\"Construye y mejora la autoestima\" width=\"500\" height=\"334\" \/><\/p>\n<p>Potenciar la creatividad es una de las mejores formas de animarse a crecer como persona y aumentar la capacidad para creer en uno\u00a0mismo.<\/p>\n<p>Hacer actividades creativas o dejar fluir las ideas<strong> puede solucionar muchos problemas y encaminar hacia el \u00e9xito<\/strong>, aumentando de forma significativa la autoestima.<\/p>\n<h2>2. Ayuda a aliviar el estr\u00e9s<\/h2>\n<p>Funciona como una <strong>herramienta terap\u00e9utica para aliviar las emociones negativas<\/strong> como el estr\u00e9s y la depresi\u00f3n.<\/p>\n<p>Crear e inventar es una forma saludable de ocuparse y alejar esos pensamientos da\u00f1inos que impiden disfrutar la vida y sus instantes.<\/p>\n<h2>3. Desarrolla la comunicaci\u00f3n<\/h2>\n<p>Este punto beneficia en especial a los ni\u00f1os. Muchos de ellos tienen dificultades para manifestar sus sentimientos y suelen expresarse con actitudes inadecuadas.<\/p>\n<p>Al permitirles dejar salir sus ideas y plasmarlas en alguna actividad creativa, ellos poco a poco desarrollan una forma de comunicaci\u00f3n que facilita el acercamiento.<\/p>\n<h2>4. Mejora las relaciones sociales<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-85937\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Mejora-las-relaciones-sociales-500x334.jpg\" alt=\"Mejora las relaciones sociales\" width=\"500\" height=\"334\" \/><\/p>\n<p>Por facilitar la expresi\u00f3n de las emociones y las ideas, muchos mejoran su capacidad para relacionarse socialmente.<\/p>\n<p>La creatividad influye de forma directa en la personalidad de cada uno y deja salir a flote cualidades que permiten destacarse en el entorno social.<\/p>\n<div class=\"ad-desktop\">\n<div id=\"div-gpt-ad-1443439665272-0\">\n<div id=\"div-gpt-ad-1443439665272-0_ad_container\">\n<div><object data=\"http:\/\/pagead2.googlesyndication.com\/osd\/hbe.swf?id=1~0\" type=\"application\/x-shockwave-flash\" width=\"1\" height=\"1\"><\/object><\/div>\n<div id=\"inPageVideo\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2>5. Fomenta la integridad<\/h2>\n<p>Una de las principales caracter\u00edsticas de la vida de las personas creadoras es que siempre sienten la necesidad de potenciar su integridad en lo personal y a nivel laboral.<\/p>\n<p>Esto lo consiguen tratando de conservar su esencia y buscando todo tipo de soluciones para conquistar eso que desean lograr.<\/p>\n<p>El ser creativo hace sentir a la persona realizada y <strong>le da confianza para hacer miles de cosas aprovechando sus talentos.<\/strong><\/p>\n<h2>6. Aumenta la capacidad de adaptaci\u00f3n al entorno<\/h2>\n<p>Potenciar esta cualidad es una forma de <strong>aprender a vivir con aquello que hay en el entorno sin importar los cambios<\/strong> que este sufra.<\/p>\n<p>Esto, a su vez, facilita la adaptaci\u00f3n al entorno y la realizaci\u00f3n de las modificaciones necesarias para hacerlo m\u00e1s c\u00f3modo.<\/p>\n<h2>7. Es una gran forma de ahorrar<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-85938\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Es-una-gran-forma-de-ahorrar-500x335.jpg\" alt=\"Es una gran forma de ahorrar\" width=\"500\" height=\"335\" \/><\/p>\n<p>Tener facilidad para crear ayuda a encontrarle utilidad a muchos de los elementos que parecen no ser \u00fatiles en el ambiente.<\/p>\n<p><strong>La creatividad ofrece soluciones con art\u00edculos simples<\/strong>, sin necesidad de invertir grandes sumas de dinero y d\u00e1ndole muchos usos alternativos para facilitar tareas cotidianas.<\/p>\n<p>Adem\u00e1s, ayuda a ser m\u00e1s amigables con el ambiente, ya que <strong>aumenta el h\u00e1bito de reciclar y reutilizar.<\/strong><\/p>\n<h2>8. Ayuda a\u00a0salir de la rutina<\/h2>\n<p>Para salir de la rutina no siempre es necesario viajar o hacer alg\u00fan tipo de actividad fuera del hogar. Emprender proyectos creativos es muy f\u00e1cil y en ocasiones se puede hacer con cosas que est\u00e1n dentro del hogar.<\/p>\n<p>Es una gran forma de aumentar la motivaci\u00f3n, encontrar la felicidad y entretenerse por fuera de esas costumbres que van haciendo aburrida la vida.<\/p>\n<h2>9. Para\u00a0sentirse \u00fatil<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-85939\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Para-sentirse-%C3%BAtil-500x333.jpg\" alt=\"Para sentirse \u00fatil\" width=\"500\" height=\"333\" \/><\/p>\n<p>El simple hecho de poner en marcha una idea creativa despierta ese sentimiento que nos hace sentir \u00fatiles.<\/p>\n<p>Sin importar qu\u00e9 tan peque\u00f1a o grande sea la forma de expresar esta cualidad, <strong>se produce una sensaci\u00f3n de satisfacci\u00f3n, en especial si logra beneficiar a otros.<\/strong><\/p>\n<h2>10. Mejora la calidad de vida<\/h2>\n<p>Al dejar\u00a0fluir las habilidades a trav\u00e9s de la creatividad se puede encontrar la respuesta para muchas preguntas y la soluci\u00f3n para muchos problemas. En general,\u00a0ayuda a mejorar la calidad de vida e<strong> inspira a seguir creciendo como persona.<\/strong><\/p>\n<p>\u00bfEres una persona creativa? Existen m\u00faltiples formas de sacarle provecho a este atributo para disfrutar de cada una de sus virtudes. Lo m\u00e1s importante es animarse y <strong>no dejar que ning\u00fan aspecto negativo le ponga freno.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La creatividad es una forma de ayudarnos a sentirnos \u00fatiles y a crecer como personas, por lo que tambi\u00e9n nos puede servir de terapia para aquellos momentos m\u00e1s depresivos.<\/p>\n","protected":false},"author":12,"featured_media":51921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-51920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51920"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51920\/revisions"}],"predecessor-version":[{"id":51922,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51920\/revisions\/51922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51921"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}