{"id":51926,"date":"2016-01-06T20:48:46","date_gmt":"2016-01-07T00:48:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=51926"},"modified":"2016-01-06T20:48:46","modified_gmt":"2016-01-07T00:48:46","slug":"griffey-jr-y-piazza-electos-al-salon-de-la-fama-del-beisbol","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/griffey-jr-y-piazza-electos-al-salon-de-la-fama-del-beisbol\/","title":{"rendered":"Griffey Jr. y Piazza electos al Sal\u00f3n de la Fama del b\u00e9isbol"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ken-griffen-Jr.jpg.jpg\" rel=\"attachment wp-att-51927\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-51927\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ken-griffen-Jr.jpg.jpg\" alt=\"ken griffen Jr.jpg\" width=\"576\" height=\"324\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ken-griffen-Jr.jpg.jpg 576w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ken-griffen-Jr.jpg-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/ken-griffen-Jr.jpg-105x59.jpg 105w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><br \/>\n<\/a>Ken Griffey Jr. fue electo al Sal\u00f3n de la Fama del b\u00e9isbol con el mayor porcentaje de la historia, y Mike Piazza se le unir\u00e1 en Cooperstown en este verano.<!--more--><br \/>\n<strong>Gu\u00eda r\u00e1pida sobre el Sal\u00f3n de la Fama en Cooperstown<\/strong><\/p>\n<aside class=\"inline editorial float-r\" data-behavior=\"article_related\">\n<ul>\n<li>Si usted es uno de esos aficionados ocasionales &#8212; o si ha estado viviendo debajo de una piedra o colgado de una rama por las \u00faltimas d\u00e9cadas &#8212; le ofrecemos esta gu\u00eda r\u00e1pida para que se ponga al d\u00eda sobre lo que significa para un pelotero llevar las siglas \u00abHOF\u00bb luego de su nombre.<\/li>\n<\/ul>\n<\/aside>\n<p>Griffey fue mencionado en 437 boletas (de un total de 440) en su primera aparici\u00f3n en el proceso llevado a cabo por la Asociaci\u00f3n de Escritores de b\u00e9isbol de EEUU. Su porcentaje de 99.3 super\u00f3 la marca anterior de 98.84, establecida por el lanzador Tom Seaver, quien fue mencionado en 425 de 430 boletas en 1992. Ning\u00fan jugador electo ha sacado el 100 por ciento de los votos.<\/p>\n<p>\u00abContento y conmocionado por estar en semejante club de elite\u00bb, dijo Griffey a MLB Network, sobre sus sentimientos tras conocerse los resultados. \u00abPor si no lo saben, soy verdaderamente supersticioso. He participado tres veces en el juego del Sal\u00f3n de la Fama y jam\u00e1s he puesto un pie en el recinto. No he visto ni siquiera la fachada. La \u00fanica vez que quer\u00eda entrar ah\u00ed era como miembro\u00bb.<\/p>\n<p>Seleccionado en el turno No. 1 por los Marineros de Seattle en el sorteo de 1987, Griffey se convierte en el primer seleccionado en el turno No. 1 en ser exaltado al Sal\u00f3n de la Fama.<\/p>\n<aside class=\"inline inline-photo full\"><\/aside>\n<p>Sus 630 jonrones lo ubican sexto en la lista de todos los tiempos, y sus 1,836 RBIs lo colocan 13\u00ba. Fue electo a 13 Juegos de Estrellas y gan\u00f3 10 Guantes de Oro, empatado en el tercer puesto entre los jardineros. Es uno de tres jugadores con 500 jonrones y 10 Guantes de Oro, junto con Willie Mays y Mike Schmidt, y es uno de siete jugadores con 300 jonrones y 1,100 carreras remolcadas antes de cumplir 30 a\u00f1os.<\/p>\n<p>Luego de quedarse corto por 28 votos el a\u00f1o pasado, Piazza recibi\u00f3 365 votos en su cuarta aparici\u00f3n en la boleta y ser\u00e1 exaltado al Sal\u00f3n junto con Griffey el 24 de julio.<\/p>\n<p>\u00abEs incre\u00edble, algo especial. \u00a1Guau!\u00bb, exclam\u00f3 Piazza en una llamada telef\u00f3nica con MLB Network. \u00abEstoy sentado en el piso, boquiabierto\u00bb.<\/p>\n<p>\u00abEstoy sentado aqu\u00ed con mi boca en el suelo\u00bb, dijo.<\/p>\n<div id=\"attachment_51928\" style=\"width: 393px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/piaza.jpg\" rel=\"attachment wp-att-51928\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-51928\" class=\"wp-image-51928\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/piaza.jpg\" alt=\"piaza\" width=\"383\" height=\"216\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/piaza.jpg 576w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/piaza-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/piaza-105x59.jpg 105w\" sizes=\"auto, (max-width: 383px) 100vw, 383px\" \/><\/a><p id=\"caption-attachment-51928\" class=\"wp-caption-text\">Sporting News\/Getty Images<\/p><\/div>\n<p>Piazza fue seleccionado en su cuarto a\u00f1o en la boleta. Mientras Griffey era altamente cotizado por los escuchas, Piazza fue seleccionado en la ronda 62 por los Dodgers de Los Angeles en 1988 como un favor al padre de Piazza quien era amigo de Tommy Lasorda.<\/p>\n<p>Seleccionado en el turno No. 1,390, Piazza se convirti\u00f3 en el Novato del A\u00f1o de 1993 para Los Angeles y es el jugador m\u00e1s bajo seleccionado en el sorteo que haya sido exaltado a Cooperstown.<\/p>\n<p>Piazza, l\u00edder de todos los tiempos en cuadrangulares para un receptor, tambi\u00e9n se convirti\u00f3 en una leyenda para los Mets de Nueva York al ayudar al equipo a llegar a la Serie Mundial del 2000.<\/p>\n<p>Necesitandose el 75 por ciento de los votos para ser exaltado, Jeff Bagwell (71.6 por ciento), Tim Raines (69.8) y Trevor Hoffman (67.3) redondearon los primeros cinco en la votaci\u00f3n de este a\u00f1o. El analista de ESPN Curt Schillinglleg\u00f3 sexto en la lista por encima de Roger Clemens y Barry Bonds. Estos \u00faltimos han sido marcados por alegaciones de uso de esteroides.<\/p>\n<p>La mitad de los 10 m\u00e1ximos jonroneros de la historia no est\u00e1 todav\u00eda en el Sal\u00f3n de la Fama: Bonds (762), Alex Rodr\u00edguez (654), Jim Thome (612), el dominicano Sammy Sosa (609) y McGwire (583).<\/p>\n<p>Sosa recibi\u00f3 este a\u00f1o 7% de los votos, dos puntos porcentuales por encima del m\u00ednimo requerido para poder participar en la pr\u00f3xima elecci\u00f3n.<\/p>\n<p>Rodr\u00edguez, quien purg\u00f3 en 2014 una suspensi\u00f3n de un a\u00f1o por dopaje, sigue en activo. Thome ser\u00e1 candidato por primera vez en 2018.<\/p>\n<p>Edgar Mart\u00ednez vio incrementado su apoyo de 27 a 43% y Mike Mussina de 25 a 43%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ken Griffey Jr. fue electo al Sal\u00f3n de la Fama del b\u00e9isbol con el mayor porcentaje de la historia, y Mike Piazza se le unir\u00e1 en Cooperstown en este verano.<\/p>\n","protected":false},"author":12,"featured_media":51927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-51926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=51926"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51926\/revisions"}],"predecessor-version":[{"id":51929,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/51926\/revisions\/51929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/51927"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=51926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=51926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=51926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}