{"id":52077,"date":"2016-01-12T17:58:32","date_gmt":"2016-01-12T21:58:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52077"},"modified":"2016-01-12T17:58:32","modified_gmt":"2016-01-12T21:58:32","slug":"robotic-falconry-el-dron-que-captura-a-otros-con-una-red-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/robotic-falconry-el-dron-que-captura-a-otros-con-una-red-video\/","title":{"rendered":"Robotic Falconry, el dron que captura a otros con una red #video"},"content":{"rendered":"<p class=\"ng-scope\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/cazador-de-drones.jpg\" rel=\"attachment wp-att-52078\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-52078\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/cazador-de-drones.jpg\" alt=\"cazador de drones\" width=\"746\" height=\"430\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/cazador-de-drones.jpg 933w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/cazador-de-drones-300x173.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/cazador-de-drones-768x443.jpg 768w\" sizes=\"auto, (max-width: 746px) 100vw, 746px\" \/><\/a>Un grupo de ingenieros del Laboratorio de Rob\u00f3tica (Human-Interactive Robotics Lab &#8211; HIRoLab) de la Universidad Tecnol\u00f3gica de Michigan crearon un prototipo de <strong>dron con un sistema de captura, el cual dispara una red atrapando a cualquier aeronave intrusa.<\/strong> Lo bautizaron como<strong>\u00abRobotic Falconry\u00bb<\/strong>.<!--more--><\/p>\n<p class=\"ng-scope\">Este dron podr\u00eda servir como \u201cguardia de seguridad a\u00e9reo\u201d y evitar que otras aeronaves se escabullan en recintos privados, tr\u00e1fico a\u00e9reo e instalaciones militares.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/jvdKNBSWPyU\" width=\"630\" height=\"37\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p class=\"ng-scope\">A <strong>Mo Rastgaar<\/strong>, profesor de Ingenier\u00eda Mec\u00e1nica en la Universidad Tecnol\u00f3gica de Michigan, quien est\u00e1 a cargo del proyecto, se le ocurri\u00f3 esta idea cuando estaba viendo el Mundial del F\u00fatbol y escuch\u00f3 sobre unos francotiradores protegiendo al p\u00fablico. A \u00e9l no le pareci\u00f3 completamente seguro en el caso de que se tratara de aeronaves invadiendo el lugar:\u00a0<strong>\u201cPens\u00e9, si la amenaza es un dron, no quieres dispararle, podr\u00eda contener explosivos y estallar. Lo que quieres hacer es capturarlo y sacarlo de ah\u00ed\u201d.<\/strong> Desde ese entonces, ha estado trabajando en el Robotic Falconry.<\/p>\n<p class=\"ng-scope\">\u00bfC\u00f3mo funciona? Tiene un sistema que lanza una enorme red, la cual est\u00e1 conectada al dron por una cuerda. <strong>\u00c9ste puede funcionar de forma aut\u00f3noma, ser controlado por una persona o ambas<\/strong>.\u00a0Despu\u00e9s de localizar al dron intruso, la aeronave de captura lo persigue y le lanza la red, con una distancia hasta 12 metros. Su red es tan grande y puede ser desplegada tan r\u00e1pido que logra capturar hasta al dron m\u00e1s escurridizo sin que \u00e9ste escape.<\/p>\n<p class=\"ng-scope\">Actualmente el grupo de investigadores se encuentra solicitando la patente para este prototipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de ingenieros del Laboratorio de Rob\u00f3tica (Human-Interactive Robotics Lab &#8211; HIRoLab) de la Universidad Tecnol\u00f3gica de Michigan crearon un prototipo de dron con un sistema de captura, el cual dispara una red atrapando a cualquier aeronave intrusa. Lo bautizaron como\u00abRobotic Falconry\u00bb.<\/p>\n","protected":false},"author":12,"featured_media":52078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-52077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52077"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52077\/revisions"}],"predecessor-version":[{"id":52080,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52077\/revisions\/52080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52078"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}