{"id":52081,"date":"2016-01-12T18:07:02","date_gmt":"2016-01-12T22:07:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52081"},"modified":"2016-01-12T18:07:02","modified_gmt":"2016-01-12T22:07:02","slug":"seis-remedios-naturales-para-aliviar-el-dolor-de-estomago","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/seis-remedios-naturales-para-aliviar-el-dolor-de-estomago\/","title":{"rendered":"Seis remedios naturales para aliviar el dolor de est\u00f3mago"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>No es ning\u00fan secreto que las fechas decembrinas inducen a las personas a un consumo excesivo de <label>alimentos<\/label> y <label>bebidas<\/label>, que en muchas ocasionan provocan malestar estomacal sin importar la hora o el lugar; pero, \u00bfsabes c\u00f3mo aliviar el dolor de est\u00f3mago despu\u00e9s de la fiesta?<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<div id=\"field-slideshow-1-wrapper\" class=\"field-slideshow-wrapper\">\n<div class=\"field-slideshow field-slideshow-1 effect-fade timeout-4000 with-pager with-controls field-slideshow-processed\">\n<div class=\"field-slideshow-slide field-slideshow-slide-1 even first\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/colitis1cfwe.jpg\" rel=\"attachment wp-att-52082\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52082\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/colitis1cfwe.jpg\" alt=\"colitis1cfwe\" width=\"636\" height=\"415\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/colitis1cfwe.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/colitis1cfwe-300x196.jpg 300w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Algunos de los s\u00edntomas que acompa\u00f1an al dolor de est\u00f3mago son los de la indigesti\u00f3n, como diarrea, n\u00e1useas, gases, eructos y ruidos intestinales, de acuerdo con la University of Miami Health System.<\/p>\n<p><strong>\u00a1Bye, bye molestias!<\/strong><\/p>\n<p>A continuaci\u00f3n te hacemos unas recomendaciones para aliviar el dolor de est\u00f3mago y los molestos s\u00edntomas de la indigesti\u00f3n.<\/p>\n<p><strong>1. Act\u00edvate<\/strong><\/p>\n<p>La University os Miami Health System detalla que una peque\u00f1a caminata, de alrededor de 10 o 15 minutos, reactiva tu actividad intestinal y elimina los molestos c\u00f3licos y gases.<\/p>\n<p><strong>2. Aplica acupresi\u00f3n<\/strong><\/p>\n<p>Un <label>suave<\/label> <label>masaje<\/label> circular con los dedos, durante 5 minutos, en la zona inflamada, te permitir\u00e1 liberar endorfinas y deshacerte un poco del dolor.<\/p>\n<p><strong>3. Dieta l\u00edquida<\/strong><\/p>\n<p>Si tienes m\u00e1s de un d\u00eda con estos s\u00edntomas y contin\u00faas comiendo en exceso deber\u00e1s seguir una dieta l\u00edquida, durante uno o dos d\u00edas, para ayudar a limpiar a tus intestinos de la acumulaci\u00f3n de toxinas.<\/p>\n<p><strong>4. Probi\u00f3ticos<\/strong><\/p>\n<p>Ante el estre\u00f1imiento, dolor abdominal y diarrea, una forma r\u00e1pida de recuperar tu flora intestinal es ingerir lactobacilos, los cuales podr\u00e1s encontrar en muchos alimentos y suplementos al alcance de la mano.<\/p>\n<p><strong>5. Recurre a las infusiones<\/strong><\/p>\n<p>El t\u00e9 permitir\u00e1 que relajes los m\u00fasculos del est\u00f3mago, as\u00ed que una infusi\u00f3n caliente de menta o manzanilla funciona tan bien como ciertos medicamentos para aliviar los c\u00f3licos y dolor abdominal.<\/p>\n<p><strong>6. Consume jengibre<\/strong><\/p>\n<p>Ayuda a la digesti\u00f3n, reduce las n\u00e1useas y el dolor de est\u00f3mago gracias al gingerol, el 6-shogaol y la galanolactona, sustancias que aumentan los jugos digestivos y neutralizan los \u00e1cidos del est\u00f3mago.<\/p>\n<p>Recuerda que lo m\u00e1s importante no es aliviar, sino prevenir, por lo cual no debes excederte en el consumo de alimentos grasos, picantes, bebidas alcoh\u00f3licas, ni pasarte en tus horas de comida.<\/p>\n<p>Tampoco dejes de lado unos minutos al d\u00eda para realizar ejercicio aer\u00f3bico y de relajaci\u00f3n. \u00a1Divi\u00e9rtete y a disfrutar con moderaci\u00f3n!<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/bienestar.salud180.com\/salud-dia-dia\/6-remedios-naturales-vs-el-dolor-de-estomago\" target=\"_blank\">Salud180<\/a> \/ AM<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No es ning\u00fan secreto que las fechas decembrinas inducen a las personas a un consumo excesivo de alimentos y bebidas, que en muchas ocasionan provocan malestar estomacal sin importar la hora o el lugar; pero, \u00bfsabes c\u00f3mo aliviar el dolor de est\u00f3mago despu\u00e9s de la fiesta?<\/p>\n","protected":false},"author":12,"featured_media":52082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52081"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52081\/revisions"}],"predecessor-version":[{"id":52083,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52081\/revisions\/52083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52082"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}