{"id":52102,"date":"2016-01-13T13:44:00","date_gmt":"2016-01-13T17:44:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52102"},"modified":"2016-01-13T13:44:00","modified_gmt":"2016-01-13T17:44:00","slug":"liberan-nuevas-imagenes-de-la-proxima-pelicula-de-assassins-creed","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/liberan-nuevas-imagenes-de-la-proxima-pelicula-de-assassins-creed\/","title":{"rendered":"Liberan nuevas im\u00e1genes de la pr\u00f3xima pel\u00edcula de Assassin&#8217;s Creed"},"content":{"rendered":"<p class=\"ng-scope\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-IV-Black-Flag.jpg\" rel=\"attachment wp-att-52104\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52104\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-IV-Black-Flag.jpg\" alt=\"Assassins-Creed-IV-Black-Flag\" width=\"610\" height=\"345\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-IV-Black-Flag.jpg 610w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-IV-Black-Flag-300x170.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/a><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed.jpg\" rel=\"attachment wp-att-52103\"><br \/>\n<\/a>Nuevas im\u00e1genes han sido liberadas con relaci\u00f3n a la pel\u00edcula de <strong>Assassin&#8217;s Creed<\/strong>, que est\u00e1 siendo filmada en Espa\u00f1a.\u00a0<!--more--><\/p>\n<p class=\"ng-scope\">Por medio de <a href=\"http:\/\/blog.ubi.com\/assassins-creed-movie-first-shots-from-the-film\/\" target=\"_blank\">Ubiblog<\/a>, se puede apreciar los roles que<strong> tendr\u00e1 Michael Fassbender tanto como del asesino espa\u00f1ol Aguilar como de Callum Lynch.<\/strong><\/p>\n<p class=\"ng-scope\">Tambi\u00e9n, se liber\u00f3 una imagen en la que el actor aparece como Lynch, sentado en una celda espeluznante junto a un sacerdote, en la que tambi\u00e9n hay varios mensajes colocados en las murallas.<br \/>\n<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/assassins_creed_empire_1-615x444.jpg\" rel=\"attachment wp-att-52105\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-52105\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/assassins_creed_empire_1-615x444.jpg\" alt=\"assassins_creed_empire_1-615x444\" width=\"543\" height=\"393\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/assassins_creed_empire_1-615x444.jpg 615w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/assassins_creed_empire_1-615x444-300x217.jpg 300w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><\/a><br \/>\nPor \u00faltimo, en otra fotograf\u00eda se puede observar a Fassbender junto con Ariane Labed, co-protagonista de la pel\u00edcula.<\/p>\n<p class=\"ng-scope\"><strong>Se espera que el filme sobre la popular saga de videojuegos se estrene el 21 de diciembre de 2016<\/strong> y a juzgar por las im\u00e1genes se est\u00e1 tratando de recrear de buena forma los ambientes, uno de los aspectos importantes del t\u00edtulo de Ubisoft.<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-pel\u00edcula.jpg\" rel=\"attachment wp-att-52106\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-52106\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-pel\u00edcula.jpg\" alt=\"Assassins-Creed-pel\u00edcula\" width=\"571\" height=\"321\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-pel\u00edcula.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/Assassins-Creed-pel\u00edcula-300x169.jpg 300w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevas im\u00e1genes han sido liberadas con relaci\u00f3n a la pel\u00edcula de Assassin&#8217;s Creed, que est\u00e1 siendo filmada en Espa\u00f1a.\u00a0<\/p>\n","protected":false},"author":12,"featured_media":52104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-52102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52102"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52102\/revisions"}],"predecessor-version":[{"id":52107,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52102\/revisions\/52107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52104"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}