{"id":52123,"date":"2016-01-13T21:56:36","date_gmt":"2016-01-14T01:56:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52123"},"modified":"2016-01-13T21:56:36","modified_gmt":"2016-01-14T01:56:36","slug":"kate-del-castillo-dice-que-contara-su-version-de-contactos-con-el-chapo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/kate-del-castillo-dice-que-contara-su-version-de-contactos-con-el-chapo\/","title":{"rendered":"Kate del Castillo dice que contar\u00e1 \u201csu versi\u00f3n\u201d de contactos con \u201cEl Chapo\u201d"},"content":{"rendered":"<div id=\"p_p_id_contentviewerportlet_WAR_newsportlet_INSTANCE_ed50c63be8d34f72a3c64a7436af2f73_\" class=\"portlet-boundary portlet-boundary_contentviewerportlet_WAR_newsportlet_  portlet-static portlet-static-end content-viewer-portlet \">\n<div class=\"td-portlet\">\n<section id=\"portlet_contentviewerportlet_WAR_newsportlet_INSTANCE_ed50c63be8d34f72a3c64a7436af2f73\" class=\"portlet\">\n<div class=\"portlet-content\">\n<div class=\" portlet-content-container\">\n<div class=\"portlet-body\">\n<div class=\"last td-viewer full-access\">\n<div class=\"detalle-texto\">\n<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6070988_20160113204007.jpg\" rel=\"attachment wp-att-52124\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52124\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6070988_20160113204007.jpg\" alt=\"image_content_6070988_20160113204007\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6070988_20160113204007.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6070988_20160113204007-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>M\u00e9xico. La actriz mexicana Kate del Castillo anunci\u00f3 hoy que contar\u00e1 \u201csu versi\u00f3n\u201d de los contactos con el narcotraficante Joaqu\u00edn \u201cEl Chapo\u201d Guzm\u00e1n, tras asegurar que se han fabricado \u201chistorias falsas\u201d para \u201cdistraer\u201d a la gente \u201cdel verdadero tema\u201d.<!--more--><\/p>\n<p>\u201cComo era de esperarse muchos han decidido manipular la informaci\u00f3n y fabricar historias falsas para distraernos del verdadero tema. Pronto contar\u00e9 mi versi\u00f3n\u201d, asegura en la red social Twitter.<\/p>\n<p>\u201cGracias por su apoyo\u201d, expresa Del Castillo en su primera comunicaci\u00f3n p\u00fablica desde que la revista Rolling Stone publicara la entrevista que el estadounidense Sean Penn hizo al l\u00edder del c\u00e1rtel de Sinaloa con la ayuda de la actriz a principios de octubre pasado, cuando estaba pr\u00f3fugo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div id=\"p_p_id_articletopicsportlet_WAR_newsportlet_INSTANCE_fc7e1ab7f89a458fa395a5d4096cabe3_\" class=\"portlet-boundary portlet-boundary_articletopicsportlet_WAR_newsportlet_  portlet-static portlet-static-end article-topics-portlet detalle-metadatos\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico. La actriz mexicana Kate del Castillo anunci\u00f3 hoy que contar\u00e1 \u201csu versi\u00f3n\u201d de los contactos con el narcotraficante Joaqu\u00edn \u201cEl Chapo\u201d Guzm\u00e1n, tras asegurar que se han fabricado \u201chistorias falsas\u201d para \u201cdistraer\u201d a la gente \u201cdel verdadero tema\u201d.<\/p>\n","protected":false},"author":12,"featured_media":52124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-52123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52123"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52123\/revisions"}],"predecessor-version":[{"id":52125,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52123\/revisions\/52125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52124"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}