{"id":52182,"date":"2016-01-15T17:16:34","date_gmt":"2016-01-15T21:16:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52182"},"modified":"2016-01-15T17:16:34","modified_gmt":"2016-01-15T21:16:34","slug":"la-ops-confirma-primer-caso-del-virus-zika-en-haiti","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-ops-confirma-primer-caso-del-virus-zika-en-haiti\/","title":{"rendered":"La OPS confirma primer caso del virus Zika en Hait\u00ed"},"content":{"rendered":"<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6079944_20160115125442.jpg\" rel=\"attachment wp-att-52183\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52183\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6079944_20160115125442.jpg\" alt=\"image_content_6079944_20160115125442\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6079944_20160115125442.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6079944_20160115125442-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>La Organizaci\u00f3n Panamericana de la Salud (OPS) confirm\u00f3 el primer caso del virus Zika en Hait\u00ed.<!--more--><\/p>\n<p>En el cuadro de pa\u00edses que reportan transmisi\u00f3n aut\u00f3ctona de la enfermedad, de la OPS, aparece el vecino pa\u00eds y con este suman 14 las naciones con registro de la enfermedad.<\/p>\n<p>Desde hace d\u00edas se rumora que el virus estaba en Hait\u00ed, porque una turista alemana lleg\u00f3 a su pa\u00eds con los s\u00edntomas del virus, pero no se hab\u00eda confirmado porque esa persona estuvo tambi\u00e9n en la isla de Guadalupe.<\/p>\n<p>El cuadro de pa\u00edses que reportan transmisi\u00f3n aut\u00f3ctona de al enfermedad figura en la p\u00e1gina web oficial de la OPS <a href=\"http:\/\/www.paho.org\/hq\/index.php?option=com_topics&amp;view=article&amp;id=427&amp;Itemid=41484&amp;lang=es\" target=\"_blank\">www.paho.org<\/a><\/p>\n<\/div>\n<div class=\"infografia\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"waslazy\" src=\"http:\/\/www.diariolibre.com\/documents\/10157\/0\/594x459\/0c0\/0d0\/none\/10904\/OKLR\/image_content_6080855_20160115145615.jpg\" alt=\"\" width=\"594\" height=\"459\" data-original=\"\/documents\/10157\/0\/594x459\/0c0\/0d0\/none\/10904\/OKLR\/image_content_6080855_20160115145615.jpg\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n Panamericana de la Salud (OPS) confirm\u00f3 el primer caso del virus Zika en Hait\u00ed.<\/p>\n","protected":false},"author":12,"featured_media":52183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52182"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52182\/revisions"}],"predecessor-version":[{"id":52184,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52182\/revisions\/52184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52183"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}